 {"id":45259,"date":"2022-09-05T12:00:40","date_gmt":"2022-09-05T10:00:40","guid":{"rendered":"https:\/\/nauticescala.com\/?post_type=news&#038;p=45259"},"modified":"2022-09-05T12:00:43","modified_gmt":"2022-09-05T10:00:43","slug":"2022-escala-international-weta-regatta","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/","title":{"rendered":"R\u00e9my Landier and Anne Etienne win the 2022 L&#8217;Escala International Weta Regatta"},"content":{"rendered":"\n<p>The crew made up of R\u00e9my Landier and Anne Etienne is the winner of the second edition of the Escala International Weta Regatta. The CNEV Esparron sailors obtained once again the overall victory in the Double-handed category of the competition co-organized by the Club N\u00e0utic l\u2019Escala and RS Veleros, the exclusive distributor of Weta trimarans in Spain.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/09\/2022-nauticescala-escala-international-weta-regatta-3.jpg\" alt=\"2022-nauticescala-Escala International Weta Regatta (3)\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>The regatta was held between the 2nd and 4th of September in l&#8217;Escala. Three days of competition and 10 races celebrated under excellent conditions. On Friday and Saturday, the seven Weta trimarans enjoyed winds of 60-70 between 14 and 17 knots of intensity and a thermal of up to 12 during the last day.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Landier and Etienne signed an impeccable performance, with nine partial victories. Thanks to this, they led the ranking with a total of eight points and up to 11 points ahead of the seconds, Estela Requena and Carlos Virgili from CN Sant Feliu de Gu\u00edxols.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/09\/2022-nauticescala-escala-international-weta-regatta-12.jpg\" alt=\"2022-nauticescala-Escala International Weta Regatta (12)\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Requena and Virgili achieved the second place in the overall and the Double-handed rankings, with third place in the fleet going to the first Solo, Philippe Genestier from CNV Aix les Bains. After Genestier, the Solo podium is completed by Patrick Sirven from CVRL and Pierre-Emmanuel Andrieux.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>The prize-giving ceremony took place in Club N\u00e0utic l\u2019Escala at 5pm on Sunday with the speeches of Pere Sala, sports representative of the Club N\u00e0utic l\u2019Escala management board; Toni Castells on behalf of RS Veleros and Josep Bofill, mayor of l&#8217;Escala.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h3 class=\"wp-block-heading\" id=\"h-check-all-results\"><a href=\"https:\/\/nauticescala.com\/en\/book-your-activity\/2022-lescala-international-weta-regatta\/\">Check all results<\/a><\/h3>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n    \n        <div class=\"btn-box\">\n            <a href=\"https:\/\/www.flickr.com\/photos\/nauticescala\/albums\/72157719803539404\" target=\"_blank\" class=\"btn btn-primary\">Pictures<\/a>\n\n        \n        \n\n<\/div><!-- end btn-box -->\n\n   \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section><div class='photonic-flickr-stream photonic-stream ' id='photonic-flickr-stream-1'>\n<div id='photonic-slideshow-flickr-1' class='photonic-slideshow splide default title-display-tooltip photonic-slideshow-adapt-height-width' data-splide='{&quot;type&quot;:&quot;fade&quot;,&quot;perPage&quot;:&quot;1&quot;,&quot;autoplay&quot;:true,&quot;interval&quot;:&quot;5000&quot;,&quot;speed&quot;:&quot;1000&quot;,&quot;drag&quot;:true,&quot;pauseOnHover&quot;:true,&quot;pagination&quot;:false,&quot;slideFocus&quot;:false,&quot;arrows&quot;:true,&quot;direction&quot;:&quot;ltr&quot;,&quot;breakpoints&quot;:{&quot;480&quot;:{&quot;perPage&quot;:1}}}'>\n\t<div class='splide__track'>\n\t\t<ul class='photonic-slideshow-content splide__list'>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177762171_258e9a1f3b_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-178' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177762171' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177762156_4ecf2e8b1e_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-177' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177762156' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177762146_4f9f4f7aaa_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-176' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177762146' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177762151_3aebe2b6cd_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-175' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177762151' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177172137_f1e050d968_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-174' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177172137' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177172092_d70d955478_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-173' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177172092' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258713_38483c8fed_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-172' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258713' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177172117_371a9640ce_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-171' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177172117' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177962159_07899949e3_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-170' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177962159' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177962099_1aabab7cbd_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-169' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177962099' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177762041_ea23bc5942_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-168' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177762041' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178199360_bb52182d67_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-167' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178199360' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177962094_73d1f20523_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-166' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177962094' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177762016_c3f9588ebf_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-165' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177762016' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258663_042ce66f4a_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-164' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258663' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178199315_407f4989c1_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-163' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178199315' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177762021_4013641dcf_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-162' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177762021' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258608_3af95cfdcf_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-161' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258608' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258613_7d563649ab_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-160' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258613' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177761976_828b7eafda_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-159' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177761976' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258603_e92d10e4d1_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-158' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258603' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177171982_b097a66c92_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-157' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177171982' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178199255_35600d8a7b_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-156' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178199255' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177171937_eedd58643f_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-155' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177171937' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177171957_7c9c687c33_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-154' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177171957' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177961939_4fba4da940_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-153' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177961939' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177171887_5e73e66059_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-152' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177171887' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178199205_fad6c1652f_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-151' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178199205' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178199165_03e874c75f_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-150' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178199165' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177761816_410066cff9_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-149' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177761816' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178199120_a2d698b21d_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-148' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178199120' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177171882_cbcb4192ec_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-147' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177171882' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177961894_df9b25f5f5_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-146' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177961894' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177961864_76e017a9cc_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-145' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177961864' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177961849_064ec88945_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-144' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177961849' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177761766_b63874122d_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-143' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177761766' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178199085_804c7cf2e0_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-142' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178199085' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177761776_c142da7386_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-141' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177761776' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258443_8ef4a0deb9_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-140' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258443' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177961799_d3c6943623_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-139' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177961799' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258433_dfae060728_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-138' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258433' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178199080_99b56208f4_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-137' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178199080' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177961764_7bae134406_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-136' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177961764' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258393_7767987f0e_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-135' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258393' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258388_543385e05e_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-134' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258388' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177961749_e9acf4cdf2_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-133' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177961749' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258368_69aedcfd82_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-132' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258368' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178198985_785d474b04_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-131' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178198985' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258363_963d0adb58_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-130' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258363' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177761691_0ed05cacb7_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-129' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177761691' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258883_a50ee01365_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-128' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258883' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258878_72266353ca_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-127' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258878' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177172252_d369069477_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-126' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177172252' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258838_4690c5d039_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-125' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258838' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177962319_f25326e283_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-124' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177962319' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53177762201_4e9f109eac_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-123' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53177762201' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53178258798_cdbff8e297_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-122' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53178258798' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53174547552_50aef09552_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-121' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53174547552' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53174547557_aa6b922b47_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-120' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53174547557' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175340789_028073bfd7_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-119' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175340789' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175340759_ed9eb48032_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-118' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175340759' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175634313_8bcd38112f_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-117' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175634313' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53174547822_a881d924cd_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-116' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53174547822' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175576980_5ac096dcc7_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-115' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175576980' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175340734_149c7d9a96_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-114' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175340734' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175576985_c738c1b6d0_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-113' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175576985' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53174547792_5e61dfa106_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-112' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53174547792' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53174547772_731be6bc6e_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-111' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53174547772' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175634248_61bd4a9e38_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-110' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175634248' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175576950_272e8810d7_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-109' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175576950' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53174547757_f622ebb91f_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-108' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53174547757' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53174547747_fc31dd632c_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-107' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53174547747' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175634238_afb937d84e_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-106' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175634238' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175634218_1126d35bf9_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-105' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175634218' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175576920_00a5903a6e_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-104' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175576920' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53174547707_aebf8127b4_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-103' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53174547707' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175340644_9bfb4dfc7b_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-102' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175340644' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175340634_2559c79580_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-101' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175340634' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175576895_cf1bfed50a_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-100' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175576895' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175137861_da688a8a78_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-99' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175137861' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175340629_45307ad775_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-98' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175340629' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175634138_cd6882a2b5_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-97' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175634138' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175576870_6b3d3ed014_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-96' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175576870' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175576835_8ff62eab53_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-95' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175576835' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175576840_639f55b861_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-94' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175576840' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175137806_b2c07c52bb_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-92' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175137806' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175340579_08d3688450_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-91' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175340579' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175634098_ecee50161b_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-93' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175634098' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175576785_bcb0396b57_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-7 (2)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175576785' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175340539_b6c1f03706_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-6 (2)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175340539' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175340534_fb68aac254_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-5 (2)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175340534' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175340509_b6cb7260c8_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-4 (2)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175340509' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53175576755_13bb4ecbaf_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-3 (2)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53175576755' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172336047_309761e085_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-90' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172336047' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129554_a0152e5561_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-89' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129554' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172336007_8a7670b934_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-88' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172336007' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129549_bbb42fe85b_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-87' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129549' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173414148_a3a9b2eb9c_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-86' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173414148' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364595_a6bf0c6c1c_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-85' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364595' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173414138_449f1d1a6e_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-84' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173414138' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172927191_a2db464b9d_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-83' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172927191' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173414093_314f8cf9d2_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-82' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173414093' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173414098_44e2429a8e_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-81' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173414098' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172927166_82205865cc_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-80' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172927166' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172335952_b10fc4750c_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-79' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172335952' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172927151_c863a44812_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-78' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172927151' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364555_0a4794b478_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-77' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364555' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173414083_9f8f6073f8_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-76' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173414083' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364495_0def8956c6_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-75' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364495' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364490_67f338dbda_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-74' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364490' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172927126_f4d99f9c03_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-73' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172927126' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173414053_a52d3bae50_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-72' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173414053' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173414028_bd574914ea_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-71' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173414028' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173414018_987d5b9834_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-70' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173414018' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129429_39831c9c1f_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-69' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129429' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172927051_0c0dac02e4_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-68' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172927051' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172335867_7b186bc6c4_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-67' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172335867' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172927046_cc3affc1de_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-66' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172927046' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364440_a96de3afde_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-65' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364440' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364425_1e84790c92_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-64' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364425' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172927021_49cc4d9210_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-63' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172927021' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129369_5eadeb0efd_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-62' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129369' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172927006_f8b9b1c782_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-61' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172927006' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173413928_194294b99c_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-60' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173413928' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172926981_0848407d0c_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-59' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172926981' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129329_e2e440be84_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-58' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129329' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129319_189dc01683_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-57' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129319' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129304_063465e47d_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-56' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129304' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129299_daa45095eb_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-55' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129299' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129259_03eb58a017_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-54' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129259' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173413883_7265aad38d_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-53' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173413883' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173413878_a428044973_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-52' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173413878' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173413873_7e296d76bf_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-51' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173413873' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129244_04a4b17396_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-50' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129244' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172926926_19fe12d3a4_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-49' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172926926' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172335757_f411255fd5_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-48' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172335757' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173413848_3400087c85_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-47' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173413848' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129204_d0ee294a58_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-46' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129204' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173413833_9772996501_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-45' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173413833' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364325_13348a7f6b_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-44' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364325' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364320_873ac01557_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-43' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364320' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173413808_d225830b5d_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-42' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173413808' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173413798_596e2081d4_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-41' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173413798' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129159_9e1681ca70_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-40' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129159' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129164_5d0bebeab3_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-39' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129164' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129144_abaabe2335_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-38' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129144' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172335652_d383823183_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-37' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172335652' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364255_9e6d4ce218_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-36' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364255' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364250_7adf35f19a_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-35' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364250' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172926821_ff0bead5b9_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-34' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172926821' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364185_4724e229c7_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-33' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364185' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172926776_e18781f54f_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-32' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172926776' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129109_0dc371fe49_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-31' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129109' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173413703_20bc9d9ebc_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-30' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173413703' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172926751_5dcea98bba_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-29' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172926751' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53172335577_bb9880a046_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-28' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53172335577' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173413708_a355332aa9_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-27' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173413708' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364645_0b88ed00f9_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-26' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364645' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173129609_e4438ed202_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-25' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173129609' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53173364630_61074e5528_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-24' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53173364630' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171109646_3e7c8c773d_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-23' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171109646' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171109651_f379014cdd_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-22' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171109651' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171546010_59bc0abc78_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-21' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171546010' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171109631_13811175a1_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-20' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171109631' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171596328_eeb1551929_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-19' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171596328' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171596323_ac1f1dcc81_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-18' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171596323' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171596353_b77eb65cc2_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-17' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171596353' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53170006132_086d735d80_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-16' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53170006132' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53170006117_80e2af81f3_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-15' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53170006117' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171078358_64d48b55bf_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-14' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171078358' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171029025_95006d9fd8_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-13' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171029025' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171029015_a031f7cbb8_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-12' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171029015' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171028970_c45e8b7c91_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-11' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171028970' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171028955_30eb8e669a_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-10' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171028955' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53170006092_909947787f_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-9' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53170006092' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171078313_ddf226701e_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171078313' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53170789184_b7eb6c8d44_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-7' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53170789184' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53170592116_ad3324b7a5_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-6' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53170592116' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171028940_9528233287_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-5' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171028940' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53171078423_c6f49bc8d0_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53171078423' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53170006192_1540ff055e_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-3' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53170006192' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53170006142_c71571b402_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup-2' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53170006142' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53170006147_93f31c460e_h.jpg' alt='2023-nauticescala-2023 Weta Europa Cup' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53170006147' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52333901938_ad303672cc_h.jpg' alt='2022-nauticescala-L&#039;Escala International Weta Regatta-11' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52333901938' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52333667061_1bc142f540_h.jpg' alt='2022-nauticescala-L&#039;Escala International Weta Regatta-10' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52333667061' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52334095350_ffa585d397_h.jpg' alt='2022-nauticescala-L&#039;Escala International Weta Regatta-9' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52334095350' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52332712682_777191fd5a_h.jpg' alt='2022-nauticescala-Atena Regata, L&#039;Escala International Weta Regatta-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52332712682' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52333901858_8c1c9a99a3_h.jpg' alt='2022-nauticescala-Atena Regata, L&#039;Escala International Weta Regatta-3' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52333901858' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52333964339_74b4424d05_h.jpg' alt='2022-nauticescala-Atena Regata, L&#039;Escala International Weta Regatta-2' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52333964339' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52333964319_3c9514e461_h.jpg' alt='2022-nauticescala-Atena Regata, L&#039;Escala International Weta Regatta' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52333964319' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52331299161_be8730f414_h.jpg' alt='2022-nauticescala-L&#039;Escala International Weta Regatta-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52331299161' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52331299156_ab9351436d_h.jpg' alt='2022-nauticescala-L&#039;Escala International Weta Regatta-7' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52331299156' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52331597914_fb22e4559c_h.jpg' alt='2022-nauticescala-L&#039;Escala International Weta Regatta-6' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52331597914' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52331727975_86771cbcdd_h.jpg' alt='2022-nauticescala-L&#039;Escala International Weta Regatta-5' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52331727975' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52331539563_25b5376e82_h.jpg' alt='2022-nauticescala-L&#039;Escala International Weta Regatta-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52331539563' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52330340647_df3825934f_h.jpg' alt='2022-nauticescala-L&#039;Escala International Weta Regatta-3' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52330340647' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52331539528_1feee5d520_h.jpg' alt='2022-nauticescala-L&#039;Escala International Weta Regatta-2' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52331539528' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52331299176_4c34c575e9_h.jpg' alt='2022-nauticescala-L&#039;Escala International Weta Regatta' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52331299176' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329463620_ff3920e777_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (2)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329463620' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329338829_cc4903dd49_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (3)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329338829' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329464240_318d9d76b9_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (4)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329464240' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329035041_c4085f90e5_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (5)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329035041' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52328082297_3edff71f96_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (6)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52328082297' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329287298_e3a638866a_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (7)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329287298' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329287303_6eb713766a_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (8)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329287303' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329287268_4232cf3f3e_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (9)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329287268' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329287258_ed14bc6244_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (10)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329287258' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329287233_ae32df2def_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (11)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329287233' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329464155_59c72f105d_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (12)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329464155' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329287193_2241face22_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (13)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329287193' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329464135_9377d2d808_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (14)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329464135' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329287163_5da146fa7e_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (15)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329287163' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52328082162_8068529eb0_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (16)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52328082162' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329464110_9ba3399186_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (17)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329464110' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329287148_812657c4f7_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (18)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329287148' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329034846_ca1aa804a2_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (19)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329034846' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329034841_1a0fee8e2c_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (20)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329034841' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52328082087_5ff0b63ee5_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (21)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52328082087' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329338559_538700cc63_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (22)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329338559' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329287113_9e800c060d_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (23)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329287113' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52328082052_7c27310da6_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (24)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52328082052' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329338529_1c1942e7e3_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (25)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329338529' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329034781_04243989c5_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (26)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329034781' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329338514_fb645ae500_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (27)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329338514' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329338484_2e20802e91_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (28)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329338484' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329463895_b7363ed663_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (29)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329463895' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329034706_1e768710bb_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (30)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329034706' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329286968_19c9b3d32d_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (31)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329286968' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329338404_805019baa0_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (32)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329338404' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329338399_40f1f7e549_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (33)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329338399' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329463850_66314dc7ed_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (34)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329463850' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52328081797_83a9d81c99_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (35)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52328081797' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52328081772_f48bdce977_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (36)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52328081772' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52328081722_0303e4d00e_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (37)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52328081722' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329338269_5ce2f2e9c4_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (38)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329338269' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329034516_8717b13fdf_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (39)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329034516' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329286758_a621e2dd5f_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (40)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329286758' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329463685_882f46c7bb_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (41)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329463685' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329338184_c4e18b369b_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (42)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329338184' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52329034436_0302b66800_h.jpg' alt='2022-nauticescala-Escala International Weta Regatta (1)' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52329034436' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51456290286_c84ca5148f_h.jpg' alt='2021-Club Nautic lEscala--15' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51456290286' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455523297_569ffc992d_h.jpg' alt='2021-Club Nautic lEscala--14' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455523297' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51456540408_7bf0e1d3f7_h.jpg' alt='2021-Club Nautic lEscala--13' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51456540408' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51456540283_4bb4930e40_h.jpg' alt='2021-Club Nautic lEscala--12' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51456540283' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455522987_5ccf128865_h.jpg' alt='2021-Club Nautic lEscala--11' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455522987' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51457028624_329911c90c_h.jpg' alt='2021-Club Nautic lEscala--10' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51457028624' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51457028559_6bbdd0b228_h.jpg' alt='2021-Club Nautic lEscala--9' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51457028559' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51457028484_0e8959c741_h.jpg' alt='2021-Club Nautic lEscala--8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51457028484' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51456289731_54e9690e74_h.jpg' alt='2021-Club Nautic lEscala--7' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51456289731' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51456289706_752e2ebb20_h.jpg' alt='2021-Club Nautic lEscala--6' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51456289706' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51457028429_a9c32ec617_h.jpg' alt='2021-Club Nautic lEscala--5' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51457028429' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51456289586_1195963222_h.jpg' alt='2021-Club Nautic lEscala--4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51456289586' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51457247485_346ee71428_h.jpg' alt='2021-Club Nautic lEscala--3' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51457247485' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51457029119_e11b67b650_h.jpg' alt='2021-Club Nautic lEscala--2' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51457029119' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51456540563_c63fda0302_h.jpg' alt='2021-Club Nautic lEscala-' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51456540563' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455664505_bacc8dbbee_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-118' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455664505' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51453943322_e1ac936d07_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-117' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51453943322' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51453943277_5b68e56ab4_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-116' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51453943277' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455449324_f3ac21360a_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-115' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455449324' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455664365_43d0d1bf4b_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-114' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455664365' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455449289_a0fee0a450_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-113' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455449289' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455664305_a530233a5e_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-112' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455664305' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454708211_8e4ebd9574_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-111' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454708211' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51453943057_9f1484cf3b_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-110' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51453943057' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454952163_9ba5961f63_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-109' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454952163' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454952133_06b3ef054b_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-108' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454952133' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455449049_2dbae83914_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-107' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455449049' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455664090_8b5d496e70_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-106' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455664090' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454708006_51130521a3_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-105' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454708006' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454707961_2ee7a872b6_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-104' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454707961' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51453942807_e4c3608066_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-103' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51453942807' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454951933_cf1d6559f7_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-102' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454951933' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454951888_4d5b0fa865_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-101' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454951888' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454951848_311ae3f36b_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-100' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454951848' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454707841_34a4c6dc63_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-99' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454707841' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454707766_79da0875db_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-98' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454707766' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51453942587_9000161762_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-97' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51453942587' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454707671_7854907405_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-96' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454707671' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454951558_34e5c7a70a_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-95' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454951558' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454707566_68324bac26_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-94' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454707566' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455448324_430ce2ce98_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-93' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455448324' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51453942282_8a12c012c3_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-92' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51453942282' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51453942227_08ebe72409_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-91' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51453942227' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454707361_3c5e1d906c_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-90' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454707361' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455448074_cadc607b35_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-89' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455448074' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454951183_bcca1a36ff_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-88' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454951183' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455663350_af8e8765d0_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-87' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455663350' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454951093_1d75f9dec3_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-86' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454951093' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51454951028_a06d2282a1_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-85' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51454951028' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51453941847_e6b36c1f66_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-84' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51453941847' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455447739_74a6bd60a9_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-83' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455447739' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51455663090_cce4820536_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-82' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51455663090' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51445673501_b1b2c71557_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-81' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51445673501' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446627080_31dc84fb69_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-80' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446627080' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51444912057_def4953cdd_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-79' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51444912057' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446626970_b6fa1ba965_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-78' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446626970' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446628070_681b8410d5_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-77' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446628070' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446628030_b82a98d0ce_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-76' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446628030' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51444912927_d4766c4b1e_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-75' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51444912927' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51445674231_358630593c_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-74' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51445674231' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51445674186_4628f84d04_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-73' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51445674186' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446627960_4b238d2ccc_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-72' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446627960' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51445674151_1dae876d25_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-71' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51445674151' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446417564_41e044a1f8_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-70' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446417564' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446417559_16d8a976ce_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-69' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446417559' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446417499_e19ea085c4_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-68' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446417499' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446417464_ae72f71ec9_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-67' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446417464' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51444912722_d911c549e6_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-66' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51444912722' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446627835_daadcfe2f4_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-65' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446627835' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446627815_d39e6bb31c_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-64' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446627815' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446417369_b973636b89_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-63' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446417369' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51445674011_633bd09c27_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-62' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51445674011' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51444912627_c57c76647a_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-61' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51444912627' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446417344_235f024233_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-60' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446417344' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51445914823_41bd55c27d_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-59' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51445914823' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51444912607_43e58e84b5_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-58' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51444912607' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51444912582_2bb38a3a7f_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-57' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51444912582' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51444912562_b9b2b589ef_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-56' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51444912562' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446417239_0012085627_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-55' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446417239' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51445673866_d89413eb98_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-54' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51445673866' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446417224_c71bb3ea21_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-53' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446417224' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446627540_3c5562e99a_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-52' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446627540' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51444912437_7f78100bf8_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-51' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51444912437' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446627445_2ef9e1dc02_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-50' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446627445' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51445673771_041b86a51d_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-49' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51445673771' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51445673726_4c1814dd99_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-48' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51445673726' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51445914533_c8b77c7391_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-47' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51445914533' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51445673631_9fc3dc55c1_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-46' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51445673631' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446416919_b72fec5fb9_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-45' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446416919' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446416904_2e81827561_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-44' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446416904' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51446416864_78dedfddbd_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-43' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51446416864' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51444912147_4ff140a2d5_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-42' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51444912147' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51441919912_7080406985_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-41' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51441919912' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442922988_64ff07ac48_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-40' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442922988' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443638450_3342d46d6b_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-39' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443638450' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51441919892_5eddbce5c8_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-38' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51441919892' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443638410_4be6f04678_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-37' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443638410' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442675221_3c2c2f504f_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-36' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442675221' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443638915_0ca45a1cf9_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-35' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443638915' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51441920472_03354b6715_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-34' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51441920472' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442923448_f2f7c8b317_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-33' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442923448' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442923438_47e508f216_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-32' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442923438' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443418514_077b6ffbd3_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-31' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443418514' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51441920422_cf51080dbc_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-30' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51441920422' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51441920407_bf373b2426_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-29' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51441920407' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442923383_69540bf333_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-28' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442923383' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51441920382_e324d55cc1_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-27' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51441920382' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443418464_9cf3f297a5_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-26' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443418464' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443638775_4ee933325d_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-25' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443638775' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443418434_490f20074a_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-24' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443418434' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443418439_23858df944_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-23' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443418439' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442923333_5e4994ca02_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-22' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442923333' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442675636_25edc7e7d1_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-21' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442675636' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442675606_7ea9cc68e7_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-20' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442675606' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442675586_9ac144ea49_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-19' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442675586' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442923293_5df0ab323d_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-18' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442923293' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443638690_624c4a428f_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-17' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443638690' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51441920207_6b75adcb16_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-16' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51441920207' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442923268_a6645b2c42_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-15' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442923268' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51441920172_3bfb3ce8a3_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-14' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51441920172' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443638650_3fcb87fcc4_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-13' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443638650' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443418249_933e0bc570_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-12' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443418249' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443638640_719cf9c5d0_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-11' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443638640' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442675456_ab0bd485b4_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-10' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442675456' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442675441_03743477b8_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-9' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442675441' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442675436_b6821d0a72_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442675436' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443418199_32507559d5_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-7' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443418199' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443638545_0f92696d77_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-6' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443638545' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442675396_3cca29257a_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-5' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442675396' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51443418114_471fa1fe88_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51443418114' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442923103_f5bc62954c_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-3' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442923103' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442675336_62bd13015c_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021-2' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442675336' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51442923048_cf87109b64_h.jpg' alt='2021-Club Nautic lEscala-L&#039;Escala International Weta Regatta 2021' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51442923048' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t<\/ul>\n\t<\/div><!-- splide__track -->\n<\/div><!-- .photonic-slideshow-->\n\n<\/div><!-- .photonic-stream or .photonic-panel -->\n","protected":false},"excerpt":{"rendered":"<p>2022 L&#8217;Escala International Weta Regatta took place in L&#8217;Escala from 2nd to 4th Septembre. 3 days of great sailing in the sea of Emp\u00faries!<\/p>\n","protected":false},"featured_media":45231,"parent":0,"template":"","news-categories":[962,952],"news-tags":[],"class_list":["post-45259","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-regattas","news-categories-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>R\u00e9my Landier and Anne Etienne win the 2022 L&#039;Escala International Weta Regatta &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"2022 L&#039;Escala International Weta Regatta took place in L&#039;Escala from 2nd to 4th Septembre. 3 days of great sailing in the sea of Emp\u00faries\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9my Landier and Anne Etienne win the 2022 L&#039;Escala International Weta Regatta\" \/>\n<meta property=\"og:description\" content=\"2022 L&#039;Escala International Weta Regatta took place in L&#039;Escala from 2nd to 4th Septembre. 3 days of great sailing in the sea of Emp\u00faries\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-05T10:00:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/09\/2022-nauticescala-lescala-international-weta-regatta-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/en\\\/news\\\/2022-escala-international-weta-regatta\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/en\\\/news\\\/2022-escala-international-weta-regatta\\\/\",\"name\":\"R\u00e9my Landier and Anne Etienne win the 2022 L'Escala International Weta Regatta &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/en\\\/news\\\/2022-escala-international-weta-regatta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/en\\\/news\\\/2022-escala-international-weta-regatta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2022-nauticescala-lescala-international-weta-regatta-3.jpg\",\"datePublished\":\"2022-09-05T10:00:40+00:00\",\"dateModified\":\"2022-09-05T10:00:43+00:00\",\"description\":\"2022 L'Escala International Weta Regatta took place in L'Escala from 2nd to 4th Septembre. 3 days of great sailing in the sea of Emp\u00faries\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/en\\\/news\\\/2022-escala-international-weta-regatta\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/en\\\/news\\\/2022-escala-international-weta-regatta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/en\\\/news\\\/2022-escala-international-weta-regatta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2022-nauticescala-lescala-international-weta-regatta-3.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2022-nauticescala-lescala-international-weta-regatta-3.jpg\",\"width\":1800,\"height\":907,\"caption\":\"2022-nauticescala-L'Escala International Weta Regatta-3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/en\\\/news\\\/2022-escala-international-weta-regatta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"R\u00e9my Landier and Anne Etienne win the 2022 L&#8217;Escala International Weta Regatta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"R\u00e9my Landier and Anne Etienne win the 2022 L'Escala International Weta Regatta &#8211; Club N\u00e0utic L\u2019Escala","description":"2022 L'Escala International Weta Regatta took place in L'Escala from 2nd to 4th Septembre. 3 days of great sailing in the sea of Emp\u00faries","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/","og_locale":"en_US","og_type":"article","og_title":"R\u00e9my Landier and Anne Etienne win the 2022 L'Escala International Weta Regatta","og_description":"2022 L'Escala International Weta Regatta took place in L'Escala from 2nd to 4th Septembre. 3 days of great sailing in the sea of Emp\u00faries","og_url":"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2022-09-05T10:00:43+00:00","og_image":[{"width":1800,"height":907,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/09\/2022-nauticescala-lescala-international-weta-regatta-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/","url":"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/","name":"R\u00e9my Landier and Anne Etienne win the 2022 L'Escala International Weta Regatta &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/09\/2022-nauticescala-lescala-international-weta-regatta-3.jpg","datePublished":"2022-09-05T10:00:40+00:00","dateModified":"2022-09-05T10:00:43+00:00","description":"2022 L'Escala International Weta Regatta took place in L'Escala from 2nd to 4th Septembre. 3 days of great sailing in the sea of Emp\u00faries","breadcrumb":{"@id":"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/09\/2022-nauticescala-lescala-international-weta-regatta-3.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/09\/2022-nauticescala-lescala-international-weta-regatta-3.jpg","width":1800,"height":907,"caption":"2022-nauticescala-L'Escala International Weta Regatta-3"},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/en\/news\/2022-escala-international-weta-regatta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/en\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"R\u00e9my Landier and Anne Etienne win the 2022 L&#8217;Escala International Weta Regatta"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/en\/wp-json\/wp\/v2\/news\/45259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/en\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/en\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/en\/wp-json\/wp\/v2\/media\/45231"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/en\/wp-json\/wp\/v2\/media?parent=45259"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/en\/wp-json\/wp\/v2\/news-categories?post=45259"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/en\/wp-json\/wp\/v2\/news-tags?post=45259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}