 {"id":15876,"date":"2019-06-09T13:51:00","date_gmt":"2019-06-09T11:51:00","guid":{"rendered":"http:\/\/nauticescala.com\/noticies\/open-de-espana-de-j70-final\/"},"modified":"2019-06-09T13:51:00","modified_gmt":"2019-06-09T11:51:00","slug":"open-de-espana-de-j70-final","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/","title":{"rendered":"Open de Espa\u00f1a de J70 para Noticia de Jos\u00e9 Mar\u00eda Torcida"},"content":{"rendered":"\n<p><strong>El <em>Noticia<\/em> (RCM Santander), se ha hecho hoy, domingo 9 de junio, con el Open de Espa\u00f1a de J70 celebrado en el Club N\u00e1utico l&#8217;Escala.<\/strong> Ha sido despu\u00e9s de dos d\u00edas intensos de regata, uno anulado y 8 pruebas celebradas con condiciones m\u00e1s que variadas de navegaci\u00f3n y una cabecera de clasificaci\u00f3n extremadamente disputada. Sin m\u00e1s mangas navegadas el domingo por la ausencia de viento, los de Jos\u00e9 Mar\u00eda Torcida confirmaban su victoria respecto al segundo y tercer clasificados, <em>Lumar <\/em>(RCN Gran Canaria &#8211; RCMT Punta Umbr\u00eda) liderado por Luis Mart\u00ednez Doreste y <em>Abril Verde<\/em> (RCN Vigo) con Luis P\u00e9rez Canal a la ca\u00f1a.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><strong>La cita ha contado con 17 tripulaciones con algunos de los mejores regatistas de la clase del pa\u00eds.<\/strong> Se han desplazado a l&#8217;Escala navegantes de Catalu\u00f1a, Galicia, Canarias y hasta representantes de Rusia y Uruguay. Elenco completo y de gran nivel que se las ha visto con una meteorolog\u00eda que ha sido todo un reto por su variedad de viento, ola y sol.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h4 class=\"wp-block-heading\">Del sur y del norte<\/h4>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Tras una jornada destinada a mediciones, formalizaci\u00f3n de inscripciones y entrenamientos libres, el pasado jueves 6 de junio, las primeras mangas del campeonato se celebraban el viernes. D\u00eda de extremos, primero con viento de componente sur de entre 15 y 18 nudos y despu\u00e9s cambio de tercio: una del cl\u00e1sico viento del norte de la zona con una intensidad de 20 &#8211; 25 nudos, acompa\u00f1ado. El oleaje, generoso, fue una constante durante todo el d\u00eda, aunque tambi\u00e9n vari\u00f3 su direcci\u00f3n, y brind\u00f3 condiciones para disfrutar del planeo. Con todo, se celebraron tres pruebas, con dos victorias de <em>Lumar<\/em>, que se adjudicaba el liderato provisional de la regata.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h4 class=\"wp-block-heading\">Pruebas m\u00e1s que disputadas<\/h4>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Para el s\u00e1bado 8, el mar de Emp\u00faries ofreci\u00f3 ola y un viento de que se mantuvo alrededor del 60\u00ba. La intensidad ascendi\u00f3 de los 12 nudos a los 18 para despu\u00e9s volver a suavizarse para la \u00faltima manga del d\u00eda. En total, fueron cuatro y muy re\u00f1idas. La flota naveg\u00f3 bastante agrupada y con baile de posiciones constante hasta el \u00faltimo momento. En este caso, <em>Noticia<\/em> consigui\u00f3 dos de los primeros puestos del d\u00eda, mientras que los otros dos fueron para <em>New Territories<\/em> de Alexei Semenov del CN Arenys de Mar y <em>Abril Verde<\/em>. Tras la aplicaci\u00f3n de un descarte, <em>Noticia<\/em> consegu\u00eda situarse en primer lugar de la general con 12 puntos y tan s\u00f3lo dos y tres puntos de ventaja sobre el segundo y el tercero, <em>Lumar<\/em> y <em>Abril Verde<\/em>. Las posiciones de podio quedaban, as\u00ed, todav\u00eda abiertas.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El domingo, \u00faltima entrega de la regata, amaneci\u00f3 en calma. La ausencia de viento oblig\u00f3 a la flota a esperar en tierra y finalmente, a anular las pruebas previstas. Se acababa, as\u00ed, la lucha y el t\u00edtulo era para <em>Noticia<\/em>. Los premios a los mejores se entregaron durante una ceremonia que se avanz\u00f3 a las 14 horas.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El Club N\u00e1utico l\u2019Escala ha organizado el Open de Espa\u00f1a de J70 2019 por delegaci\u00f3n de la Real Federaci\u00f3n Espa\u00f1ola de Vela, la Federaci\u00f3n Catalana de Vela y la Asociaci\u00f3n Espa\u00f1ola de Propietarios de J70. Recibe la colaboraci\u00f3n, adem\u00e1s, del Ayuntamiento de l\u2019Escala, la Diputaci\u00f3n de Girona y el Consell Catal\u00e0 de l\u2019Esport, as\u00ed como el patrocinio de la empresa especialista en productos ahumados Benfumat.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.flickr.com\/photos\/nauticescala\/albums\/72157708977041751\" target=\"_blank\" rel=\"noreferrer noopener\">Fotograf\u00edas<\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>El Open de Espa\u00f1a de J70 se resuelve tras dos d\u00edas intensos de regata, uno anulado y 8 pruebas celebradas con condiciones m\u00e1s que variadas de navegaci\u00f3n.<\/p>\n","protected":false},"featured_media":15875,"parent":0,"template":"","news-categories":[],"news-tags":[],"class_list":["post-15876","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Open de Espa\u00f1a de J70 para Noticia de Jos\u00e9 Mar\u00eda Torcida<\/title>\n<meta name=\"description\" content=\"El Noticia (RCM Santander), se ha hecho hoy, domingo 9 de junio, con el Open de Espa\u00f1a de J70 celebrado en el Club N\u00e1utico l&#039;Escala. Ha sido despu\u00e9s de dos d\u00edas intensos de regata, uno anulado y 8 pruebas celebradas con condiciones m\u00e1s que variadas de navegaci\u00f3n y una cabecera de clasificaci\u00f3n extremadamente disputada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Open de Espa\u00f1a de J70 para Noticia de Jos\u00e9 Mar\u00eda Torcida\" \/>\n<meta property=\"og:description\" content=\"El Noticia (RCM Santander), se ha hecho hoy, domingo 9 de junio, con el Open de Espa\u00f1a de J70 celebrado en el Club N\u00e1utico l&#039;Escala. Ha sido despu\u00e9s de dos d\u00edas intensos de regata, uno anulado y 8 pruebas celebradas con condiciones m\u00e1s que variadas de navegaci\u00f3n y una cabecera de clasificaci\u00f3n extremadamente disputada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2019\/06\/2018-club-nautic-lescala-port-esportiu-costa-brava-campionat-de-catlunya-de-j70-35.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"820\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/open-de-espana-de-j70-final\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/open-de-espana-de-j70-final\\\/\",\"name\":\"Open de Espa\u00f1a de J70 para Noticia de Jos\u00e9 Mar\u00eda Torcida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/open-de-espana-de-j70-final\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/open-de-espana-de-j70-final\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/2018-club-nautic-lescala-port-esportiu-costa-brava-campionat-de-catlunya-de-j70-35.jpg\",\"datePublished\":\"2019-06-09T11:51:00+00:00\",\"description\":\"El Noticia (RCM Santander), se ha hecho hoy, domingo 9 de junio, con el Open de Espa\u00f1a de J70 celebrado en el Club N\u00e1utico l'Escala. Ha sido despu\u00e9s de dos d\u00edas intensos de regata, uno anulado y 8 pruebas celebradas con condiciones m\u00e1s que variadas de navegaci\u00f3n y una cabecera de clasificaci\u00f3n extremadamente disputada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/open-de-espana-de-j70-final\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/open-de-espana-de-j70-final\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/open-de-espana-de-j70-final\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/2018-club-nautic-lescala-port-esportiu-costa-brava-campionat-de-catlunya-de-j70-35.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/2018-club-nautic-lescala-port-esportiu-costa-brava-campionat-de-catlunya-de-j70-35.jpg\",\"width\":820,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/open-de-espana-de-j70-final\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Open de Espa\u00f1a de J70 para Noticia de Jos\u00e9 Mar\u00eda Torcida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Open de Espa\u00f1a de J70 para Noticia de Jos\u00e9 Mar\u00eda Torcida","description":"El Noticia (RCM Santander), se ha hecho hoy, domingo 9 de junio, con el Open de Espa\u00f1a de J70 celebrado en el Club N\u00e1utico l'Escala. Ha sido despu\u00e9s de dos d\u00edas intensos de regata, uno anulado y 8 pruebas celebradas con condiciones m\u00e1s que variadas de navegaci\u00f3n y una cabecera de clasificaci\u00f3n extremadamente disputada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/","og_locale":"es_ES","og_type":"article","og_title":"Open de Espa\u00f1a de J70 para Noticia de Jos\u00e9 Mar\u00eda Torcida","og_description":"El Noticia (RCM Santander), se ha hecho hoy, domingo 9 de junio, con el Open de Espa\u00f1a de J70 celebrado en el Club N\u00e1utico l'Escala. Ha sido despu\u00e9s de dos d\u00edas intensos de regata, uno anulado y 8 pruebas celebradas con condiciones m\u00e1s que variadas de navegaci\u00f3n y una cabecera de clasificaci\u00f3n extremadamente disputada.","og_url":"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/","og_site_name":"Club N\u00e0utic L\u2019Escala","og_image":[{"width":820,"height":420,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2019\/06\/2018-club-nautic-lescala-port-esportiu-costa-brava-campionat-de-catlunya-de-j70-35.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/","url":"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/","name":"Open de Espa\u00f1a de J70 para Noticia de Jos\u00e9 Mar\u00eda Torcida","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2019\/06\/2018-club-nautic-lescala-port-esportiu-costa-brava-campionat-de-catlunya-de-j70-35.jpg","datePublished":"2019-06-09T11:51:00+00:00","description":"El Noticia (RCM Santander), se ha hecho hoy, domingo 9 de junio, con el Open de Espa\u00f1a de J70 celebrado en el Club N\u00e1utico l'Escala. Ha sido despu\u00e9s de dos d\u00edas intensos de regata, uno anulado y 8 pruebas celebradas con condiciones m\u00e1s que variadas de navegaci\u00f3n y una cabecera de clasificaci\u00f3n extremadamente disputada.","breadcrumb":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2019\/06\/2018-club-nautic-lescala-port-esportiu-costa-brava-campionat-de-catlunya-de-j70-35.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2019\/06\/2018-club-nautic-lescala-port-esportiu-costa-brava-campionat-de-catlunya-de-j70-35.jpg","width":820,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/es\/noticias\/open-de-espana-de-j70-final\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"Open de Espa\u00f1a de J70 para Noticia de Jos\u00e9 Mar\u00eda Torcida"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news\/15876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/15875"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=15876"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-categories?post=15876"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-tags?post=15876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}