 {"id":27240,"date":"2021-04-28T12:57:55","date_gmt":"2021-04-28T10:57:55","guid":{"rendered":"http:\/\/nauticescala.com\/noticies\/medfoto-concurs-internacional-de-fotografia-de-la-mediterrania\/"},"modified":"2021-04-28T13:22:18","modified_gmt":"2021-04-28T11:22:18","slug":"medfoto-concurso-internacional-de-fotografia-del-mediterraneo","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/","title":{"rendered":"El Club presenta MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo"},"content":{"rendered":"\n<p>El Club N\u00e0utic l&#8217;Escala y la <a href=\"https:\/\/alivefund.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fundaci\u00f3 Aliv<\/a>e dan a conocer MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo. El certamen fue presentado el pasado s\u00e1bado 24 de abril en el marco de la primera charla online de la secci\u00f3n de Actividades Subacu\u00e1ticas del Club. MedFoto nace del acuerdo que firmaron el Club N\u00e0utic l&#8217;Escala y la Fundaci\u00f3 Alive, el pasado 5 de febrero, seg\u00fan el que se compromet\u00edan a trabajar conjuntamente para crear un certamen fotogr\u00e1fico con el objetivo de difundir los valores ambientales y humanos del mar Mediterr\u00e1neo.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El mar y el mar Mediterr\u00e1neo en concreto han estado muy vinculados al pueblo marinero de l&#8217;Escala desde sus or\u00edgenes. De hecho, los griegos desembarcaron en la Pen\u00ednsula Ib\u00e9rica desde Emp\u00faries, donde sus vestigios nos recuerdan d\u00eda a d\u00eda la importancia de preservar su legado historico y cultural del que el mar es uno de sus principales ejes vertebradores.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Este mar que ba\u00f1a nuestras costas es, pues, muy rico en valores. Es cultura e historia; un medio de trabajo y de recreo para el hombre y h\u00e1bitat de miles de especies de animales y vegetales que configuran su paisaje tan especial. Valores que deben convivir para el presente y para las generaciones futuras y que \u00fanicamente podremos preservar disfrutando y trabajando en el mar de forma sostenible.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/06\/loligo-vulgaris-c-bernat-garrigos.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h3 class=\"wp-block-heading\">Un concurso abierto a diferentes categor\u00edas y con premios en met\u00e1lico<\/h3>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El Club N\u00e0utic l\u2019Escala y la Fundaci\u00f3 Alive dan a conocer el fruto de meses de trabajo, un <strong>concurso de fotograf\u00eda dedicado a todas las vertientes del mar Mediterr\u00e1neo<\/strong> con la tem\u00e1tica el mar y las personas. Des del paisaje a la vida marina; desde lo que pasa sobre su superficie hasta lo que pasa bajo sus aguas; desde las actividades n\u00e1uticas profesionales hasta las deportivas. Es por este motivo que ofrece hasta siete categor\u00edas de concurso, entre ellas una exclusiva para im\u00e1genes tomadas con dispositivos m\u00f3biles.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>MedFoto es, adem\u00e1s, <strong>un concurso abierto a todo el mundo que desee participar: aficionados a la fotograf\u00eda y profesionales. <\/strong>Todos ellos podr\u00e1n presentar hasta 15 fotograf\u00edas en cualquiera de las categor\u00edas del certamen. <strong>El per\u00edodo de inscripci\u00f3n y env\u00edo de las im\u00e1genes se abrir\u00e1 el pr\u00f3ximo s\u00e1bado 1 de mayo y se prolongar\u00e1 hasta el 31 del mismo mes.<\/strong><\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/02\/2015-cn-lescala-costa-brava-regates.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h3 class=\"wp-block-heading\">Un projecte colaborativo<\/h3>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El certamen MedFoto es una iniciativa conjunta del Club N\u00e0utic l&#8217;Escala y la Fundaci\u00f3 Alive. El Club N\u00e0utic l&#8217;Escala es una asociaci\u00f3n deportiva sin \u00e1nimo de lucro que tiene por objetivo promover la n\u00e1utica deportiva y de recreo brindando acceso al mar a todo el mundo. La Fundaci\u00f3 Alive es una fundaci\u00f3n privada que trabaja para mejorar el conocimiento de la biodiversidad mediante la recolecci\u00f3n, catalogaci\u00f3n y difusi\u00f3n de informaci\u00f3n biol\u00f3gica. El Ayuntamiento de l&#8217;Escala apoya el proyecto en el marco de su esfuerzo constante por difundir los valores y los entornos locales como medio para mejorar la calidad de vida de la ciudadan\u00eda.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h3 class=\"wp-block-heading\">\u00a1<a href=\"https:\/\/nauticescala.com\/medfoto\/?lang=es\" target=\"_blank\" rel=\"noreferrer noopener\">Consulta las bases del concurso y participa!<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfTe gusta el mar? \u00bfY la fotograf\u00eda? Si la respuesta es s\u00ed, \u00a1MedFoto es tu oportunidad! Descubre el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo..<\/p>\n","protected":false},"featured_media":27033,"parent":0,"template":"","news-categories":[967],"news-tags":[],"class_list":["post-27240","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-social-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Club presenta MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"El Club N\u00e0utic l&#039;Escala y la Fundaci\u00f3 Alive dan a conocer MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Club presenta MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo\" \/>\n<meta property=\"og:description\" content=\"El Club N\u00e0utic l&#039;Escala y la Fundaci\u00f3 Alive dan a conocer MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-28T11:22:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/04\/club-nautic-lescala-medfoto-concurs-internacional-de-fotografia-de-la-mediterrania.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\\\/\",\"name\":\"El Club presenta MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/club-nautic-lescala-medfoto-concurs-internacional-de-fotografia-de-la-mediterrania.jpg\",\"datePublished\":\"2021-04-28T10:57:55+00:00\",\"dateModified\":\"2021-04-28T11:22:18+00:00\",\"description\":\"El Club N\u00e0utic l'Escala y la Fundaci\u00f3 Alive dan a conocer MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/club-nautic-lescala-medfoto-concurs-internacional-de-fotografia-de-la-mediterrania.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/club-nautic-lescala-medfoto-concurs-internacional-de-fotografia-de-la-mediterrania.jpg\",\"width\":1800,\"height\":907},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El Club presenta MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Club presenta MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo &#8211; Club N\u00e0utic L\u2019Escala","description":"El Club N\u00e0utic l'Escala y la Fundaci\u00f3 Alive dan a conocer MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/","og_locale":"es_ES","og_type":"article","og_title":"El Club presenta MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo","og_description":"El Club N\u00e0utic l'Escala y la Fundaci\u00f3 Alive dan a conocer MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo.","og_url":"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2021-04-28T11:22:18+00:00","og_image":[{"width":1800,"height":907,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/04\/club-nautic-lescala-medfoto-concurs-internacional-de-fotografia-de-la-mediterrania.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/","url":"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/","name":"El Club presenta MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/04\/club-nautic-lescala-medfoto-concurs-internacional-de-fotografia-de-la-mediterrania.jpg","datePublished":"2021-04-28T10:57:55+00:00","dateModified":"2021-04-28T11:22:18+00:00","description":"El Club N\u00e0utic l'Escala y la Fundaci\u00f3 Alive dan a conocer MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo.","breadcrumb":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/04\/club-nautic-lescala-medfoto-concurs-internacional-de-fotografia-de-la-mediterrania.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/04\/club-nautic-lescala-medfoto-concurs-internacional-de-fotografia-de-la-mediterrania.jpg","width":1800,"height":907},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/es\/noticias\/medfoto-concurso-internacional-de-fotografia-del-mediterraneo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"El Club presenta MedFoto, el primer Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news\/27240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/27033"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=27240"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-categories?post=27240"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-tags?post=27240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}