 {"id":46304,"date":"2022-10-07T17:45:21","date_gmt":"2022-10-07T15:45:21","guid":{"rendered":"https:\/\/nauticescala.com\/noticies\/2022-eurilca-master-european-championships-inici\/"},"modified":"2022-10-07T17:49:31","modified_gmt":"2022-10-07T15:49:31","slug":"2022-eurilca-master-european-championships-inicio","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/","title":{"rendered":"\u00a1Empieza el 2022 EurILCA Master European Championships de l\u2019Escala!"},"content":{"rendered":"\n<p>Hoy, viernes 7 de octubre, ha empezado el <a href=\"https:\/\/nauticescala.com\/en\/book-your-activity\/ilca-master-european-championship-2022\/\">2022 EurILCA Master European Champhionships<\/a> en el Club N\u00e0utic L\u2019Escala. La mayor parte de la flota, integrada por hasta 264 regatistas procedentes de 27 pa\u00edses de todo el mundo, ya est\u00e1 en L&#8217;Escala y ha aprovechado el d\u00eda lluvioso para confirmar inscripciones y superar la inspecci\u00f3n de su material de navegaci\u00f3n.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Les esperan seis d\u00edas de navegaci\u00f3n y diversi\u00f3n en el Mar de Emp\u00faries que se iniciar\u00e1n ma\u00f1ana s\u00e1bado 8 de octubre con una regata de entrenamiento que tendr\u00e1 lugar a las 15 h. Finalizada la prueba, que permitir\u00e1 conocer mejor el campo de regata, el punto de encuentro de navegantes, acompa\u00f1antes, organizaci\u00f3n e instituciones colaboradoras ser\u00e1 la inauguraci\u00f3n del campeonato.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-2022-eurilca-master-european-championships-c-thom-touw-6.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>La ceremonia empezar\u00e1 a las 18 h en el Village del 2022 EurILCA Master European Champhionships y contar\u00e1 con las intervenciones de Gerard Mar\u00edn, comodoro del Club N\u00e0utic L&#8217;Escala; Alan Davis, coordinador Master de EurILCA; Josep Maria Isern, vicepresidente de la Federaci\u00f3n Catalana de Vela; y el Alcalde de L\u2019Escala, Josep Bofill.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El momento culminante del acto ser\u00e1 la izada de la bandera de la clase ILCA en el m\u00e1stil de se\u00f1ales de la regata. Despu\u00e9s, todos los asistentes podr\u00e1n disfrutar de una degustaci\u00f3n de anchoas de L&#8217;Escala, la mejor embajadora del municipio marinero.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Las regatas puntuables tendr\u00e1n lugar entre el domingo y el jueves 13 de octubre, con dos pruebas programadas por d\u00eda ideales para disfrutar del fant\u00e1stico entorno de L\u2019Escala, Emp\u00faries y el Parque Natural del Montgr\u00ed. La flota navegar\u00e1 distribuida en dos campos de regata.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-2022-eurilca-master-european-championships-c-thom-touw-21.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Los d\u00edas 9, 10 y 11, al volver a puerto, los participantes podr\u00e1n recuperar fuerzas con un plato de pasta que podr\u00e1n degustar compartiendo experiencias con otros navegantes. El martes 11 de octubre les espera un d\u00eda especial, y es que se les ofrecer\u00e1 una barbacoa amenizada con la m\u00fasica del DJ Palma.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El programa social finalizar\u00e1 con la ceremonia de entrega de trofeos, que se celebrar\u00e1 el jueves 13 de octubre alrededor de las 17 h y descubrir\u00e1 a los ganadores absolutos y de las diferentes categor\u00edas del 2022 EurILCA Master European Championships.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El Club N\u00e0utic l&#8217;Escala organiza el 2022 EurILCA Master European Championships despu\u00e9s de haber sido seleccionado por parte de EurILCA (ILCA European Region) el pasado mes de abril.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-2022-eurilca-master-european-championships-c-thom-touw-9.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>La regata cuenta con la colaboraci\u00f3n de la Secretar\u00eda General del Deporte y de la Actividad F\u00edsica de la Generalitat de Catalunya, la Diputaci\u00f3n de Girona, el Patronato de Turismo Costa Brava Girona, la Real Federaci\u00f3n Espa\u00f1ola de Vela y el Ayuntamiento de L&#8217;Escala, as\u00ed como de Ports de la Generalitat, la Federaci\u00f3n Catalana de Vela y la Asociaci\u00f3n Espa\u00f1ola de la Clase ILCA.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Tambi\u00e9n recibe el apoyo log\u00edstico del Camping La Ballena Alegre, del Club de Vela La Ballena Alegre y de la empresa de servicios n\u00e1uticos Nautivela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mayor parte de la flota de 2022 EurILCA Master European Championships, ya est\u00e1 en L&#8217;Escala y ha aprovechado el d\u00eda para confirmar inscripciones y superar la inspecci\u00f3n de su material de navegaci\u00f3n.<\/p>\n","protected":false},"featured_media":46299,"parent":0,"template":"","news-categories":[964],"news-tags":[],"class_list":["post-46304","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-regatas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00a1Empieza el 2022 EurILCA Master European Championships de l\u2019Escala! &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"La mayor parte de la flota de 2022 EurILCA Master European Championships, ya est\u00e1 en L&#039;Escala y ha aprovechado el d\u00eda para confirmar inscripciones y superar la inspecci\u00f3n de su material de navegaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Empieza el 2022 EurILCA Master European Championships de l\u2019Escala!\" \/>\n<meta property=\"og:description\" content=\"La mayor parte de la flota de 2022 EurILCA Master European Championships, ya est\u00e1 en L&#039;Escala y ha aprovechado el d\u00eda para confirmar inscripciones y superar la inspecci\u00f3n de su material de navegaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-07T15:49:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-2022-eurilca-master-european-championships-c-thom-touw-28.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/2022-eurilca-master-european-championships-inicio\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/2022-eurilca-master-european-championships-inicio\\\/\",\"name\":\"\u00a1Empieza el 2022 EurILCA Master European Championships de l\u2019Escala! &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/2022-eurilca-master-european-championships-inicio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/2022-eurilca-master-european-championships-inicio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/2022-nauticescala-2022-eurilca-master-european-championships-c-thom-touw-28.jpg\",\"datePublished\":\"2022-10-07T15:45:21+00:00\",\"dateModified\":\"2022-10-07T15:49:31+00:00\",\"description\":\"La mayor parte de la flota de 2022 EurILCA Master European Championships, ya est\u00e1 en L'Escala y ha aprovechado el d\u00eda para confirmar inscripciones y superar la inspecci\u00f3n de su material de navegaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/2022-eurilca-master-european-championships-inicio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/2022-eurilca-master-european-championships-inicio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/2022-eurilca-master-european-championships-inicio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/2022-nauticescala-2022-eurilca-master-european-championships-c-thom-touw-28.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/2022-nauticescala-2022-eurilca-master-european-championships-c-thom-touw-28.jpg\",\"width\":1800,\"height\":907},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/2022-eurilca-master-european-championships-inicio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00a1Empieza el 2022 EurILCA Master European Championships de l\u2019Escala!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00a1Empieza el 2022 EurILCA Master European Championships de l\u2019Escala! &#8211; Club N\u00e0utic L\u2019Escala","description":"La mayor parte de la flota de 2022 EurILCA Master European Championships, ya est\u00e1 en L'Escala y ha aprovechado el d\u00eda para confirmar inscripciones y superar la inspecci\u00f3n de su material de navegaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Empieza el 2022 EurILCA Master European Championships de l\u2019Escala!","og_description":"La mayor parte de la flota de 2022 EurILCA Master European Championships, ya est\u00e1 en L'Escala y ha aprovechado el d\u00eda para confirmar inscripciones y superar la inspecci\u00f3n de su material de navegaci\u00f3n.","og_url":"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2022-10-07T15:49:31+00:00","og_image":[{"width":1800,"height":907,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-2022-eurilca-master-european-championships-c-thom-touw-28.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/","url":"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/","name":"\u00a1Empieza el 2022 EurILCA Master European Championships de l\u2019Escala! &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-2022-eurilca-master-european-championships-c-thom-touw-28.jpg","datePublished":"2022-10-07T15:45:21+00:00","dateModified":"2022-10-07T15:49:31+00:00","description":"La mayor parte de la flota de 2022 EurILCA Master European Championships, ya est\u00e1 en L'Escala y ha aprovechado el d\u00eda para confirmar inscripciones y superar la inspecci\u00f3n de su material de navegaci\u00f3n.","breadcrumb":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-2022-eurilca-master-european-championships-c-thom-touw-28.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-2022-eurilca-master-european-championships-c-thom-touw-28.jpg","width":1800,"height":907},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/es\/noticias\/2022-eurilca-master-european-championships-inicio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"\u00a1Empieza el 2022 EurILCA Master European Championships de l\u2019Escala!"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news\/46304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/46299"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=46304"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-categories?post=46304"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-tags?post=46304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}