 {"id":52087,"date":"2023-04-09T19:32:23","date_gmt":"2023-04-09T17:32:23","guid":{"rendered":"https:\/\/nauticescala.com\/noticies\/campionat-espanya-optimist-2023-guanyadors\/"},"modified":"2023-04-09T20:00:20","modified_gmt":"2023-04-09T18:00:20","slug":"campeonato-espana-optimist-2023-ganadores","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/","title":{"rendered":"El Campeonato de Espa\u00f1a de Optimist 2023 de L&#8217;Escala ya tiene vencedores"},"content":{"rendered":"\n<p>Hoy, domingo 9 de abril, ha finalizado el <a href=\"https:\/\/nauticescala.com\/es\/compra-actividades-costa-brava\/2023-campeonato-de-espana-optimist\/\">Campeonato de Espa\u00f1a de Optimist 2023<\/a> del Club N\u00e0utic l&#8217;Escala. El catal\u00e1n Joan Domingo en categor\u00eda Sub 16 masculina, el balear Jorge Ben\u00edtez, en la Sub 13; la balear Martina Gomila en divisi\u00f3n femenina Sub 16 y la valenciana Marta Ferrando, en la Sub 13 se han proclamado vencedores y vencedoras de la regata. La comunidad aut\u00f3noma ganadora ha sido la Comunidad Valenciana.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\t<div class=\"offset-section\">\n\t    <div class=\"video-player\">\n\t        <div class=\"video-holder\">\n\t            <div class=\"video-element\" data-id=\"NGf5-j9_caY\" id=\"video-01\"><\/div>\n\t        <\/div><!-- end video-holder -->\n\t    <\/div><!-- end video-player -->\n\t<\/div><!-- end offset-section -->\t\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Las series finales se han completado seg\u00fan el programa previsto. Se han disputado tres nuevas pruebas con un viento del 110-120 de entre ocho y 12 nudos decisivas para determinar el podio final de todas las categor\u00edas.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El regatista del Club N\u00e0utic Cambrils Joan Domingo ha subido al podio acompa\u00f1ado del balear Hugo Rodr\u00edguez del Club N\u00e1utico S&#8217;Arenal y el valenciano Eduardo Reyes del Real Club N\u00e1utico de Valencia, segundo y tercero respectivamente.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-16-2.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>En la divisi\u00f3n masculina Sub 13, el balear Jorge Ben\u00edtez del Real Club N\u00e1utico Puerto de Pollensa se ha alzado con la victoria. La plata y el bronce fueron para el valenciano Arthur Baker del Club N\u00e1utico de J\u00e1vea y el balear Xuacu Garc\u00eda del Club N\u00e1utico Cala Gamba, respectivamente.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El t\u00edtulo femenino Sots 16 ha sido por Martina Gomila del Club N\u00e1utico S\u00b4Arenal. El segundo y tercer puesto de la categor\u00eda fueron por la valenciana Blanca Ferrando del Real Club N\u00e1utico de Valencia y la balear Beatriz Quintana del Club N\u00e1utico Cala Gamba, respectivamente.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-311.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Entre las m\u00e1s j\u00f3venes se levanta con la victoria Marta Ferrando del Real Club N\u00e1utico de Valencia. La canaria Lili Mar\u00eda Skomska del Real Club N\u00e1utico de Gran Canaria se adjudica la segunda plaza y la balear Mar\u00eda de Lucas Bestard del Real Club N\u00e1utico de Palma, la tercera.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>La regata ha contado con la participaci\u00f3n de 158 j\u00f3venes navegantes procedentes de once comunidades aut\u00f3nomas.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-302.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>La entrega de trofeos ha puesto punto y final al Campeonato de Espa\u00f1a de Optimist 2023 de L&#8217;Escala reconociendo a los ganadores y ganadoras del t\u00edtulo. El acto ha contado con las intervenciones del presidente del Club Narc\u00eds Carreres, el presidente de la Asociaci\u00f3n Espa\u00f1ola de la Clase Internacional Optimist Joaqu\u00edn Valero, el presidente de la Federaci\u00f3n Catalana de Vela Xavier Torres, Josep Maria Isern, vicepresidente de la Federaci\u00f3n Catalana de Vela y representante de la Federaci\u00f3n Espa\u00f1ola de Vela y el alcalde de l&#8217;Escala Josep Bofill.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-253.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El campeonato est\u00e1 organizado por el Club N\u00e0utic l&#8217;Escala por delegaci\u00f3n de la Real Federaci\u00f3n Espa\u00f1ola de Vela con la colaboraci\u00f3n de la Federaci\u00f3n Catalana de Vela y la Asociaci\u00f3n Espa\u00f1ola de la Clase Internacional Optimist y el patrocinio del Ayuntamiento de L&#8217;Escala, la Diputaci\u00f3n de Girona, el Patronato de Turismo Costa Brava Girona, Repsol y Bonpreu \u2013 Esclat.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Destaca, tambi\u00e9n, el apoyo recibido por parte de la Secretar\u00eda General del Deporte y de la Actividad F\u00edsica de la Generalitat de Catalu\u00f1a, Ports de la Generalitat, Nautivela, Intermar Sailing, Camping La Ballena Alegre, Vacances Costa Brava, L&#8217;Escala Resort y Hotel Nieves Mar.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n    \n        <div class=\"btn-box\">\n            <a href=\"https:\/\/nauticescala.com\/es\/compra-actividades-costa-brava\/2023-campeonato-de-espana-optimist\/\" target=\"_self\" class=\"btn btn-primary\">M\u00e9s informaci\u00f3<\/a>\n\n        \n        \n\n<\/div><!-- end btn-box -->\n\n   \n","protected":false},"excerpt":{"rendered":"<p>El Campeonato de Espa\u00f1a Optimist 2023 finaliza con las tres mangas de series finales previstas.<\/p>\n","protected":false},"featured_media":52066,"parent":0,"template":"","news-categories":[953,964],"news-tags":[],"class_list":["post-52087","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-deporte","news-categories-regatas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Campeonato de Espa\u00f1a de Optimist 2023 de L&#039;Escala ya tiene vencedores &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"El Campeonato de Espa\u00f1a Optimist 2023 finaliza con las tres mangas de series finales previstas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Campeonato de Espa\u00f1a de Optimist 2023 de L&#039;Escala ya tiene vencedores\" \/>\n<meta property=\"og:description\" content=\"El Campeonato de Espa\u00f1a Optimist 2023 finaliza con las tres mangas de series finales previstas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-09T18:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-286.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/campeonato-espana-optimist-2023-ganadores\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/campeonato-espana-optimist-2023-ganadores\\\/\",\"name\":\"El Campeonato de Espa\u00f1a de Optimist 2023 de L'Escala ya tiene vencedores &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/campeonato-espana-optimist-2023-ganadores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/campeonato-espana-optimist-2023-ganadores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-286.jpg\",\"datePublished\":\"2023-04-09T17:32:23+00:00\",\"dateModified\":\"2023-04-09T18:00:20+00:00\",\"description\":\"El Campeonato de Espa\u00f1a Optimist 2023 finaliza con las tres mangas de series finales previstas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/campeonato-espana-optimist-2023-ganadores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/campeonato-espana-optimist-2023-ganadores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/campeonato-espana-optimist-2023-ganadores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-286.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-286.jpg\",\"width\":1800,\"height\":907},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/campeonato-espana-optimist-2023-ganadores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El Campeonato de Espa\u00f1a de Optimist 2023 de L&#8217;Escala ya tiene vencedores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Campeonato de Espa\u00f1a de Optimist 2023 de L'Escala ya tiene vencedores &#8211; Club N\u00e0utic L\u2019Escala","description":"El Campeonato de Espa\u00f1a Optimist 2023 finaliza con las tres mangas de series finales previstas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/","og_locale":"es_ES","og_type":"article","og_title":"El Campeonato de Espa\u00f1a de Optimist 2023 de L'Escala ya tiene vencedores","og_description":"El Campeonato de Espa\u00f1a Optimist 2023 finaliza con las tres mangas de series finales previstas.","og_url":"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2023-04-09T18:00:20+00:00","og_image":[{"width":1800,"height":907,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-286.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/","url":"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/","name":"El Campeonato de Espa\u00f1a de Optimist 2023 de L'Escala ya tiene vencedores &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-286.jpg","datePublished":"2023-04-09T17:32:23+00:00","dateModified":"2023-04-09T18:00:20+00:00","description":"El Campeonato de Espa\u00f1a Optimist 2023 finaliza con las tres mangas de series finales previstas.","breadcrumb":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-286.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2023-club-nautic-lescala-campeonato-espana-optimist-lescala-2023-286.jpg","width":1800,"height":907},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/es\/noticias\/campeonato-espana-optimist-2023-ganadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"El Campeonato de Espa\u00f1a de Optimist 2023 de L&#8217;Escala ya tiene vencedores"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news\/52087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/52066"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=52087"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-categories?post=52087"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-tags?post=52087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}