 {"id":52494,"date":"2023-04-25T14:42:38","date_gmt":"2023-04-25T12:42:38","guid":{"rendered":"https:\/\/nauticescala.com\/?post_type=news&#038;p=52494"},"modified":"2023-04-25T14:46:55","modified_gmt":"2023-04-25T12:46:55","slug":"semana-de-los-parques-naturales-2023","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/","title":{"rendered":"Semana de los Parques Naturales 2023"},"content":{"rendered":"\n<p>El pr\u00f3ximo 24 de mayo es el D\u00eda Internacional de los Parques Naturales y con motivo de este d\u00eda, el Parque Natural del Montgr\u00ed y las Islas Medes celebra, del 19 al 27 de mayo, la Semana de los Parques Naturales.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Unos d\u00edas, pues, muy especiales para acercarse a disfrutar del Parque Natural del Montgr\u00ed desde el mar. \u00bfTe apuntas?<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Tanto si tienes embarcaci\u00f3n propia como si no tienes, tenemos propuestas para ti:<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h3 class=\"wp-block-heading\">\u00a1Ven a celebrar la Semana de los Parques Naturales 2023 en L&#8217;Escala!<\/h3>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n                            <div class=\"accordion-block\">\n                    <div id=\"accordion\" class=\"accordion\">\n                                                                            <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-01\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Con tu embarcaci\u00f3n<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-01\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-52499\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2022-nauticescala-juvenil-94.jpg\" alt=\"2022-nauticescala-campus Juvenil-94\" width=\"1800\" height=\"907\" srcset=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2022-nauticescala-juvenil-94.jpg 1800w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2022-nauticescala-juvenil-94-300x151.jpg 300w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2022-nauticescala-juvenil-94-1024x516.jpg 1024w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2022-nauticescala-juvenil-94-768x387.jpg 768w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2022-nauticescala-juvenil-94-1536x774.jpg 1536w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2022-nauticescala-juvenil-94-1000x504.jpg 1000w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2022-nauticescala-juvenil-94-700x353.jpg 700w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2022-nauticescala-juvenil-94-350x176.jpg 350w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2022-nauticescala-juvenil-94-100x50.jpg 100w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/04\/2022-nauticescala-juvenil-94-600x302.jpg 600w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/><\/p>\n<p>Desde L&#8217;Escala hasta l&#8217;Estartit, el Parque Natural del Montgr\u00ed nos ofrece un paraje espectacular para explorar navegando. Los acantilados se levantan y esconden rincones maravillosos como Cala Ferriol, Cala Pedrosa o La Foradada hasta llegar a las Islas Medas.<\/p>\n<p>Llegar navegando nos permite disfrutar de puntos accesibles s\u00f3lo por mar y si tu afici\u00f3n es el submarinismo, descubrir un fondo marino de gran valor ecol\u00f3gico, de fauna y flora exhuberantes, formaciones rocosas y cuevas para los m\u00e1s intr\u00e9pidos. \u00bfQuieres saber m\u00e1s?<\/p>\n<h3>\u00a1Consulta los <a href=\"https:\/\/parcsnaturals.gencat.cat\/es\/xarxa-de-parcs\/illes-medes\/gaudeix-del-parc\/equipaments-i-itineraris\/itineraris-marins\/index.html\">itinerarios marinos<\/a> que propone el Parque!<\/h3>\n<p>Tanto si decides disfrutarlo desde el fondo del mar como desde su superficie con un ba\u00f1o de naturaleza, recuerda hacerlo con responsabilidad. Respetar el entorno del Parque es la \u00fanica forma de preservarlo para que las futuras generaciones tambi\u00e9n puedan conocer esta experiencia.<\/p>\n<h3>\u00a1Consulta el <a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/06\/CAS_2021.pdf\" target=\"_blank\" rel=\"noopener\">siguiente documento<\/a> y practica la navegaci\u00f3n responsable!<\/h3>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-02\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>\u00bfNo tienes embarcaci\u00f3n? \u00a1Te llevamos!<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-02\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-24388\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/03\/2020-club-nautic-lescala-rg-sup-18.jpg\" alt=\"\" width=\"1200\" height=\"605\" srcset=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/03\/2020-club-nautic-lescala-rg-sup-18.jpg 1200w, https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/03\/2020-club-nautic-lescala-rg-sup-18-300x151.jpg 300w, https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/03\/2020-club-nautic-lescala-rg-sup-18-1024x516.jpg 1024w, https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/03\/2020-club-nautic-lescala-rg-sup-18-768x387.jpg 768w, https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/03\/2020-club-nautic-lescala-rg-sup-18-1000x504.jpg 1000w, https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/03\/2020-club-nautic-lescala-rg-sup-18-700x353.jpg 700w, https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/03\/2020-club-nautic-lescala-rg-sup-18-350x176.jpg 350w, https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/03\/2020-club-nautic-lescala-rg-sup-18-100x50.jpg 100w, https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/03\/2020-club-nautic-lescala-rg-sup-18-600x303.jpg 600w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>\u00bfTe gustar\u00eda descubrir el Parque Natural del Montgr\u00ed desde el mar, pero no tienes embarcaci\u00f3n propia? Ven al Club, \u00a1te ayudamos!<\/p>\n<p>En el Centro N\u00e1utico del Club encontrar\u00e1s siempre actividades deportivas para disfrutar del fant\u00e1stico entorno de l&#8217;Escala navegando en kayak, stand up paddle, vela ligera, crucero y remo de mar. Adem\u00e1s, para celebrar la Semana del Parque, te proponemos descubrir el Parque Natural del Montgr\u00ed con stand up paddle:<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><strong>Ruta Guiada de stand up paddle &#8211; s\u00e1bado 27 de mayo<\/strong>\n<ul>\n<li>Actividad en grupo reducido y con gu\u00eda-instructor para que saques el m\u00e1ximo provecho a la experiencia.<\/li>\n<li>Horario: 16:30 &#8211; 18:30 h<\/li>\n<li>Precio: 15 \u20ac\/persona<\/li>\n<li><a href=\"https:\/\/nauticescala.com\/activitats-costa-brava\/ruta-guiada-sup\/\">\u00a1Inscr\u00edbete!<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Desde el Club, sin embargo, tambi\u00e9n podr\u00e1s adentrarte en los paisajes del Parque practicando submarinismo, alquilando tu embarcaci\u00f3n o en una ruta de ch\u00e1rter a motor gracias a las empresas colaboradoras del Club.<\/p>\n<p><strong><a href=\"https:\/\/nauticescala.com\/es\/noticias\/descuentos-ventajas-2023\/\">\u00a1Cons\u00faltalas<\/a> y recuerda que si eres socio del Club podr\u00e1s acogerte a descuentos para disfrutar de sus servicios con las mejores condiciones!<\/strong><\/p>\n<ul>\n<li style=\"list-style-type: none;\"><\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                        <\/div><!-- end accordion -->\n                <\/div><!-- end accordion-block -->\n            \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\t<div class=\"container\">\n\n<div class=\"content-block\">\n \t \t\n \t \t   \n \t\t    <div class=\"partners-block\">\t    \t\n\t    \t  \n\t    \t   \n\t    \t\t\t        <ul class=\"partners-list\">\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/05\/logo-parc-natural-350x67.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/www.novaimport.com\/ca\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/05\/logo-novaimport-350x98.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"http:\/\/www.orcadiving.net\/ca\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/02\/orca-diving-home.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/www.creuers-marenostrum.com\/ca\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/02\/creuers-marenostrum-home.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t            \n\t\t        <\/ul><!-- end partners-list -->\t    \t\t\n\t    \t\t    <\/div><!-- end partners-block --> \t   \t\n \t   \n<\/div><!-- end content-block -->\n\n\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>El 24 de mayo es el D\u00eda Internacional de los Parques Naturales y con motivo de este d\u00eda, el Parque Natural del Montgr\u00ed y las Islas Medas celebra la Semana de los Parques Natural 2023. \u00a1Ven a disfrutarla desde el mar con el Club!<\/p>\n","protected":false},"featured_media":34047,"parent":0,"template":"","news-categories":[967],"news-tags":[],"class_list":["post-52494","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-social-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Semana de los Parques Naturales 2023 &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"El 24 de mayo es el D\u00eda Internacional de los Parques Naturales y con motivo de este d\u00eda, el Parque Natural del Montgr\u00ed y las Islas Medas celebra la Semana de los Parques Natural 2023. \u00a1Ven a disfrutarla desde el mar con el Club!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Semana de los Parques Naturales 2023\" \/>\n<meta property=\"og:description\" content=\"El 24 de mayo es el D\u00eda Internacional de los Parques Naturales y con motivo de este d\u00eda, el Parque Natural del Montgr\u00ed y las Islas Medas celebra la Semana de los Parques Natural 2023. \u00a1Ven a disfrutarla desde el mar con el Club!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-25T12:46:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/10\/2021-club-nautic-lescala-costra-brava-11.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/semana-de-los-parques-naturales-2023\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/semana-de-los-parques-naturales-2023\\\/\",\"name\":\"Semana de los Parques Naturales 2023 &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/semana-de-los-parques-naturales-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/semana-de-los-parques-naturales-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/2021-club-nautic-lescala-costra-brava-11.jpg\",\"datePublished\":\"2023-04-25T12:42:38+00:00\",\"dateModified\":\"2023-04-25T12:46:55+00:00\",\"description\":\"El 24 de mayo es el D\u00eda Internacional de los Parques Naturales y con motivo de este d\u00eda, el Parque Natural del Montgr\u00ed y las Islas Medas celebra la Semana de los Parques Natural 2023. \u00a1Ven a disfrutarla desde el mar con el Club!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/semana-de-los-parques-naturales-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/semana-de-los-parques-naturales-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/semana-de-los-parques-naturales-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/2021-club-nautic-lescala-costra-brava-11.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/2021-club-nautic-lescala-costra-brava-11.jpg\",\"width\":1800,\"height\":907,\"caption\":\"Club Nautic lEscala-el teu amarrador de lloguer per gaudir de la Costa Brava tot lany\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/semana-de-los-parques-naturales-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Semana de los Parques Naturales 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Semana de los Parques Naturales 2023 &#8211; Club N\u00e0utic L\u2019Escala","description":"El 24 de mayo es el D\u00eda Internacional de los Parques Naturales y con motivo de este d\u00eda, el Parque Natural del Montgr\u00ed y las Islas Medas celebra la Semana de los Parques Natural 2023. \u00a1Ven a disfrutarla desde el mar con el Club!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Semana de los Parques Naturales 2023","og_description":"El 24 de mayo es el D\u00eda Internacional de los Parques Naturales y con motivo de este d\u00eda, el Parque Natural del Montgr\u00ed y las Islas Medas celebra la Semana de los Parques Natural 2023. \u00a1Ven a disfrutarla desde el mar con el Club!","og_url":"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2023-04-25T12:46:55+00:00","og_image":[{"width":1800,"height":907,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/10\/2021-club-nautic-lescala-costra-brava-11.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/","url":"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/","name":"Semana de los Parques Naturales 2023 &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/10\/2021-club-nautic-lescala-costra-brava-11.jpg","datePublished":"2023-04-25T12:42:38+00:00","dateModified":"2023-04-25T12:46:55+00:00","description":"El 24 de mayo es el D\u00eda Internacional de los Parques Naturales y con motivo de este d\u00eda, el Parque Natural del Montgr\u00ed y las Islas Medas celebra la Semana de los Parques Natural 2023. \u00a1Ven a disfrutarla desde el mar con el Club!","breadcrumb":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/10\/2021-club-nautic-lescala-costra-brava-11.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/10\/2021-club-nautic-lescala-costra-brava-11.jpg","width":1800,"height":907,"caption":"Club Nautic lEscala-el teu amarrador de lloguer per gaudir de la Costa Brava tot lany"},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/es\/noticias\/semana-de-los-parques-naturales-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"Semana de los Parques Naturales 2023"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news\/52494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/34047"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=52494"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-categories?post=52494"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-tags?post=52494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}