 {"id":57501,"date":"2023-08-23T13:50:33","date_gmt":"2023-08-23T11:50:33","guid":{"rendered":"https:\/\/nauticescala.com\/noticies\/ocean-ecostructures\/"},"modified":"2023-08-24T16:39:09","modified_gmt":"2023-08-24T14:39:09","slug":"ocean-ecostructures","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/","title":{"rendered":"El Club con la regeneraci\u00f3n marina"},"content":{"rendered":"\n<p>El sistema de regeneraci\u00f3n de la biodiversidad marina Ocean Ecostructures est\u00e1 dando frutos en el Club. Las cuatro unidades del sistema de regeneraci\u00f3n de la Biodiversidad Marina Bioboosting System <a href=\"https:\/\/nauticescala.com\/es\/noticias\/alianza-ocean-ecostructures\/\">instalados hace poco m\u00e1s de un a\u00f1o<\/a> en el Club por parte de Ocean Ecostructures est\u00e1n generando un impacto positivo en el \u00e1mbito portuario de la entidad.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Por un lado, se ha detectado que las estructuras est\u00e1n produciendo una cifra de biomasa en aumento con un total de 2.781,8 g de peso seco. Por otro lado, las cuatro unidades han sido colonizadas por una gran variedad de organismos que incluye desde algas hasta peces pasando por especies como moluscos o esponjas.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/08\/2023-nauticescala-instalacio-ocean-ecostructures.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>As\u00ed lo ha revelado el informe de seguimiento presentado por la empresa este mes de agosto, lo que confirma que el sistema est\u00e1 dando sus frutos de cara a mejorar las condiciones ecol\u00f3gicas en el \u00e1mbito del puerto. Mediante esta t\u00e9cnica, el Club se convierte en un agente activo de la recuperaci\u00f3n de la biodiversidad y la lucha contra el cambio clim\u00e1tico.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Esta acci\u00f3n sigue las l\u00edneas estrat\u00e9gicas del mandato 2021-27 de la Junta Directiva del Club y su adhesi\u00f3n a los Objetivos de Desarrollo Sostenible 2030 de las Naciones Unidas. En este sentido, contribuye a los objetivos n\u00famero 14, protecci\u00f3n de la vida marina, y el 17, alianzas para lograrlos.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><strong>\u00bfQuieres conocer el n\u00famero de especies, la biomasa, el ox\u00edgeno generado y el CO2 capturado del ecosistema de L&#8217;Escala? \u00a1Consulta la App OceanEcostructures!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sistema de regeneraci\u00f3n de la biodiversidad marina Ocean Ecostructures contribuye a la mejora de las condiciones ecol\u00f3gicas del puerto.<\/p>\n","protected":false},"featured_media":57408,"parent":0,"template":"","news-categories":[956],"news-tags":[],"class_list":["post-57501","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-medio-ambiente"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Club con la regeneraci\u00f3n marina &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"El sistema de regeneraci\u00f3n de la biodiversidad marina Ocean Ecostructures contribuye a la mejora de las condiciones ecol\u00f3gicas del puerto.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Club con la regeneraci\u00f3n marina\" \/>\n<meta property=\"og:description\" content=\"El sistema de regeneraci\u00f3n de la biodiversidad marina Ocean Ecostructures contribuye a la mejora de las condiciones ecol\u00f3gicas del puerto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-24T14:39:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/08\/2023-nauticescala-rrpp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/ocean-ecostructures\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/ocean-ecostructures\\\/\",\"name\":\"El Club con la regeneraci\u00f3n marina &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/ocean-ecostructures\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/ocean-ecostructures\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2023-nauticescala-rrpp.jpg\",\"datePublished\":\"2023-08-23T11:50:33+00:00\",\"dateModified\":\"2023-08-24T14:39:09+00:00\",\"description\":\"El sistema de regeneraci\u00f3n de la biodiversidad marina Ocean Ecostructures contribuye a la mejora de las condiciones ecol\u00f3gicas del puerto.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/ocean-ecostructures\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/ocean-ecostructures\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/ocean-ecostructures\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2023-nauticescala-rrpp.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/2023-nauticescala-rrpp.jpg\",\"width\":1800,\"height\":907,\"caption\":\"2023-nauticescala-medi ambient-ocean ecostructures\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/ocean-ecostructures\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El Club con la regeneraci\u00f3n marina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Club con la regeneraci\u00f3n marina &#8211; Club N\u00e0utic L\u2019Escala","description":"El sistema de regeneraci\u00f3n de la biodiversidad marina Ocean Ecostructures contribuye a la mejora de las condiciones ecol\u00f3gicas del puerto.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/","og_locale":"es_ES","og_type":"article","og_title":"El Club con la regeneraci\u00f3n marina","og_description":"El sistema de regeneraci\u00f3n de la biodiversidad marina Ocean Ecostructures contribuye a la mejora de las condiciones ecol\u00f3gicas del puerto.","og_url":"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2023-08-24T14:39:09+00:00","og_image":[{"width":1800,"height":907,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/08\/2023-nauticescala-rrpp.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/","url":"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/","name":"El Club con la regeneraci\u00f3n marina &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/08\/2023-nauticescala-rrpp.jpg","datePublished":"2023-08-23T11:50:33+00:00","dateModified":"2023-08-24T14:39:09+00:00","description":"El sistema de regeneraci\u00f3n de la biodiversidad marina Ocean Ecostructures contribuye a la mejora de las condiciones ecol\u00f3gicas del puerto.","breadcrumb":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/08\/2023-nauticescala-rrpp.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/08\/2023-nauticescala-rrpp.jpg","width":1800,"height":907,"caption":"2023-nauticescala-medi ambient-ocean ecostructures"},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/es\/noticias\/ocean-ecostructures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"El Club con la regeneraci\u00f3n marina"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news\/57501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/57408"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=57501"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-categories?post=57501"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-tags?post=57501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}