 {"id":58470,"date":"2023-10-03T16:05:14","date_gmt":"2023-10-03T14:05:14","guid":{"rendered":"https:\/\/nauticescala.com\/noticies\/salons-nautics-2023\/"},"modified":"2023-10-20T17:40:02","modified_gmt":"2023-10-20T15:40:02","slug":"salones-nauticos-2023","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/","title":{"rendered":"Encuentra el Club en los salones n\u00e1uticos de oto\u00f1o"},"content":{"rendered":"\n<p>El verano se acaba, pero desde el Club seguimos a tu lado y aprovechamos los salones n\u00e1uticos de oto\u00f1o para acercarnos a ti en tu casa.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h3 class=\"wp-block-heading\" id=\"h-nos-vemos\">\u00bfNos vemos?<\/h3>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n                            <div class=\"accordion-block\">\n                    <div id=\"accordion\" class=\"accordion\">\n                                                                            <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-01\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Sal\u00f3n N\u00e1utico de Barcelona<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-01\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-58464\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/2022-nauticescala-salo-nautic-de-barcelona-1.jpg\" alt=\"2022-nauticescala-salo nautic de barcelona (1)\" width=\"1800\" height=\"907\" srcset=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/2022-nauticescala-salo-nautic-de-barcelona-1.jpg 1800w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/2022-nauticescala-salo-nautic-de-barcelona-1-300x151.jpg 300w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/2022-nauticescala-salo-nautic-de-barcelona-1-1024x516.jpg 1024w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/2022-nauticescala-salo-nautic-de-barcelona-1-768x387.jpg 768w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/2022-nauticescala-salo-nautic-de-barcelona-1-1536x774.jpg 1536w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/2022-nauticescala-salo-nautic-de-barcelona-1-1000x504.jpg 1000w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/2022-nauticescala-salo-nautic-de-barcelona-1-700x353.jpg 700w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/2022-nauticescala-salo-nautic-de-barcelona-1-350x176.jpg 350w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/2022-nauticescala-salo-nautic-de-barcelona-1-100x50.jpg 100w, https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/2022-nauticescala-salo-nautic-de-barcelona-1-600x302.jpg 600w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/><\/p>\n<p>Un a\u00f1o m\u00e1s, el <a href=\"https:\/\/www.salonnautico.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Sal\u00f3n N\u00e1utico de Barcelona<\/strong><\/a> es cita obligada para el Club y para todos los amantes de la n\u00e1utica deportiva y de recreo. La feria tendr\u00e1 lugar <strong>del 11 al 15 de octubre entre el Moll de la Fusta, el Moll d&#8217;Espanya y el Port Vell de la ciudad condal y estar\u00e1 abierta de 10 a 19 h.<\/strong><\/p>\n<p>Si tienes previsto visitarlo, podr\u00e1s encontrarnos en el stand de la Associaci\u00f3 Catalana de Ports i Tur\u00edstics (D478). En este espacio, podr\u00e1s informarte de las principales actividades y servicios portuarios de la temporada 2023-24.<\/p>\n<p>La agenda del Club en el Sal\u00f3n, adem\u00e1s, permitir\u00e1 conocer los primeros detalles de las pr\u00f3ximas ediciones del MedFoto y de la Ruta de la Tramuntana.<\/p>\n<p>La cuarta edici\u00f3n del Concurso Internacional de Fotograf\u00eda del Mediterr\u00e1neo <a href=\"https:\/\/medfoto.org\/?lang=es\" target=\"_blank\" rel=\"noopener\"><strong>MedFoto<\/strong><\/a> coorganizado por la Fundaci\u00f3 Alive y el Club con el apoyo de Ports de la Generalitat <strong>ser\u00e1 presentada en el stand de la Generalitat de Catalunya<\/strong> (E593). El encuentro tendr\u00e1 lugar el viernes 13 de octubre a las 17 h y contar\u00e1 con representantes de las tres entidades, as\u00ed como del Ayuntamiento de L&#8217;Escala.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-46540\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-salo-nautic-de-barcelona-6.jpg\" alt=\"\" width=\"1800\" height=\"907\" srcset=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-salo-nautic-de-barcelona-6.jpg 1800w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-salo-nautic-de-barcelona-6-300x151.jpg 300w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-salo-nautic-de-barcelona-6-1024x516.jpg 1024w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-salo-nautic-de-barcelona-6-768x387.jpg 768w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-salo-nautic-de-barcelona-6-1536x774.jpg 1536w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-salo-nautic-de-barcelona-6-1000x504.jpg 1000w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-salo-nautic-de-barcelona-6-700x353.jpg 700w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-salo-nautic-de-barcelona-6-350x176.jpg 350w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-salo-nautic-de-barcelona-6-100x50.jpg 100w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/2022-nauticescala-salo-nautic-de-barcelona-6-600x302.jpg 600w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/><\/p>\n<p>Este espacio ser\u00e1 tambi\u00e9n el <strong>viernes 13 a las 11 h<\/strong>, escenario de una<strong> mesa redonda dedicada al deporte adaptado<\/strong>. Xavi L\u00f3pez, director deportivo del Club, intervendr\u00e1 para dar a conocer los proyectos de vela adaptada del Club junto con un representante de Mifas, asociaci\u00f3n con la que el Club lleva a cabo el proyecto \u00abPor un mar accesible\u00bb.<\/p>\n<p>Por otro lado, el Club participar\u00e1 en la <strong>presentaci\u00f3n de la pr\u00f3xima edici\u00f3n de la <a href=\"https:\/\/www.larutadelatramuntana.com\/\" target=\"_blank\" rel=\"noopener\">Ruta de la Tramuntana<\/a><\/strong> como puerto de destino y coorganizador de la segunda etapa. Ser\u00e1 el mismo <strong>viernes 13 en el \u00c1gora Port<\/strong> (Portal de la Pau, Barcelona. Frente al monumento a Col\u00f3n y a la antigua sede de la Autoridad Portuaria) <strong>a las 17:15 h<\/strong>.<\/p>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-02\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Feria de Muestras de Girona<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-02\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-46820\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-11.jpg\" alt=\"\" width=\"1800\" height=\"907\" srcset=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-11.jpg 1800w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-11-300x151.jpg 300w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-11-1024x516.jpg 1024w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-11-768x387.jpg 768w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-11-1536x774.jpg 1536w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-11-1000x504.jpg 1000w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-11-700x353.jpg 700w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-11-350x176.jpg 350w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-11-100x50.jpg 100w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-11-600x302.jpg 600w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/><\/p>\n<p>Del <strong>28 de octubre al 1 de noviembre<\/strong>, los servicios portuarios y las actividades deportivas del Club se dar\u00e1n a conocer desde la <a href=\"https:\/\/firademostres.firagirona.com\/es\/\" target=\"_blank\" rel=\"noopener\"><strong>Feria de Muestras de Girona<\/strong><\/a>. Un a\u00f1o m\u00e1s, en el stand del Club encontrar\u00e1s toda la informaci\u00f3n que necesitas, pero tambi\u00e9n podr\u00e1s disfrutar de sorteos, retos y de una <strong>degustaci\u00f3n de anchoas y cava<\/strong> que tendr\u00e1 lugar el d\u00eda <strong>29 de octubre a las 12 h<\/strong>.<\/p>\n<p>El stand del Club en la Feria, tambi\u00e9n se convertir\u00e1 en un espacio para conocer y aprender gracias a la <strong>mesa redonda \u00abPor un mar accesible\u00bb<\/strong>. La charla se celebrar\u00e1 el d\u00eda <strong>31 de octubre a las 12 h<\/strong> y contar\u00e1 con las intervenciones de responsables tanto del Club como de la asociaci\u00f3n Mifas.<\/p>\n<p>La Feria de Muestras estar\u00e1 abierta de 10 a 20 h.<\/p>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-03\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Salon Nautique d\u2019Automne de Cap d\u2019Agde <\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-03\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-46824\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-4.jpg\" alt=\"\" width=\"1800\" height=\"907\" srcset=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-4.jpg 1800w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-4-300x151.jpg 300w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-4-1024x516.jpg 1024w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-4-768x387.jpg 768w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-4-1536x774.jpg 1536w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-4-1000x504.jpg 1000w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-4-700x353.jpg 700w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-4-350x176.jpg 350w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-4-100x50.jpg 100w, https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/2022-club-nautic-lescala-4-600x302.jpg 600w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/><\/p>\n<p>Si visitas el sur de Francia entre los d\u00edas 28 de octubre y 1 de noviembre, \u00a1te recomendamos que no te pierdas el <a href=\"https:\/\/www.capsalon.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Salon Nautique d\u2019Automne de Cap d\u2019Agde<\/strong><\/a>!<\/p>\n<p>Con la colaboraci\u00f3n de la Societ\u00e9 des R\u00e9gates d\u2019Agde et du Cap d\u2019Agde, <strong>daremos a conocer la pr\u00f3xima edici\u00f3n de L\u2019Escalagde el s\u00e1bado 28 de octubre a las 11:30 h<\/strong>. El acto finalizar\u00e1 con una degustaci\u00f3n de anchoas y vino de Cap d\u2019Agde.<\/p>\n<p>La feria n\u00e1utica estar\u00e1 abierta de 10 a 18 h y la entrada es gratuita.<\/p>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                        <\/div><!-- end accordion -->\n                <\/div><!-- end accordion-block -->\n            \n","protected":false},"excerpt":{"rendered":"<p>Un a\u00f1o m\u00e1s, aprovechamos los salones n\u00e1uticos de oto\u00f1o para acercarnos a ti. Nos podr\u00e1s encontrar en los salones de Barcelona, Girona y Agde.<\/p>\n","protected":false},"featured_media":58463,"parent":0,"template":"","news-categories":[1069],"news-tags":[],"class_list":["post-58470","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-port-2-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Encuentra el Club en los salones n\u00e1uticos de oto\u00f1o &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"Aprovechamos los salones n\u00e1uticos de oto\u00f1o para acercarnos a ti. Nos podr\u00e1s encontrar en los salones de Barcelona, Girona y Agde. \u00a1Vis\u00edtanos!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuentra el Club en los salones n\u00e1uticos de oto\u00f1o\" \/>\n<meta property=\"og:description\" content=\"Aprovechamos los salones n\u00e1uticos de oto\u00f1o para acercarnos a ti. Nos podr\u00e1s encontrar en los salones de Barcelona, Girona y Agde. \u00a1Vis\u00edtanos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-20T15:40:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/snb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1004\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salones-nauticos-2023\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salones-nauticos-2023\\\/\",\"name\":\"Encuentra el Club en los salones n\u00e1uticos de oto\u00f1o &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salones-nauticos-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salones-nauticos-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/snb.jpg\",\"datePublished\":\"2023-10-03T14:05:14+00:00\",\"dateModified\":\"2023-10-20T15:40:02+00:00\",\"description\":\"Aprovechamos los salones n\u00e1uticos de oto\u00f1o para acercarnos a ti. Nos podr\u00e1s encontrar en los salones de Barcelona, Girona y Agde. \u00a1Vis\u00edtanos!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salones-nauticos-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salones-nauticos-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salones-nauticos-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/snb.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/snb.jpg\",\"width\":2000,\"height\":1004},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salones-nauticos-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Encuentra el Club en los salones n\u00e1uticos de oto\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Encuentra el Club en los salones n\u00e1uticos de oto\u00f1o &#8211; Club N\u00e0utic L\u2019Escala","description":"Aprovechamos los salones n\u00e1uticos de oto\u00f1o para acercarnos a ti. Nos podr\u00e1s encontrar en los salones de Barcelona, Girona y Agde. \u00a1Vis\u00edtanos!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/","og_locale":"es_ES","og_type":"article","og_title":"Encuentra el Club en los salones n\u00e1uticos de oto\u00f1o","og_description":"Aprovechamos los salones n\u00e1uticos de oto\u00f1o para acercarnos a ti. Nos podr\u00e1s encontrar en los salones de Barcelona, Girona y Agde. \u00a1Vis\u00edtanos!","og_url":"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2023-10-20T15:40:02+00:00","og_image":[{"width":2000,"height":1004,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/snb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/","url":"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/","name":"Encuentra el Club en los salones n\u00e1uticos de oto\u00f1o &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/snb.jpg","datePublished":"2023-10-03T14:05:14+00:00","dateModified":"2023-10-20T15:40:02+00:00","description":"Aprovechamos los salones n\u00e1uticos de oto\u00f1o para acercarnos a ti. Nos podr\u00e1s encontrar en los salones de Barcelona, Girona y Agde. \u00a1Vis\u00edtanos!","breadcrumb":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/snb.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/10\/snb.jpg","width":2000,"height":1004},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/es\/noticias\/salones-nauticos-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"Encuentra el Club en los salones n\u00e1uticos de oto\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news\/58470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/58463"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=58470"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-categories?post=58470"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-tags?post=58470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}