 {"id":68611,"date":"2024-08-27T16:26:00","date_gmt":"2024-08-27T14:26:00","guid":{"rendered":"https:\/\/nauticescala.com\/noticies\/un-port-blau\/"},"modified":"2024-08-28T17:21:32","modified_gmt":"2024-08-28T15:21:32","slug":"un-puerto-azul","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/","title":{"rendered":"Un Puerto Azul gracias a las nuevas tecnolog\u00edas"},"content":{"rendered":"\n<p>El Club ha adquirido una unidad de la bomba DPOL de Ekkopol. Situado sobre la l\u00e1mina de agua del puerto, este aparato recoge residuos flotantes e hidrocarburos de forma autom\u00e1tica durante las 24 horas del d\u00eda.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Su implementaci\u00f3n, contemplada en el plan de acciones 2024 del Club, optimiza la calidad del agua del interior de la d\u00e1rsena, contribuyendo a la regeneraci\u00f3n de su biodiversidad. El proyecto ha recibido la financiaci\u00f3n del Grup d\u2019Acci\u00f3 Local Pesquer Costa Brava, el Fondo Europeo Mar\u00edtimo y de la Pesca y el Departamento de Acci\u00f3n Clim\u00e1tica, Alimentaci\u00f3n y Agenda Rural de la Generalitat de Catalunya.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/04\/2024-nauticescala-detalls-10.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Trabaja as\u00ed por un Puerto Azul manteniendo sus instalaciones limpias. En este sentido, pero sobre tierra, la llegada de una nueva escoba el\u00e9ctrica facilitar\u00e1 las tareas de limpieza exterior que realiza a diario el equipo de Marineria del Club.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h3 class=\"wp-block-heading\"><a href=\"https:\/\/nauticescala.com\/es\/puerto-en-la-costa-brava\/un-puerto-responsable\/\">Consulta las acciones medioambientales que lleva a cabo el Club<\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Un Puerto Azul: El Club apuesta por las nuevas tecnolog\u00edas para mantener el puerto y las aguas interiores en buen estado.<\/p>\n","protected":false},"featured_media":72788,"parent":0,"template":"","news-categories":[956],"news-tags":[],"class_list":["post-68611","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-medio-ambiente"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Un Puerto Azul gracias a las nuevas tecnolog\u00edas &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"Un Puerto Azul: El Club apuesta por las nuevas tecnolog\u00edas para mantener el puerto y las aguas interiores en buen estado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un Puerto Azul gracias a las nuevas tecnolog\u00edas\" \/>\n<meta property=\"og:description\" content=\"Un Puerto Azul: El Club apuesta por las nuevas tecnolog\u00edas para mantener el puerto y las aguas interiores en buen estado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-28T15:21:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/05\/2024-nauticescala-detalls-marina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/un-puerto-azul\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/un-puerto-azul\\\/\",\"name\":\"Un Puerto Azul gracias a las nuevas tecnolog\u00edas &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/un-puerto-azul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/un-puerto-azul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2024-nauticescala-detalls-marina.jpg\",\"datePublished\":\"2024-08-27T14:26:00+00:00\",\"dateModified\":\"2024-08-28T15:21:32+00:00\",\"description\":\"Un Puerto Azul: El Club apuesta por las nuevas tecnolog\u00edas para mantener el puerto y las aguas interiores en buen estado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/un-puerto-azul\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/un-puerto-azul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/un-puerto-azul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2024-nauticescala-detalls-marina.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/2024-nauticescala-detalls-marina.jpg\",\"width\":1800,\"height\":907},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/un-puerto-azul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Un Puerto Azul gracias a las nuevas tecnolog\u00edas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Un Puerto Azul gracias a las nuevas tecnolog\u00edas &#8211; Club N\u00e0utic L\u2019Escala","description":"Un Puerto Azul: El Club apuesta por las nuevas tecnolog\u00edas para mantener el puerto y las aguas interiores en buen estado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/","og_locale":"es_ES","og_type":"article","og_title":"Un Puerto Azul gracias a las nuevas tecnolog\u00edas","og_description":"Un Puerto Azul: El Club apuesta por las nuevas tecnolog\u00edas para mantener el puerto y las aguas interiores en buen estado.","og_url":"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2024-08-28T15:21:32+00:00","og_image":[{"width":1800,"height":907,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/05\/2024-nauticescala-detalls-marina.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/","url":"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/","name":"Un Puerto Azul gracias a las nuevas tecnolog\u00edas &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/05\/2024-nauticescala-detalls-marina.jpg","datePublished":"2024-08-27T14:26:00+00:00","dateModified":"2024-08-28T15:21:32+00:00","description":"Un Puerto Azul: El Club apuesta por las nuevas tecnolog\u00edas para mantener el puerto y las aguas interiores en buen estado.","breadcrumb":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/05\/2024-nauticescala-detalls-marina.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/05\/2024-nauticescala-detalls-marina.jpg","width":1800,"height":907},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/es\/noticias\/un-puerto-azul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"Un Puerto Azul gracias a las nuevas tecnolog\u00edas"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news\/68611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/72788"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=68611"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-categories?post=68611"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-tags?post=68611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}