 {"id":76614,"date":"2025-02-11T13:37:23","date_gmt":"2025-02-11T12:37:23","guid":{"rendered":"https:\/\/nauticescala.com\/noticies\/esports-nautics-2025\/"},"modified":"2025-02-13T18:15:57","modified_gmt":"2025-02-13T17:15:57","slug":"deportes-nauticos-2025","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/","title":{"rendered":"Deportes n\u00e1uticos 2025: \u00a1m\u00e1xima diversi\u00f3n!"},"content":{"rendered":"\n<p>En el Centro N\u00e1utico del Club encontrar\u00e1s las propuestas que necesitas: vela de crucero, vela ligera, remo de mar, kayak, stand up paddle\u2026<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h3 class=\"wp-block-heading\">\u00a1Descubre las novedades de la temporada y elige o combina a tu gusto!<\/h3>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Este 2025, el objetivo del equipo ser\u00e1 garantizar la mejor agenda y la mejor calidad en las actividades y servicios deportivos del Centro, con especial atenci\u00f3n a los programas de abonado a la instalaci\u00f3n, a los cursos de formaci\u00f3n y a los campus multiactividad.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n                            <div class=\"accordion-block\">\n                    <div id=\"accordion\" class=\"accordion\">\n                                                                            <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-01\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Proyectos<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-01\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p><strong>Se reforzar\u00e1n los equipos de competici\u00f3n infantil, juvenil y adulto del Club<\/strong> ofreciendo el apoyo necesario a sus miembros, que act\u00faan como embajadores del Club en aguas catalanas y m\u00e1s all\u00e1.<\/p>\n<p>Por otro lado, <strong>se dar\u00e1 continuidad a los proyectos:<\/strong><\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><span style=\"text-decoration: underline;\">Por un mar joven:<\/span> creado con el prop\u00f3sito de la actividad f\u00edsica en el medio natural entre los j\u00f3venes, este proyecto integra iniciativas como las Extraescolares Juveniles del Club.<\/li>\n<li><span style=\"text-decoration: underline;\">Por un mar accesible:<\/span> este programa, dirigido a facilitar el acceso al mar a las personas con discapacidad a trav\u00e9s del deporte de la vela, llegar\u00e1 este a\u00f1o a su tercera edici\u00f3n.<\/li>\n<li><span style=\"text-decoration: underline;\">Deporte Azul e Instituto de la Vela:<\/span> estas dos propuestas promueven la pr\u00e1ctica de los deportes n\u00e1uticos entre los alumnos de los centros escolares de L\u2019Escala.<\/li>\n<li><a href=\"https:\/\/nauticescala.com\/es\/compra-actividades-en-la-costa-brava\/?date-range=20250401-20250630&amp;orderby=dates\"><span style=\"text-decoration: underline;\">Actividades previstas:<\/span><\/a> ya puedes consultar las actividades previstas para la primavera y la Semana Santa 2025 y el d\u00eda 1 de marzo abriremos las inscripciones de los Campus de Verano para socios del Club.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li style=\"list-style-type: none;\"><\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-02\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Instalaciones <\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-02\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Reestructuraci\u00f3n de la oficina deportiva para mejorar el servicio y el control de las actividades.<\/li>\n<li>Adaptaci\u00f3n del aula del Centro N\u00e1utico como sala de fitness a disposici\u00f3n gratuita de los abonados en horarios de apertura de la instalaci\u00f3n con reserva previa.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-03\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Embarcaciones <\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-03\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p>Ampliar y renovar la flota es un trabajo continuo con el que procuramos ofrecerte siempre un servicio de la mejor calidad.<\/p>\n<h3>Novedades:<\/h3>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Incorporaci\u00f3n de una nueva unidad de la modalidad Catamar\u00e1n RS CAT 16.<\/li>\n<li>Actualizaci\u00f3n de parte de la flota de SUP y kayak, as\u00ed como de los accesorios de las embarcaciones ILCA, J70 y Raquero.<\/li>\n<li>Sustituci\u00f3n de una de las embarcaciones de seguridad para garantizar el mejor servicio a las personas usuar<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                        <\/div><!-- end accordion -->\n                <\/div><!-- end accordion-block -->\n            \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<h3 class=\"wp-block-heading\">M\u00e1s la informaci\u00f3n en la secci\u00f3n del <a href=\"https:\/\/nauticescala.com\/es\/actividades-nauticas-en-la-costa-brava\/\">centro de actividades n\u00e1uticas<\/a>!<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Este 2025, disfruta de la m\u00e1xima diversi\u00f3n con los deportes n\u00e1uticos en el Centro N\u00e1utico del Club!<\/p>\n","protected":false},"featured_media":67218,"parent":0,"template":"","news-categories":[953],"news-tags":[],"class_list":["post-76614","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-deporte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Deportes n\u00e1uticos 2025: \u00a1m\u00e1xima diversi\u00f3n! &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"\u00a1Este 2025, disfruta de la m\u00e1xima diversi\u00f3n con los deportes n\u00e1uticos en el Centro N\u00e1utico del Club!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deportes n\u00e1uticos 2025: \u00a1m\u00e1xima diversi\u00f3n!\" \/>\n<meta property=\"og:description\" content=\"\u00a1Este 2025, disfruta de la m\u00e1xima diversi\u00f3n con los deportes n\u00e1uticos en el Centro N\u00e1utico del Club!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-13T17:15:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/03\/2023-nauticescala-creuer-curs-vela-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/deportes-nauticos-2025\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/deportes-nauticos-2025\\\/\",\"name\":\"Deportes n\u00e1uticos 2025: \u00a1m\u00e1xima diversi\u00f3n! &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/deportes-nauticos-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/deportes-nauticos-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2023-nauticescala-creuer-curs-vela-2.jpg\",\"datePublished\":\"2025-02-11T12:37:23+00:00\",\"dateModified\":\"2025-02-13T17:15:57+00:00\",\"description\":\"\u00a1Este 2025, disfruta de la m\u00e1xima diversi\u00f3n con los deportes n\u00e1uticos en el Centro N\u00e1utico del Club!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/deportes-nauticos-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/deportes-nauticos-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/deportes-nauticos-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2023-nauticescala-creuer-curs-vela-2.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2023-nauticescala-creuer-curs-vela-2.jpg\",\"width\":1800,\"height\":907},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/deportes-nauticos-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Deportes n\u00e1uticos 2025: \u00a1m\u00e1xima diversi\u00f3n!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deportes n\u00e1uticos 2025: \u00a1m\u00e1xima diversi\u00f3n! &#8211; Club N\u00e0utic L\u2019Escala","description":"\u00a1Este 2025, disfruta de la m\u00e1xima diversi\u00f3n con los deportes n\u00e1uticos en el Centro N\u00e1utico del Club!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Deportes n\u00e1uticos 2025: \u00a1m\u00e1xima diversi\u00f3n!","og_description":"\u00a1Este 2025, disfruta de la m\u00e1xima diversi\u00f3n con los deportes n\u00e1uticos en el Centro N\u00e1utico del Club!","og_url":"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2025-02-13T17:15:57+00:00","og_image":[{"width":1800,"height":907,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/03\/2023-nauticescala-creuer-curs-vela-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/","url":"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/","name":"Deportes n\u00e1uticos 2025: \u00a1m\u00e1xima diversi\u00f3n! &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/03\/2023-nauticescala-creuer-curs-vela-2.jpg","datePublished":"2025-02-11T12:37:23+00:00","dateModified":"2025-02-13T17:15:57+00:00","description":"\u00a1Este 2025, disfruta de la m\u00e1xima diversi\u00f3n con los deportes n\u00e1uticos en el Centro N\u00e1utico del Club!","breadcrumb":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/03\/2023-nauticescala-creuer-curs-vela-2.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/03\/2023-nauticescala-creuer-curs-vela-2.jpg","width":1800,"height":907},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/es\/noticias\/deportes-nauticos-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"Deportes n\u00e1uticos 2025: \u00a1m\u00e1xima diversi\u00f3n!"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news\/76614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/67218"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=76614"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-categories?post=76614"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-tags?post=76614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}