 {"id":93106,"date":"2025-10-16T11:14:49","date_gmt":"2025-10-16T09:14:49","guid":{"rendered":"https:\/\/nauticescala.com\/?post_type=news&#038;p=93106"},"modified":"2025-10-18T12:33:54","modified_gmt":"2025-10-18T10:33:54","slug":"salud-azul","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/","title":{"rendered":"El Club N\u00e0utic l\u2019Escala y el ABS l\u2019Escala impulsan la \u201cSalud azul\u201d con tres nuevas actividades terap\u00e9uticas"},"content":{"rendered":"\n<p><em>El uso del mar se consolida como una herramienta de salud comunitaria, ampliando los beneficios f\u00edsicos y emocionales para pacientes con ansiedad, discapacidad temporal y c\u00e1ncer.<\/em> <em>Entre las acciones, destaca el Dragon Boat, destinado a personas que hayan superado cualquier tipo de c\u00e1ncer.<\/em><\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El Club N\u00e0utic l\u2019Escala y el \u00c1rea B\u00e1sica de Salud (ABS) de l\u2019Escala impulsan tres nuevas actividades n\u00e1uticas terap\u00e9uticas con el objetivo de mejorar el bienestar f\u00edsico y emocional de los pacientes. De este modo, el uso del mar y las actividades mar\u00edtimas se consolidan como una herramienta terap\u00e9utica y se incorporan a las propuestas de salud comunitaria que ofrece el ABS para la recuperaci\u00f3n f\u00edsica y emocional de los pacientes, la llamada \u201cSalud azul\u201d.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Este proyecto tiene como punto de partida la prueba piloto pionera que se llev\u00f3 a cabo en los meses de junio y julio, con el apoyo de la Universidad de Barcelona y Dipsalut, en la que pacientes con trastornos de ansiedad del ABS l\u2019Escala participaron en sesiones de navegaci\u00f3n de vela ligera del Club N\u00e0utic l\u2019Escala para mejorar su bienestar emocional.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-4.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><br><strong>Tres nuevas actividades<\/strong><\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Este mes de octubre se retomar\u00e1 esta actividad de vela ligera y se ampl\u00edan las propuestas relacionadas con el mar para dirigirse a nuevos grupos de pacientes.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Se estrenar\u00e1 la navegaci\u00f3n con embarcaciones adaptadas para personas con una discapacidad temporal. El objetivo es acelerar su recuperaci\u00f3n y mejorar la condici\u00f3n f\u00edsica mediante la actividad mar\u00edtima.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>La tercera propuesta consiste en el Dragon Boat (Bote Drag\u00f3n) que, gracias al apoyo econ\u00f3mico de la Fundaci\u00f3n \u201cla Caixa\u201d, este curso 2025-2026 se podr\u00e1 ofrecer de manera gratuita. Es una modalidad de pirag\u00fcismo proveniente de antiguas tradiciones chinas con la figura del drag\u00f3n como s\u00edmbolo principal. Es apta para todos, f\u00e1cil de aprender, no requiere experiencia previa y permite a los palistas practicar ejercicio f\u00edsico al aire libre, reforzando el sentido de equipo y el objetivo com\u00fan.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Esta actividad est\u00e1 destinada a personas que hayan superado cualquier tipo de c\u00e1ncer, buscando mejorar su calidad de vida e incidir en aspectos emocionales y sociales como el trabajo en grupo y la autoestima.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Adem\u00e1s de contar con la financiaci\u00f3n de la Fundaci\u00f3n \u201cla Caixa\u201d, el Dragon Boat es posible gracias a la colaboraci\u00f3n del Ayuntamiento de l\u2019Escala y Dipsalut, la implicaci\u00f3n de la Fundaci\u00f3n Salut Empord\u00e0 y la aportaci\u00f3n log\u00edstica y t\u00e9cnica del Club N\u00e0utic l\u2019Escala.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-3.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><br><strong>Actividades de salud comunitaria<\/strong><\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Estas tres acciones de \u201cSalud azul\u201d se enmarcan dentro de la amplia oferta de actividades de salud comunitaria que el ABS l\u2019Escala retoma este mes de octubre tras la pausa veraniega. El ABS cuenta con una treintena de propuestas gracias a la colaboraci\u00f3n de entidades locales como el Club Tennis Taula CER l\u2019Escala, el Club N\u00e0utic l\u2019Escala y el Club Rem l\u2019Escala.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Estas actividades incluyen propuestas consolidadas y novedades: desde tenis de mesa o f\u00fatbol para personas mayores de 60 a\u00f1os, hasta sesiones para personas cuidadoras, para algias cr\u00f3nicas o fragilidad, hasta grupos de deshabituaci\u00f3n tab\u00e1quica, menopausia o cambio de h\u00e1bitos alimentarios, pasando por mindfulness, danzaterapia y Qi Gong.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\t<div class=\"container\">\n\n<div class=\"content-block\">\n \t \t\n \t \t   \n \t\t    <div class=\"partners-block\">\t    \t\n\t    \t\t    \t\t<h3>Proyecto financiado por: <\/h3>\n\t    \t  \n\t    \t   \n\t    \t\t\t        <ul class=\"partners-list\">\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-2-350x51.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/logo-dipsalut-jpg-350x162.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/fundacio-salut-emporda.png\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/01\/ajuntament-escala-1.webp\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t            \n\t\t        <\/ul><!-- end partners-list -->\t    \t\t\n\t    \t\t    <\/div><!-- end partners-block --> \t   \t\n \t   \n<\/div><!-- end content-block -->\n\n\t<\/div>\n\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n","protected":false},"excerpt":{"rendered":"<p>Una prueba piloto en L\u2019Escala analiza los beneficios de la navegaci\u00f3n en el bienestar emocional. Descubre el proyecto Salut Blava.<\/p>\n","protected":false},"featured_media":93245,"parent":0,"template":"","news-categories":[953],"news-tags":[],"class_list":["post-93106","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-deporte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Salut Blava: mar como terapia emocional en el Club N\u00e0utic l\u2019Escala<\/title>\n<meta name=\"description\" content=\"Una prueba piloto en L\u2019Escala analiza los beneficios de la navegaci\u00f3n en el bienestar emocional. Descubre el proyecto Salut Blava.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Club N\u00e0utic l\u2019Escala y el ABS l\u2019Escala impulsan la \u201cSalud azul\u201d con tres nuevas actividades terap\u00e9uticas\" \/>\n<meta property=\"og:description\" content=\"Una prueba piloto en L\u2019Escala analiza los beneficios de la navegaci\u00f3n en el bienestar emocional. Descubre el proyecto Salut Blava.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-18T10:33:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"905\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salud-azul\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salud-azul\\\/\",\"name\":\"Salut Blava: mar como terapia emocional en el Club N\u00e0utic l\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salud-azul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salud-azul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/2025-nauticescala-rem-salut-blava-2.jpg\",\"datePublished\":\"2025-10-16T09:14:49+00:00\",\"dateModified\":\"2025-10-18T10:33:54+00:00\",\"description\":\"Una prueba piloto en L\u2019Escala analiza los beneficios de la navegaci\u00f3n en el bienestar emocional. Descubre el proyecto Salut Blava.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salud-azul\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salud-azul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salud-azul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/2025-nauticescala-rem-salut-blava-2.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/2025-nauticescala-rem-salut-blava-2.jpg\",\"width\":1800,\"height\":905},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/salud-azul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El Club N\u00e0utic l\u2019Escala y el ABS l\u2019Escala impulsan la \u201cSalud azul\u201d con tres nuevas actividades terap\u00e9uticas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Salut Blava: mar como terapia emocional en el Club N\u00e0utic l\u2019Escala","description":"Una prueba piloto en L\u2019Escala analiza los beneficios de la navegaci\u00f3n en el bienestar emocional. Descubre el proyecto Salut Blava.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/","og_locale":"es_ES","og_type":"article","og_title":"El Club N\u00e0utic l\u2019Escala y el ABS l\u2019Escala impulsan la \u201cSalud azul\u201d con tres nuevas actividades terap\u00e9uticas","og_description":"Una prueba piloto en L\u2019Escala analiza los beneficios de la navegaci\u00f3n en el bienestar emocional. Descubre el proyecto Salut Blava.","og_url":"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2025-10-18T10:33:54+00:00","og_image":[{"width":1800,"height":905,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/","url":"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/","name":"Salut Blava: mar como terapia emocional en el Club N\u00e0utic l\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-2.jpg","datePublished":"2025-10-16T09:14:49+00:00","dateModified":"2025-10-18T10:33:54+00:00","description":"Una prueba piloto en L\u2019Escala analiza los beneficios de la navegaci\u00f3n en el bienestar emocional. Descubre el proyecto Salut Blava.","breadcrumb":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-2.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-2.jpg","width":1800,"height":905},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/es\/noticias\/salud-azul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"El Club N\u00e0utic l\u2019Escala y el ABS l\u2019Escala impulsan la \u201cSalud azul\u201d con tres nuevas actividades terap\u00e9uticas"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news\/93106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/93245"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=93106"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-categories?post=93106"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-tags?post=93106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}