 {"id":93811,"date":"2025-11-21T15:17:52","date_gmt":"2025-11-21T14:17:52","guid":{"rendered":"https:\/\/nauticescala.com\/?post_type=news&#038;p=93811"},"modified":"2025-11-21T15:59:16","modified_gmt":"2025-11-21T14:59:16","slug":"mullat-2025","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/","title":{"rendered":"Aportaci\u00f3n de 2000 euros para la esclerosis m\u00faltiple"},"content":{"rendered":"\n<p><strong>L\u2019Escala, 14 de noviembre<\/strong><\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El Club N\u00e1utico L\u2019Escala ha hecho entrega del cheque solidario a la\u00a0Fundaci\u00f3n Esclerosis M\u00faltiple<strong> <\/strong>(FEM), con un total de\u00a02.000 \u20ac recaudados\u00a0gracias a la campa\u00f1a\u00a0<em>Mulla&#8217;t por la Esclerosis M\u00faltiple<\/em>. Esta aportaci\u00f3n procede de la jornada celebrada el pasado 12 de julio, con el objetivo de apoyar a las personas afectadas por esta enfermedad e impulsar la investigaci\u00f3n para frenar su progresi\u00f3n.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/11\/2025-nauticescala-mullat-9.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><br>El acto de entrega tuvo lugar en la sede administrativa del Club y cont\u00f3 con la presencia del presidente del Club,&nbsp;Narc\u00eds Carreras, el director gerente&nbsp;<strong>Raimon Roca<\/strong>, la responsable de comunicaci\u00f3n y campa\u00f1as en Girona de la FEM&nbsp;Montse Prats, y&nbsp;Carles Bech&nbsp;en representaci\u00f3n de&nbsp;Colors Olympia Grup, as\u00ed como&nbsp;Jotun, y tambi\u00e9n&nbsp;Enric Riera, usuario y navegante del Club N\u00e1utico L\u2019Escala, que quiso sumarse a este momento tan especial.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El Club se muestra muy orgulloso de esta acci\u00f3n, posible gracias a la implicaci\u00f3n de socios, usuarios y colaboradores, que participaron activamente en la jornada del 12 de julio. Ese d\u00eda, los asistentes pudieron disfrutar de modalidades como&nbsp;kayak y stand up paddle&nbsp;en un ambiente festivo y solidario, con la posibilidad de llevarse un obsequio y adquirir art\u00edculos de la campa\u00f1a para sumar a la recaudaci\u00f3n. Gracias a esta suma de esfuerzos, al apoyo imprescindible de las empresas&nbsp;Jotun&nbsp;y&nbsp;Olympia, y a la aportaci\u00f3n complementaria del Club para alcanzar el importe final, se ha conseguido&nbsp;duplicar el objetivo inicial, demostrando la fuerza de la comunidad n\u00e1utica.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/11\/2025-nauticescala-mullat-11.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><br>Con esta acci\u00f3n, el Club reafirma que su fuerza no est\u00e1 solo en el mar, sino tambi\u00e9n en las personas. Queremos facilitar que todos puedan disfrutar del mar y, al mismo tiempo, contribuir a causas que importan. Cada gesto solidario suma para construir una comunidad m\u00e1s justa y saludable, y esto forma parte de nuestro ADN: acercar el mar, crear v\u00ednculos y hacer que la experiencia n\u00e1utica sea accesible y significativa.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>El Club quiere agradecer la implicaci\u00f3n de todos los participantes y el apoyo de las empresas colaboradoras que han hecho posible esta iniciativa. Acciones como esta son un ejemplo del compromiso del Club con los&nbsp;Objetivos de Desarrollo Sostenible (ODS)&nbsp;y la&nbsp;Agenda 2030.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/11\/2025-nauticescala-mullat-5.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\t<div class=\"container\">\n\n<div class=\"content-block\">\n \t \t\n \t \t   \n \t\t    <div class=\"partners-block\">\t    \t\n\t    \t  \n\t    \t   \n\t    \t\t\t        <ul class=\"partners-list\">\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/olympiagrup.com\/es\/colors\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/03\/jotun-home-1.jpg\" alt=\"Jotun-Home\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/www.jotun.com\/es-es\/decorative\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/olympia-grup-350x59.jpg\" alt=\"Olympia grup\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t            \n\t\t        <\/ul><!-- end partners-list -->\t    \t\t\n\t    \t\t    <\/div><!-- end partners-block --> \t   \t\n \t   \n<\/div><!-- end content-block -->\n\n\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>El Club N\u00e0utic l\u2019Escala ha hecho entrega, juntamente con Jotun y Colors Olympia Grup del tal\u00f3n solidario a la Fundaci\u00f3n Esclerosi M\u00faltiple (FEM).<\/p>\n","protected":false},"featured_media":93774,"parent":0,"template":"","news-categories":[953],"news-tags":[],"class_list":["post-93811","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-deporte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aportaci\u00f3n de 2000 euros para la esclerosis m\u00faltiple &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aportaci\u00f3n de 2000 euros para la esclerosis m\u00faltiple\" \/>\n<meta property=\"og:description\" content=\"El Club N\u00e0utic l\u2019Escala ha hecho entrega, juntamente con Jotun y Colors Olympia Grup del tal\u00f3n solidario a la Fundaci\u00f3n Esclerosi M\u00faltiple (FEM).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-21T14:59:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/11\/2025-nauticescala-mullat-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"905\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/mullat-2025\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/mullat-2025\\\/\",\"name\":\"Aportaci\u00f3n de 2000 euros para la esclerosis m\u00faltiple &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/mullat-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/mullat-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/2025-nauticescala-mullat-8.jpg\",\"datePublished\":\"2025-11-21T14:17:52+00:00\",\"dateModified\":\"2025-11-21T14:59:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/mullat-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/mullat-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/mullat-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/2025-nauticescala-mullat-8.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/2025-nauticescala-mullat-8.jpg\",\"width\":1800,\"height\":905},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/noticias\\\/mullat-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aportaci\u00f3n de 2000 euros para la esclerosis m\u00faltiple\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aportaci\u00f3n de 2000 euros para la esclerosis m\u00faltiple &#8211; Club N\u00e0utic L\u2019Escala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/","og_locale":"es_ES","og_type":"article","og_title":"Aportaci\u00f3n de 2000 euros para la esclerosis m\u00faltiple","og_description":"El Club N\u00e0utic l\u2019Escala ha hecho entrega, juntamente con Jotun y Colors Olympia Grup del tal\u00f3n solidario a la Fundaci\u00f3n Esclerosi M\u00faltiple (FEM).","og_url":"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2025-11-21T14:59:16+00:00","og_image":[{"width":1800,"height":905,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/11\/2025-nauticescala-mullat-8.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/","url":"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/","name":"Aportaci\u00f3n de 2000 euros para la esclerosis m\u00faltiple &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/11\/2025-nauticescala-mullat-8.jpg","datePublished":"2025-11-21T14:17:52+00:00","dateModified":"2025-11-21T14:59:16+00:00","breadcrumb":{"@id":"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/11\/2025-nauticescala-mullat-8.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/11\/2025-nauticescala-mullat-8.jpg","width":1800,"height":905},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/es\/noticias\/mullat-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"Aportaci\u00f3n de 2000 euros para la esclerosis m\u00faltiple"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news\/93811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/93774"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=93811"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-categories?post=93811"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/news-tags?post=93811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}