 {"id":14309,"date":"2020-02-12T12:03:54","date_gmt":"2020-02-12T11:03:54","guid":{"rendered":"http:\/\/nauticescala.com\/activitat\/lloguer-de-vela-lleugera\/"},"modified":"2026-05-21T10:19:42","modified_gmt":"2026-05-21T08:19:42","slug":"alquiler-de-vela-ligera","status":"publish","type":"product","link":"https:\/\/nauticescala.com\/es\/compra-actividades-costa-brava\/alquiler-de-vela-ligera\/","title":{"rendered":"Alquiler de Vela Ligera"},"content":{"rendered":"\n    \n        <div class=\"btn-box\">\n            <a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/TARIFES-LLOGUERS-26.pdf\" target=\"_blank\" class=\"btn btn-primary\">Tarifas 2026<\/a>\n\n        \n        \n\n<\/div><!-- end btn-box -->\n\n   \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n                            <div class=\"accordion-block\">\n                    <div id=\"accordion\" class=\"accordion\">\n                                                                            <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-01\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Embarcaciones disponibles<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-01\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <ul>\n<li>Laser (m\u00e1ximo 1 persona)<\/li>\n<li>Optimist (m\u00e1ximo 1 persona)<\/li>\n<li>RS Quest (m\u00e1ximo 3 personas)<\/li>\n<li>RS Zest (m\u00e1ximo 2 personas)<\/li>\n<li>Hansa 303 (m\u00e1ximo 2 personas)<\/li>\n<li>Raquero (m\u00e1ximo 6 personas)<\/li>\n<li style=\"text-align: left;\">Catamar\u00e1n RS 16 (m\u00e1ximo 4 personas)<\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-02\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>El alquiler incluye<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-02\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                                                                    \n                                                                                                                                                                    \n                                                                                                                                                                                                                                                                <ul class=\"unordered-list two-cols-text\">\n                                                                                                                                                                                                                                    <li>Embarcaci\u00f3n<\/li>\n                                                                                                                                                                                                                                                                                                                <li>Chaleco salvavidas<\/li>\n                                                                                                                                                                                                                                                                                                                <li>Mapa zona de navegaci\u00f3n<\/li>\n                                                                                                                                                                                                                                                                                                                <li>Acceso a los vestuarios y taquillas del \u00c1rea Deportiva del Club<\/li>\n                                                                                                                                                                                                                        <\/ul><!-- end unordered-list -->\n                                                                                                                                                                                                                                                 \n                                                    \n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-03\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>El alquiler no incluye<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-03\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <ul>\n<li>Si no dispones de un seguro de responsabilidad civil y da\u00f1os a terceros, deber\u00e1s contratar uno. (1.5 \u20ac\/p)<\/li>\n<li>En caso de necesitar rescate, se cobrar\u00e1n 100 \u20ac que equivalen al importe de la fianza.<\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-04\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Qu\u00e9  traer?<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-04\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                                                                    \n                                                                                                                                                                    \n                                                                                                                                                                                                                                                                <ul class=\"unordered-list two-cols-text\">\n                                                                                                                                                                                                                                    <li>Cantimplora<\/li>\n                                                                                                                                                                                                                                                                                                                <li>Crema solar<\/li>\n                                                                                                                                                                                                                                                                                                                <li>Gorra<\/li>\n                                                                                                                                                                                                                                                                                                                <li>Ba\u00f1ador o ropa de agua<\/li>\n                                                                                                                                                                                                                                                                                                                <li>Calzado que pueda mojarse<\/li>\n                                                                                                                                                                                                                                                                                                                <li>Cortavientos (si es necesario)<\/li>\n                                                                                                                                                                                                                                                                                                                <li>Ropa de repuesto<\/li>\n                                                                                                                                                                                                                        <\/ul><!-- end unordered-list -->\n                                                                                                                                                                                                                                                 \n                                                    \n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-05\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Descuentos<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-05\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                                                                    \n                                                                                                                                                                        <div class=\"two-cols-text\">\n                                                                                                                \n                                                                                                                                                                                                                                                                <ul class=\"unordered-list\">\n                                                                                                                                                                                                                                    <li>15 % de descuento por socios y socias del Club<\/li>\n                                                                                                                                                                                                                                                                                                                <li>1 alquiler gratuito por cada 5 usos<\/li>\n                                                                                                                                                                                                                                                                                                                <li>Alquiler 1 hora &#8211; 33% de descuento<\/li>\n                                                                                                                                                                                                                        <\/ul><!-- end unordered-list -->\n                                                                                                                                                                                                                                                        <\/div><!-- end two-cols-text -->\n                                                                                                                     \n                                                    \n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                        <\/div><!-- end accordion -->\n                <\/div><!-- end accordion-block -->\n            \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\t<div class=\"slideshow-item\">\n\t    <div class=\"slideshow-offset\">\n\t        <div class=\"slides\">\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/2025-nauticescala-curs-vela-8-1-2000x1008.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/54743488584-dc78d3ecb9-o-2000x1008.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/2025-nauticescala-curs-vela-cursos-vela-45-2000x1008.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/2025-nauticescala-curs-vela-cursos-vela-21-2000x1008.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/2025-nauticescala-curs-vela-cursos-vela-16-2000x1008.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/03\/2022-nauticescala-curs-vela-144.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/12\/2022-club-nautic-lescala-vela-lleugera-abonats.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/02\/2023-nauticescala-35.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/04\/2022-nauticescala-abonats-7.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/2025-nauticescala-curs-vela-7-1-2000x1008.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/04\/2024-nauticescala-vela-adaptada.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/2025-nauticescala-curs-vela-6-1-2000x1008.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/2025-nauticescala-curs-vela-3-1-2000x1008.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/2025-nauticescala-curs-vela-1-2000x1008.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t\t            <div class=\"slide\">\n\t\t                <figure class=\"image\">\n\t\t                    <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/2025-nauticescala-curs-vela-cursos-vela-32-2000x1008.jpg\" alt=\"\">\n\t\t                <\/figure><!-- end image -->\n\t\t            <\/div><!-- end slide -->\t        \t\t\n\t        \t\t           \n\t        <\/div><!-- end slides -->\n\t    <\/div><!-- end slideshow-offset -->\n\t<\/div><!-- end slideshow-item -->\n","protected":false},"excerpt":{"rendered":"<p>Duraci\u00f3n: 2 h<br \/>Edad: a partir de 8 a\u00f1os<\/p>\n","protected":false},"featured_media":66842,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[793],"product_tag":[],"activity_type":[],"level":[],"age":[],"modality":[],"payment_method":[],"class_list":{"0":"post-14309","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sin-categorizar","8":"first","9":"instock","10":"virtual","11":"sold-individually","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Alquiler de Vela Ligera &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"Alquiler de embarcaci\u00f3n de Vela Ligera - Si tienes conocimientos en navegaci\u00f3, esta es la mejor opci\u00f3n para ti tus amigos o tu familia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/?p=3943&post_type=product&preview_id=3943\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alquiler de Vela Ligera\" \/>\n<meta property=\"og:description\" content=\"Alquiler de embarcaci\u00f3n de Vela Ligera - Si tienes conocimientos en navegaci\u00f3, esta es la mejor opci\u00f3n para ti tus amigos o tu familia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/?p=3943&amp;post_type=product&amp;preview_id=3943\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-21T08:19:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/03\/2023-nauticescala-curs-vela-280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/?p=3943&post_type=product&preview_id=3943\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/?p=3943&post_type=product&preview_id=3943\",\"name\":\"Alquiler de Vela Ligera &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/?p=3943&post_type=product&preview_id=3943#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/?p=3943&post_type=product&preview_id=3943#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2023-nauticescala-curs-vela-280.jpg\",\"datePublished\":\"2020-02-12T11:03:54+00:00\",\"dateModified\":\"2026-05-21T08:19:42+00:00\",\"description\":\"Alquiler de embarcaci\u00f3n de Vela Ligera - Si tienes conocimientos en navegaci\u00f3, esta es la mejor opci\u00f3n para ti tus amigos o tu familia.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/?p=3943&post_type=product&preview_id=3943#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/?p=3943&post_type=product&preview_id=3943\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/?p=3943&post_type=product&preview_id=3943#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2023-nauticescala-curs-vela-280.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/2023-nauticescala-curs-vela-280.jpg\",\"width\":1800,\"height\":907},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/?p=3943&post_type=product&preview_id=3943#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compra actividades en la Costa Brava\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/compra-actividades-en-la-costa-brava\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alquiler de Vela Ligera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Alquiler de Vela Ligera &#8211; Club N\u00e0utic L\u2019Escala","description":"Alquiler de embarcaci\u00f3n de Vela Ligera - Si tienes conocimientos en navegaci\u00f3, esta es la mejor opci\u00f3n para ti tus amigos o tu familia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/?p=3943&post_type=product&preview_id=3943","og_locale":"es_ES","og_type":"article","og_title":"Alquiler de Vela Ligera","og_description":"Alquiler de embarcaci\u00f3n de Vela Ligera - Si tienes conocimientos en navegaci\u00f3, esta es la mejor opci\u00f3n para ti tus amigos o tu familia.","og_url":"https:\/\/nauticescala.com\/?p=3943&post_type=product&preview_id=3943","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2026-05-21T08:19:42+00:00","og_image":[{"width":1800,"height":907,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/03\/2023-nauticescala-curs-vela-280.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/?p=3943&post_type=product&preview_id=3943","url":"https:\/\/nauticescala.com\/?p=3943&post_type=product&preview_id=3943","name":"Alquiler de Vela Ligera &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/?p=3943&post_type=product&preview_id=3943#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/?p=3943&post_type=product&preview_id=3943#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/03\/2023-nauticescala-curs-vela-280.jpg","datePublished":"2020-02-12T11:03:54+00:00","dateModified":"2026-05-21T08:19:42+00:00","description":"Alquiler de embarcaci\u00f3n de Vela Ligera - Si tienes conocimientos en navegaci\u00f3, esta es la mejor opci\u00f3n para ti tus amigos o tu familia.","breadcrumb":{"@id":"https:\/\/nauticescala.com\/?p=3943&post_type=product&preview_id=3943#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/?p=3943&post_type=product&preview_id=3943"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/?p=3943&post_type=product&preview_id=3943#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/03\/2023-nauticescala-curs-vela-280.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2024\/03\/2023-nauticescala-curs-vela-280.jpg","width":1800,"height":907},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/?p=3943&post_type=product&preview_id=3943#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Compra actividades en la Costa Brava","item":"https:\/\/nauticescala.com\/es\/compra-actividades-en-la-costa-brava\/"},{"@type":"ListItem","position":3,"name":"Alquiler de Vela Ligera"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/product\/14309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/66842"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=14309"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/product_brand?post=14309"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/product_cat?post=14309"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/product_tag?post=14309"},{"taxonomy":"activity_type","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/activity_type?post=14309"},{"taxonomy":"level","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/level?post=14309"},{"taxonomy":"age","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/age?post=14309"},{"taxonomy":"modality","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/modality?post=14309"},{"taxonomy":"payment_method","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/payment_method?post=14309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}