 {"id":46607,"date":"2022-10-18T14:56:14","date_gmt":"2022-10-18T12:56:14","guid":{"rendered":"https:\/\/nauticescala.com\/?p=46607&#038;post_type=product&#038;preview_id=46607"},"modified":"2023-06-20T11:03:04","modified_gmt":"2023-06-20T09:03:04","slug":"trobada-ruta-de-lanxova","status":"publish","type":"product","link":"https:\/\/nauticescala.com\/es\/compra-actividades-costa-brava\/trobada-ruta-de-lanxova\/","title":{"rendered":"2022-2023 Trobada Ruta de l&#8217;Anxova"},"content":{"rendered":"\n                            <div class=\"accordion-block\">\n                    <div id=\"accordion\" class=\"accordion\">\n                                                                            <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-01\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Regata en diferit<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-01\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><a href=\"https:\/\/www.estela.co\/es\/tracking-regata\/8486\/ruta-anxova-medes\" target=\"_blank\" rel=\"noopener\">Prova 8<\/a><\/li>\n<li><a href=\"https:\/\/estela.co\/es\/regata\/11298\/basto-lescala-2\" target=\"_blank\" rel=\"noopener\">Prova 7<\/a><\/li>\n<li><a href=\"https:\/\/estela.co\/es\/tracking-regata\/11114\/basto-lescala-2\" target=\"_blank\" rel=\"noopener\">Prova 6<\/a><\/li>\n<li><a href=\"https:\/\/www.estela.co\/es\/tracking-regata\/10989\/anxova-3\" target=\"_blank\" rel=\"noopener\">Prova 5<\/a><\/li>\n<li><a href=\"https:\/\/estela.co\/es\/tracking-regata\/10723\/anxova-2\" target=\"_blank\" rel=\"noopener\">Prova 4<\/a><\/li>\n<li><a href=\"https:\/\/www.estela.co\/es\/tracking-regata\/10817\/basto-lescala\" target=\"_blank\" rel=\"noopener\">Prova 3<\/a><\/li>\n<li><a href=\"https:\/\/estela.co\/es\/tracking-regata\/10721\/anxova-1\" target=\"_blank\" rel=\"noopener\">Prova 2<\/a><\/li>\n<li><a href=\"https:\/\/www.estela.co\/es\/tracking-regata\/10593\/ie-2022-escala-1\" target=\"_blank\" rel=\"noopener\">Prova 1<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-02\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>TOA<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-02\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <ul>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/GENERAL-REGATA-3.pdf\" target=\"_blank\" rel=\"noopener\">GENERAL REGATA (19-06-23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/GENERAL-MINIRALLY.pdf\" target=\"_blank\" rel=\"noopener\">GENERAL MINIRALLY (19-06-23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/Genaral-RALLY.pdf\" target=\"_blank\" rel=\"noopener\">GENERAL RALLY (19-06-23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/Prova-8-MINIRALLY-17-06-23.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 8 MINIRALLY (17-06-23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/Prova-8-RALLY-REGATA-17-06-23.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 8 RALLY I REGATA (17-06-23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/PROVA-7-RALLY-I-REGATA-14-04-23.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 7 RALLY I REGATA (14-04-23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/PROVA-7-MINIRALLY-14-04-23.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 7 MINIRALLY (14-04-23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/03\/PROVA-6-RALLY-I-REGATA-11.3.23.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 6 RALLY I REGATA (11.3.23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/03\/PROVA-6MINI-RALLY-11.3.23.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 6 MINI RALLY (11.3.23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/02\/PROVA-5-RALLY-I-REGATA-11.2.23.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 5 RALLY I REGATA (11.2.23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/02\/PROVA-5-MINI-RALLY-11.2.23.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 5 MINI RALLY (11.2.23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/01\/PROVA-4-RALLY-I-REGATA-14.1.23.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 4 RALLY I REGATA (14.1.23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2023\/01\/PROVA-4-MINI-RALLY-14.1.23.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 4 MINI RALLY (14.1.23)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/PROVA-3-10-12-22.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 3 (10-12-22)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/PROVA-2-12-11-22.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 2 (12-11-22)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/PROVA-1-CREUERS-1-1.pdf\" target=\"_blank\" rel=\"noopener\">Prova 1 (8-10-22)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/INSCRITS.pdf\" target=\"_blank\" rel=\"noopener\">Llistat d&#8217;inscrits<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/11\/TEMPS-LIMIT.pdf\" target=\"_blank\" rel=\"noopener\">Llistat de temps l\u00edmit<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/10\/ANUNCI-DE-REGATA.pdf\" target=\"_blank\" rel=\"noopener\">Anunci de Regata<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/11\/RECORREGUT.pdf\" target=\"_blank\" rel=\"noopener\">Recorreguts<\/a><\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-03\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Hist\u00f2ric<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-03\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <ul>\n<li><a href=\"https:\/\/nauticescala.com\/activitats-costa-brava\/ruta-anxova-2021-22\/\">Edici\u00f3 2021-22<\/a><\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-04\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Consulta el calendari<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-04\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                                                                                                                                                                                <ul class=\"schedule-list\">\n                                                                                                                            <li>\n                                                                    <div class=\"cell\">\n                                                                                                                                                    <div class=\"date-box\">\n                                                                                                                                                                    <b>8 d&#8217;octubre<\/b>\n                                                                                                                                                                                                                                                    <span>2022<\/span>\n                                                                                                                                                            <\/div><!-- end date-box -->                                                                            \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                                   <p>Trobada de Velers<\/p> \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"btn-box\">\n                                                                                                                                                   <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUMTZNS0tLRVJNWVVRN1dTM1gwVEdBVkVDUyQlQCN0PWcu\" class=\"btn btn-primary has-shadow\">Reservar<\/a> \n                                                                                                                                            <\/div><!-- end btn-box -->\n                                                                <\/li>\n                                                                                                                            <li>\n                                                                    <div class=\"cell\">\n                                                                                                                                                    <div class=\"date-box\">\n                                                                                                                                                                    <b>12 de novembre<\/b>\n                                                                                                                                                                                                                                                    <span>2022<\/span>\n                                                                                                                                                            <\/div><!-- end date-box -->                                                                            \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                                   <p>Trobada de Velers<\/p> \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"btn-box\">\n                                                                                                                                                   <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUMTZNS0tLRVJNWVVRN1dTM1gwVEdBVkVDUyQlQCN0PWcu\" class=\"btn btn-primary has-shadow\">Reservar<\/a> \n                                                                                                                                            <\/div><!-- end btn-box -->\n                                                                <\/li>\n                                                                                                                            <li>\n                                                                    <div class=\"cell\">\n                                                                                                                                                    <div class=\"date-box\">\n                                                                                                                                                                    <b>10 de desembre<\/b>\n                                                                                                                                                                                                                                                    <span>2022<\/span>\n                                                                                                                                                            <\/div><!-- end date-box -->                                                                            \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                                   <p>Trobada de Velers<\/p> \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"btn-box\">\n                                                                                                                                                   <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUMTZNS0tLRVJNWVVRN1dTM1gwVEdBVkVDUyQlQCN0PWcu\" class=\"btn btn-primary has-shadow\">Reservar<\/a> \n                                                                                                                                            <\/div><!-- end btn-box -->\n                                                                <\/li>\n                                                                                                                            <li>\n                                                                    <div class=\"cell\">\n                                                                                                                                                    <div class=\"date-box\">\n                                                                                                                                                                    <b>14 de gener<\/b>\n                                                                                                                                                                                                                                                    <span>2023<\/span>\n                                                                                                                                                            <\/div><!-- end date-box -->                                                                            \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                                   <p>Trobada de Velers<\/p> \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"btn-box\">\n                                                                                                                                                   <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUMTZNS0tLRVJNWVVRN1dTM1gwVEdBVkVDUyQlQCN0PWcu\" class=\"btn btn-primary has-shadow\">Reservar<\/a> \n                                                                                                                                            <\/div><!-- end btn-box -->\n                                                                <\/li>\n                                                                                                                            <li>\n                                                                    <div class=\"cell\">\n                                                                                                                                                    <div class=\"date-box\">\n                                                                                                                                                                    <b>11 de febrer<\/b>\n                                                                                                                                                                                                                                                    <span>2023<\/span>\n                                                                                                                                                            <\/div><!-- end date-box -->                                                                            \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                                   <p>Trobada de Velers<\/p> \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"btn-box\">\n                                                                                                                                                   <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUMTZNS0tLRVJNWVVRN1dTM1gwVEdBVkVDUyQlQCN0PWcu\" class=\"btn btn-primary has-shadow\">Reservar<\/a> \n                                                                                                                                            <\/div><!-- end btn-box -->\n                                                                <\/li>\n                                                                                                                            <li>\n                                                                    <div class=\"cell\">\n                                                                                                                                                    <div class=\"date-box\">\n                                                                                                                                                                    <b>11 de mar\u00e7<\/b>\n                                                                                                                                                                                                                                                    <span>2023<\/span>\n                                                                                                                                                            <\/div><!-- end date-box -->                                                                            \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                                   <p>Trobada de Velers<\/p> \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"btn-box\">\n                                                                                                                                                   <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUMTZNS0tLRVJNWVVRN1dTM1gwVEdBVkVDUyQlQCN0PWcu\" class=\"btn btn-primary has-shadow\">Reservar<\/a> \n                                                                                                                                            <\/div><!-- end btn-box -->\n                                                                <\/li>\n                                                                                                                            <li>\n                                                                    <div class=\"cell\">\n                                                                                                                                                    <div class=\"date-box\">\n                                                                                                                                                                    <b>15 d&#8217;abril<\/b>\n                                                                                                                                                                                                                                                    <span>2023<\/span>\n                                                                                                                                                            <\/div><!-- end date-box -->                                                                            \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                                   <p>Trobada de Velers<\/p> \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"btn-box\">\n                                                                                                                                                   <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUMTZNS0tLRVJNWVVRN1dTM1gwVEdBVkVDUyQlQCN0PWcu\" class=\"btn btn-primary has-shadow\">Reservar<\/a> \n                                                                                                                                            <\/div><!-- end btn-box -->\n                                                                <\/li>\n                                                                                                                            <li>\n                                                                    <div class=\"cell\">\n                                                                                                                                                    <div class=\"date-box\">\n                                                                                                                                                                    <b>20 de maig<\/b>\n                                                                                                                                                                                                                                                    <span>2023<\/span>\n                                                                                                                                                            <\/div><!-- end date-box -->                                                                            \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                                   <p>Trobada de Velers<\/p> \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"btn-box\">\n                                                                                                                                                   <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUMTZNS0tLRVJNWVVRN1dTM1gwVEdBVkVDUyQlQCN0PWcu\" class=\"btn btn-primary has-shadow\">Reservar<\/a> \n                                                                                                                                            <\/div><!-- end btn-box -->\n                                                                <\/li>\n                                                                                                                            <li>\n                                                                    <div class=\"cell\">\n                                                                                                                                                    <div class=\"date-box\">\n                                                                                                                                                                    <b>17 de juny<\/b>\n                                                                                                                                                                                                                                                    <span>2023<\/span>\n                                                                                                                                                            <\/div><!-- end date-box -->                                                                            \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                                   <p>Trobada de Velers<\/p> \n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"cell\">\n                                                                                                                                            <\/div><!-- end cell -->\n                                                                    <div class=\"btn-box\">\n                                                                                                                                                   <a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUMTZNS0tLRVJNWVVRN1dTM1gwVEdBVkVDUyQlQCN0PWcu\" class=\"btn btn-primary has-shadow\">Reservar<\/a> \n                                                                                                                                            <\/div><!-- end btn-box -->\n                                                                <\/li>\n                                                                                                                       \n                                                        <\/ul><!-- end schedule-list -->                                                        \n                                                                                                    \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                        <\/div><!-- end accordion -->\n                <\/div><!-- end accordion-block -->\n            \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n    \n        <div class=\"btn-box\">\n            <a href=\"https:\/\/www.flickr.com\/photos\/nauticescala\/albums\/72157703243843302\" target=\"_blank\" class=\"btn btn-primary\">Fotografies<\/a>\n\n        \n        \n\n<\/div><!-- end btn-box -->\n\n   \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\t<div class=\"container\">\n\n<div class=\"content-block\">\n \t \t\n \t \t   \n \t\t    <div class=\"partners-block\">\t    \t\n\t    \t\t    \t\t<h3>Col\u00b7labora:<\/h3>\n\t    \t  \n\t    \t   \n\t    \t\t\t        <ul class=\"partners-list\">\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/www.vela.cat\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/08\/logo-fcv-350x215.png\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t            \n\t\t        <\/ul><!-- end partners-list -->\t    \t\t\n\t    \t\t    <\/div><!-- end partners-block --> \t   \t\n \t   \n<\/div><!-- end content-block -->\n\n\t<\/div>\n\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":25657,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[99],"product_tag":[],"activity_type":[],"level":[],"age":[],"modality":[],"payment_method":[],"class_list":{"0":"post-46607","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sense-categoria","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>2022-2023 Trobada Ruta de l&#039;Anxova &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2022-2023 Trobada Ruta de l&#039;Anxova\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-20T09:03:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/2021-club-nautic-lescala-creuer-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"605\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/trobada-ruta-de-lanxova\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/trobada-ruta-de-lanxova\\\/\",\"name\":\"2022-2023 Trobada Ruta de l'Anxova &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/trobada-ruta-de-lanxova\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/trobada-ruta-de-lanxova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2021-club-nautic-lescala-creuer-6.jpg\",\"datePublished\":\"2022-10-18T12:56:14+00:00\",\"dateModified\":\"2023-06-20T09:03:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/trobada-ruta-de-lanxova\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/trobada-ruta-de-lanxova\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/trobada-ruta-de-lanxova\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2021-club-nautic-lescala-creuer-6.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2021-club-nautic-lescala-creuer-6.jpg\",\"width\":1200,\"height\":605},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/trobada-ruta-de-lanxova\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Compra actividades en la Costa Brava\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/es\\\/compra-actividades-en-la-costa-brava\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2022-2023 Trobada Ruta de l&#8217;Anxova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"2022-2023 Trobada Ruta de l'Anxova &#8211; Club N\u00e0utic L\u2019Escala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/","og_locale":"es_ES","og_type":"article","og_title":"2022-2023 Trobada Ruta de l'Anxova","og_url":"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2023-06-20T09:03:04+00:00","og_image":[{"width":1200,"height":605,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/2021-club-nautic-lescala-creuer-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/","url":"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/","name":"2022-2023 Trobada Ruta de l'Anxova &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/2021-club-nautic-lescala-creuer-6.jpg","datePublished":"2022-10-18T12:56:14+00:00","dateModified":"2023-06-20T09:03:04+00:00","breadcrumb":{"@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/2021-club-nautic-lescala-creuer-6.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/2021-club-nautic-lescala-creuer-6.jpg","width":1200,"height":605},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-ruta-de-lanxova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/es\/"},{"@type":"ListItem","position":2,"name":"Compra actividades en la Costa Brava","item":"https:\/\/nauticescala.com\/es\/compra-actividades-en-la-costa-brava\/"},{"@type":"ListItem","position":3,"name":"2022-2023 Trobada Ruta de l&#8217;Anxova"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/product\/46607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media\/25657"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/media?parent=46607"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/product_brand?post=46607"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/product_cat?post=46607"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/product_tag?post=46607"},{"taxonomy":"activity_type","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/activity_type?post=46607"},{"taxonomy":"level","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/level?post=46607"},{"taxonomy":"age","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/age?post=46607"},{"taxonomy":"modality","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/modality?post=46607"},{"taxonomy":"payment_method","embeddable":true,"href":"https:\/\/nauticescala.com\/es\/wp-json\/wp\/v2\/payment_method?post=46607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}