 {"id":93109,"date":"2025-10-16T11:25:16","date_gmt":"2025-10-16T09:25:16","guid":{"rendered":"https:\/\/nauticescala.com\/?post_type=news&#038;p=93109"},"modified":"2025-10-18T12:34:17","modified_gmt":"2025-10-18T10:34:17","slug":"le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/","title":{"rendered":"Le Club N\u00e0utic l\u2019Escala et l\u2019ABS l\u2019Escala lancent la \u201cSant\u00e9 bleue\u201d avec trois nouvelles activit\u00e9s th\u00e9rapeutiques"},"content":{"rendered":"\n<p><em>L\u2019utilisation de la mer s\u2019affirme comme un outil de sant\u00e9 communautaire, \u00e9largissant les b\u00e9n\u00e9fices physiques et \u00e9motionnels pour les patients souffrant d\u2019anxi\u00e9t\u00e9, de handicap temporaire et de cancer.<\/em> <em>Parmi les actions, le Dragon Boat se distingue, destin\u00e9 aux personnes ayant surmont\u00e9 tout type de cancer.<\/em><\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Le Club N\u00e0utic l\u2019Escala et l\u2019Unit\u00e9 de Sant\u00e9 de Base (ABS) de l\u2019Escala lancent trois nouvelles activit\u00e9s nautiques th\u00e9rapeutiques visant \u00e0 am\u00e9liorer le bien-\u00eatre physique et \u00e9motionnel des patients. Ainsi, l\u2019utilisation de la mer et des activit\u00e9s maritimes s\u2019affirme comme un outil th\u00e9rapeutique et s\u2019int\u00e8gre aux propositions de sant\u00e9 communautaire offertes par l\u2019ABS pour la r\u00e9cup\u00e9ration physique et \u00e9motionnelle des patients, appel\u00e9e \u201cSant\u00e9 bleue\u201d.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Ce projet a d\u00e9but\u00e9 par un projet pilote pionnier men\u00e9 en juin et juillet, avec le soutien de l\u2019Universit\u00e9 de Barcelone et de Dipsalut, o\u00f9 des patients souffrant de troubles anxieux de l\u2019ABS l\u2019Escala ont particip\u00e9 \u00e0 des s\u00e9ances de voile l\u00e9g\u00e8re au Club N\u00e0utic l\u2019Escala pour am\u00e9liorer leur bien-\u00eatre \u00e9motionnel.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-4.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><br><strong>Trois nouvelles activit\u00e9s<\/strong><\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Ce mois d\u2019octobre, l\u2019activit\u00e9 de voile l\u00e9g\u00e8re reprendra et les propositions li\u00e9es \u00e0 la mer seront \u00e9largies pour s\u2019adresser \u00e0 de nouveaux groupes de patients.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Une nouvelle activit\u00e9 sera lanc\u00e9e : la navigation avec des embarcations adapt\u00e9es pour les personnes ayant un handicap temporaire. L\u2019objectif est d\u2019acc\u00e9l\u00e9rer leur r\u00e9cup\u00e9ration et d\u2019am\u00e9liorer leur condition physique gr\u00e2ce \u00e0 l\u2019activit\u00e9 maritime.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>La troisi\u00e8me proposition est le Dragon Boat, qui, gr\u00e2ce au soutien financier de la Fondation \u201cla Caixa\u201d, pourra \u00eatre propos\u00e9 gratuitement pour la saison 2025-2026. Il s\u2019agit d\u2019une modalit\u00e9 de cano\u00eb provenant d\u2019anciennes traditions chinoises, avec la figure du dragon comme symbole principal. Elle est accessible \u00e0 tous, facile \u00e0 apprendre, ne n\u00e9cessite pas d\u2019exp\u00e9rience pr\u00e9alable et permet aux pagayeurs de pratiquer une activit\u00e9 physique en plein air, renfor\u00e7ant l\u2019esprit d\u2019\u00e9quipe et l\u2019objectif commun.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Cette activit\u00e9 s\u2019adresse aux personnes ayant surmont\u00e9 tout type de cancer, cherchant \u00e0 am\u00e9liorer leur qualit\u00e9 de vie et \u00e0 agir sur des aspects \u00e9motionnels et sociaux tels que le travail en groupe et l\u2019estime de soi.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>En plus du financement de la Fondation \u201cla Caixa\u201d, le Dragon Boat est rendu possible gr\u00e2ce \u00e0 la collaboration de la Mairie de l\u2019Escala et de Dipsalut, l\u2019implication de la Fondation Salut Empord\u00e0 et l\u2019apport logistique et technique du Club N\u00e0utic l\u2019Escala.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-3.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><br><strong>Activit\u00e9s de sant\u00e9 communautaire<\/strong><\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Ces trois actions de \u201cSant\u00e9 bleue\u201d s\u2019inscrivent dans la large offre d\u2019activit\u00e9s de sant\u00e9 communautaire que l\u2019ABS l\u2019Escala reprend ce mois d\u2019octobre apr\u00e8s la pause estivale. L\u2019ABS propose une trentaine d\u2019activit\u00e9s gr\u00e2ce \u00e0 la collaboration d\u2019entit\u00e9s locales telles que le Club Tennis Taula CER l\u2019Escala, le Club N\u00e0utic l\u2019Escala et le Club Rem l\u2019Escala.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Ces activit\u00e9s incluent des propositions consolid\u00e9es et des nouveaut\u00e9s : du tennis de table ou du football pour les personnes de plus de 60 ans, des s\u00e9ances pour les aidants, pour les douleurs chroniques ou la fragilit\u00e9, des groupes de sevrage tabagique, de m\u00e9nopause ou de changement d\u2019habitudes alimentaires, ainsi que du mindfulness, de la danse-th\u00e9rapie et du Qi Gong.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\t<div class=\"container\">\n\n<div class=\"content-block\">\n \t \t\n \t \t   \n \t\t    <div class=\"partners-block\">\t    \t\n\t    \t\t    \t\t<h3>Projet financ\u00e9 par :<\/h3>\n\t    \t  \n\t    \t   \n\t    \t\t\t        <ul class=\"partners-list\">\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-2-350x51.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/logo-dipsalut-jpg-350x162.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/fundacio-salut-emporda.png\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/01\/ajuntament-escala-1.webp\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t            \n\t\t        <\/ul><!-- end partners-list -->\t    \t\t\n\t    \t\t    <\/div><!-- end partners-block --> \t   \t\n \t   \n<\/div><!-- end content-block -->\n\n\t<\/div>\n\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n","protected":false},"excerpt":{"rendered":"<p>Un projet pilote \u00e0 L\u2019Escala analyse les bienfaits de la navigation sur le bien-\u00eatre \u00e9motionnel. D\u00e9couvrez le projet Salut Blava.<\/p>\n","protected":false},"featured_media":93244,"parent":0,"template":"","news-categories":[1073],"news-tags":[],"class_list":["post-93109","news","type-news","status-publish","has-post-thumbnail","hentry","news-categories-esport-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Salut Blava: la mer th\u00e9rapie \u00e9motionnelle Club N\u00e0utic l\u2019Escala<\/title>\n<meta name=\"description\" content=\"Un projet pilote \u00e0 L\u2019Escala analyse les bienfaits de la navigation sur le bien-\u00eatre \u00e9motionnel. D\u00e9couvrez le projet Salut Blava.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Club N\u00e0utic l\u2019Escala et l\u2019ABS l\u2019Escala lancent la \u201cSant\u00e9 bleue\u201d avec trois nouvelles activit\u00e9s th\u00e9rapeutiques\" \/>\n<meta property=\"og:description\" content=\"Un projet pilote \u00e0 L\u2019Escala analyse les bienfaits de la navigation sur le bien-\u00eatre \u00e9motionnel. D\u00e9couvrez le projet Salut Blava.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-18T10:34:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"905\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\\\/\",\"name\":\"Salut Blava: la mer th\u00e9rapie \u00e9motionnelle Club N\u00e0utic l\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/2025-nauticescala-rem-salut-blava-2.jpg\",\"datePublished\":\"2025-10-16T09:25:16+00:00\",\"dateModified\":\"2025-10-18T10:34:17+00:00\",\"description\":\"Un projet pilote \u00e0 L\u2019Escala analyse les bienfaits de la navigation sur le bien-\u00eatre \u00e9motionnel. D\u00e9couvrez le projet Salut Blava.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/2025-nauticescala-rem-salut-blava-2.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/2025-nauticescala-rem-salut-blava-2.jpg\",\"width\":1800,\"height\":905},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le Club N\u00e0utic l\u2019Escala et l\u2019ABS l\u2019Escala lancent la \u201cSant\u00e9 bleue\u201d avec trois nouvelles activit\u00e9s th\u00e9rapeutiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Salut Blava: la mer th\u00e9rapie \u00e9motionnelle Club N\u00e0utic l\u2019Escala","description":"Un projet pilote \u00e0 L\u2019Escala analyse les bienfaits de la navigation sur le bien-\u00eatre \u00e9motionnel. D\u00e9couvrez le projet Salut Blava.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Le Club N\u00e0utic l\u2019Escala et l\u2019ABS l\u2019Escala lancent la \u201cSant\u00e9 bleue\u201d avec trois nouvelles activit\u00e9s th\u00e9rapeutiques","og_description":"Un projet pilote \u00e0 L\u2019Escala analyse les bienfaits de la navigation sur le bien-\u00eatre \u00e9motionnel. D\u00e9couvrez le projet Salut Blava.","og_url":"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2025-10-18T10:34:17+00:00","og_image":[{"width":1800,"height":905,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/","url":"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/","name":"Salut Blava: la mer th\u00e9rapie \u00e9motionnelle Club N\u00e0utic l\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-2.jpg","datePublished":"2025-10-16T09:25:16+00:00","dateModified":"2025-10-18T10:34:17+00:00","description":"Un projet pilote \u00e0 L\u2019Escala analyse les bienfaits de la navigation sur le bien-\u00eatre \u00e9motionnel. D\u00e9couvrez le projet Salut Blava.","breadcrumb":{"@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-2.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/10\/2025-nauticescala-rem-salut-blava-2.jpg","width":1800,"height":905},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/le-club-nautic-lescala-et-labs-lescala-lancent-la-sante-bleue-avec-trois-nouvelles-activites-therapeutiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"Le Club N\u00e0utic l\u2019Escala et l\u2019ABS l\u2019Escala lancent la \u201cSant\u00e9 bleue\u201d avec trois nouvelles activit\u00e9s th\u00e9rapeutiques"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/news\/93109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/media\/93244"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/media?parent=93109"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/news-categories?post=93109"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/news-tags?post=93109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}