 {"id":99643,"date":"2026-05-02T16:19:50","date_gmt":"2026-05-02T14:19:50","guid":{"rendered":"https:\/\/nauticescala.com\/?post_type=news&#038;p=99643"},"modified":"2026-05-02T16:34:37","modified_gmt":"2026-05-02T14:34:37","slug":"rencontre-voile-latine-centenaire-sa-rata","status":"publish","type":"news","link":"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/","title":{"rendered":"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal \u00ab Sa Rata \u00bb"},"content":{"rendered":"\n<p>Le Club N\u00e0utic de L\u2019Escala a organis\u00e9 le samedi 2 mai 2026 la Rencontre de Voile Latine \u2013 100e anniversaire du sardinal \u00ab Sa Rata \u00bb, une journ\u00e9e tr\u00e8s sp\u00e9ciale d\u00e9di\u00e9e \u00e0 la pr\u00e9servation et \u00e0 la c\u00e9l\u00e9bration du patrimoine maritime m\u00e9diterran\u00e9en.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>La rencontre a r\u00e9uni 19 embarcations \u00e0 voile latine venues de Catalogne, des \u00eeles Bal\u00e9ares et de la Catalogne Nord, avec la participation de pr\u00e8s de 150 personnes, parmi lesquelles navigateurs, \u00e9quipages, familles et passionn\u00e9s de la mer, qui ont occup\u00e9 le littoral de L\u2019Escala tout au long de la matin\u00e9e.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>L\u2019\u00e9v\u00e9nement s\u2019est tenu \u00e0 l\u2019occasion du centenaire du sardinal \u00ab Sa Rata \u00bb, une embarcation en bois construite en 1926 \u00e0 Banyuls de la Marenda (Catalogne Nord) par le ma\u00eetre charpentier de marine Colomina, et restaur\u00e9e en 1989 aux chantiers navals Sala de L\u2019Escala par le ma\u00eetre charpentier Salvador Feliu.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Tout au long de la journ\u00e9e, le legs de cette embarcation centenaire a \u00e9t\u00e9 mis en valeur. Comme le rappelle son armateur, Emili Armengol, elle navigue depuis \u00ab 100 ans, et toujours en navigation \u00bb.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/05\/2026-nauticescala-vela-llatina-35.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Durant la rencontre, les voiles latines ont dessin\u00e9 une image \u00e9vocatrice et hautement symbolique le long du littoral de L\u2019Escala, offrant une occasion unique de se connecter \u00e0 l\u2019histoire maritime, de partager des savoirs entre g\u00e9n\u00e9rations et de profiter de la navigation traditionnelle en communaut\u00e9.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>La voile latine, au-del\u00e0 d\u2019une technique de navigation, est une expression vivante de la culture m\u00e9diterran\u00e9enne et un t\u00e9moignage de la relation historique entre les communaut\u00e9s c\u00f4ti\u00e8res et la mer.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Par cette initiative, le Club N\u00e0utic de L\u2019Escala a r\u00e9affirm\u00e9 son engagement en faveur de la pr\u00e9servation, de la promotion et de la transmission de ce patrimoine maritime, consid\u00e9r\u00e9 comme un actif culturel de premier ordre.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/05\/2026-nauticescala-vela-llatina-43.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><strong>Institutions et entit\u00e9s partenaires<\/strong><\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>La Rencontre de Voile Latine a \u00e9t\u00e9 rendue possible gr\u00e2ce \u00e0 la collaboration et au soutien de diverses institutions et entit\u00e9s engag\u00e9es dans le patrimoine maritime et culturel :<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<ul class=\"wp-block-list\">\n<li>Mairie de L\u2019Escala<\/li>\n\n\n\n<li>Association des Amis de la Voile Latine de L\u2019Escala<\/li>\n\n\n\n<li>Ports de la Generalitat<\/li>\n\n\n\n<li>Mus\u00e9e de l\u2019Anchois et du Sel<\/li>\n\n\n\n<li>F\u00e9d\u00e9ration Catalane pour la Culture et le Patrimoine Maritime et Fluvial<\/li>\n<\/ul>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Le soutien de ces institutions a renforc\u00e9 la volont\u00e9 commune de donner de la visibilit\u00e9 \u00e0 la voile latine, d\u2019en encourager la pratique et de garantir la continuit\u00e9 de cet h\u00e9ritage pour les g\u00e9n\u00e9rations futures.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>Avec cette rencontre comm\u00e9morative, le Club N\u00e0utic de L\u2019Escala a consolid\u00e9 L\u2019Escala comme espace de r\u00e9f\u00e9rence pour la culture maritime traditionnelle et invite l\u2019ensemble de la population \u00e0 vivre une exp\u00e9rience authentique, empreinte de tradition, d\u2019\u00e9motion et de respect pour notre patrimoine maritime.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p>With this commemorative gathering, Club N\u00e0utic L\u2019Escala has consolidated L\u2019Escala as a reference space for traditional maritime culture, and invites the public to experience an authentic event, full of tradition, emotion and respect for our maritime heritage.<\/p>\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n    \n        <div class=\"btn-box\">\n            <a href=\"https:\/\/nauticescala.com\/activitats-costa-brava\/trobada-de-vela-llatina-lescala-2025\/\" target=\"_self\" class=\"btn btn-primary\">M\u00e9s info<\/a>\n\n        \n        \n        \n            <a href=\"https:\/\/www.flickr.com\/photos\/nauticescala\/with\/55244250854\" target=\"_self\" class=\"btn btn-primary\">Fotos<\/a>\n    \n\n        \n\n<\/div><!-- end btn-box -->\n\n   \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\t<div class=\"container\">\n\n<div class=\"content-block\">\n \t\t    <div class=\"ad-banner-box\">\n\t    \t\t    \t\t        \t        \t    <\/div><!-- end ad-banner-box --> \t\t\n \t \t\n \t \t   \n \t\t    <div class=\"partners-block\">\t    \t\n\t    \t\t    \t\t<h3>Organitzaci\u00f3:<\/h3>\n\t    \t  \n\t    \t   \n\t    \t\t\t        <ul class=\"partners-list\">\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/nauticescala.com\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/01\/logo-1-tinta-web-100.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/01\/ajuntament-escala-1.webp\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/08\/anagrama-avll-350x342.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/04\/logo-ports.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2025\/08\/museu-de-la-sal.jpeg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/05\/logo-federacio-transparent-350x215.png\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t            \n\t\t        <\/ul><!-- end partners-list -->\t    \t\t\n\t    \t\t    <\/div><!-- end partners-block --> \t   \t\n \t   \n<\/div><!-- end content-block -->\n\n\t<\/div>\n\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>    <figure class=\"image-banner\">\t\n\t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/05\/2026-nauticescala-vela-llatina-20.jpg\" alt=\"\" \/>\n\t<\/figure><!-- end image-banner -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal Sa Rata lors d\u2019une rencontre de voile latine d\u00e9di\u00e9e au patrimoine maritime m\u00e9diterran\u00e9en.<\/p>\n","protected":false},"featured_media":99657,"parent":0,"template":"","news-categories":[],"news-tags":[],"class_list":["post-99643","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal \u00ab Sa Rata \u00bb &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal Sa Rata lors d\u2019une rencontre de voile latine d\u00e9di\u00e9e au patrimoine maritime m\u00e9diterran\u00e9en.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal \u00ab Sa Rata \u00bb\" \/>\n<meta property=\"og:description\" content=\"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal Sa Rata lors d\u2019une rencontre de voile latine d\u00e9di\u00e9e au patrimoine maritime m\u00e9diterran\u00e9en.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T14:34:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/05\/2026-nauticescala-vela-llatina-22-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"907\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/rencontre-voile-latine-centenaire-sa-rata\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/rencontre-voile-latine-centenaire-sa-rata\\\/\",\"name\":\"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal \u00ab Sa Rata \u00bb &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/rencontre-voile-latine-centenaire-sa-rata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/rencontre-voile-latine-centenaire-sa-rata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/2026-nauticescala-vela-llatina-22-1.jpg\",\"datePublished\":\"2026-05-02T14:19:50+00:00\",\"dateModified\":\"2026-05-02T14:34:37+00:00\",\"description\":\"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal Sa Rata lors d\u2019une rencontre de voile latine d\u00e9di\u00e9e au patrimoine maritime m\u00e9diterran\u00e9en.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/rencontre-voile-latine-centenaire-sa-rata\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/rencontre-voile-latine-centenaire-sa-rata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/rencontre-voile-latine-centenaire-sa-rata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/2026-nauticescala-vela-llatina-22-1.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/2026-nauticescala-vela-llatina-22-1.jpg\",\"width\":1800,\"height\":907},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/nouvelles\\\/rencontre-voile-latine-centenaire-sa-rata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Not\u00edcies\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/noticies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal \u00ab Sa Rata \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal \u00ab Sa Rata \u00bb &#8211; Club N\u00e0utic L\u2019Escala","description":"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal Sa Rata lors d\u2019une rencontre de voile latine d\u00e9di\u00e9e au patrimoine maritime m\u00e9diterran\u00e9en.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal \u00ab Sa Rata \u00bb","og_description":"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal Sa Rata lors d\u2019une rencontre de voile latine d\u00e9di\u00e9e au patrimoine maritime m\u00e9diterran\u00e9en.","og_url":"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2026-05-02T14:34:37+00:00","og_image":[{"width":1800,"height":907,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/05\/2026-nauticescala-vela-llatina-22-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/","url":"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/","name":"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal \u00ab Sa Rata \u00bb &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/05\/2026-nauticescala-vela-llatina-22-1.jpg","datePublished":"2026-05-02T14:19:50+00:00","dateModified":"2026-05-02T14:34:37+00:00","description":"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal Sa Rata lors d\u2019une rencontre de voile latine d\u00e9di\u00e9e au patrimoine maritime m\u00e9diterran\u00e9en.","breadcrumb":{"@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/05\/2026-nauticescala-vela-llatina-22-1.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2026\/05\/2026-nauticescala-vela-llatina-22-1.jpg","width":1800,"height":907},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/fr\/nouvelles\/rencontre-voile-latine-centenaire-sa-rata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Not\u00edcies","item":"https:\/\/nauticescala.com\/noticies\/"},{"@type":"ListItem","position":3,"name":"L\u2019Escala a c\u00e9l\u00e9br\u00e9 le centenaire du sardinal \u00ab Sa Rata \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/news\/99643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/media\/99657"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/media?parent=99643"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/news-categories?post=99643"},{"taxonomy":"news-tags","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/news-tags?post=99643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}