 {"id":23234,"date":"2021-01-20T16:34:09","date_gmt":"2021-01-20T15:34:09","guid":{"rendered":"http:\/\/nauticescala.com\/?p=23234&#038;post_type=product&#038;preview_id=23234"},"modified":"2025-03-05T11:58:24","modified_gmt":"2025-03-05T10:58:24","slug":"regata-comodor-2021","status":"publish","type":"product","link":"https:\/\/nauticescala.com\/fr\/reservez-votre-activites-costa-brava\/regata-comodor-2021\/","title":{"rendered":"XI Copa Comodor &#8211; Gran Premi Jotun"},"content":{"rendered":"\n                            <div class=\"accordion-block\">\n                    <div id=\"accordion\" class=\"accordion\">\n                                                                            <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-01\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>T.O.A.<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-01\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <ul>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/Llistat-de-guardonats.pdf\" target=\"_blank\" rel=\"noopener\">Llistat de guardonats<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/AVIS-4.pdf\" target=\"_blank\" rel=\"noopener\">AV\u00cdS 4<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/AVIS-3.pdf\" target=\"_blank\" rel=\"noopener\">AV\u00cdS 3<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/Classifiacio-Rally.pdf\" target=\"_blank\" rel=\"noopener\">Classifiaci\u00f3 Rally<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/Classifiacio-RI.pdf\" target=\"_blank\" rel=\"noopener\">Classifiaci\u00f3 RI<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/Llistat-arribades-Rally.pdf\" target=\"_blank\" rel=\"noopener\">Llistat arribades &#8211; Rally<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/Llistat-arribades-RI.pdf\" target=\"_blank\" rel=\"noopener\">Llistat arribades &#8211; RI<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/AVIS-2-2.pdf\" target=\"_blank\" rel=\"noopener\">AV\u00cdS 2: Modificaci\u00f3 Recorregut<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/Llistat-inscrits-ORC.pdf\" target=\"_blank\" rel=\"noopener\">Llistat inscrits ORC<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/Llistat-inscrits-RI.pdf\" target=\"_blank\" rel=\"noopener\">Llistat inscrits RI<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/Llistat-temps-limit-per-milla.pdf\" target=\"_blank\" rel=\"noopener\">Llistat temps l\u00edmit per milla<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/AVIS-1-2.pdf\" target=\"_blank\" rel=\"noopener\">AV\u00cdS 1 Modificaci\u00f3 Reuni\u00f3 de Patrons<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/Llistat-de-premis.pdf\">Llistat de premis<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/LLISTAT-INSCRITS-2.pdf\">Llistat d&rsquo;inscrits (29.4.201)<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/IR-comodor-2021.pdf\" target=\"_blank\" rel=\"noopener\">Instruccions de Regata<\/a><\/li>\n<li><a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUQlhXM1pWSVFCMEEyVkxaVVY2UzkyVFBJUCQlQCN0PWcu\" target=\"_blank\" rel=\"noopener\">Demana el teu amarrador<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/TRAQUER.pdf\" target=\"_blank\" rel=\"noopener\">Instruccions Track &#8211; Estela<\/a><\/li>\n<li><a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUNFM4MTBFMURMSUtCRVdJMTkxNlhQNkFJQSQlQCN0PWcu\" target=\"_blank\" rel=\"noopener\">Signar la declaraci\u00f3 responsable \u2013 COVID-19<\/a><\/li>\n<li><a href=\"http:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/AR-Comodor21VFCV.pdf\" target=\"_blank\" rel=\"noopener\">Anunci de regata<\/a><\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-02\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Drets d&rsquo;inscripci\u00f3<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-02\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p>El per\u00edode de sol\u00b7licitud d\u2019inscripci\u00f3 <strong>finalitzar\u00e0 el dia 24 d\u2019abril de 2021 a les 18.00 h.<\/strong><\/p>\n<p>Els drets d&rsquo;inscripci\u00f3 s\u2019estableixen en:<\/p>\n<ul>\n<li><strong>Fins el 24 d\u2019abril: 50 euros per embarcaci\u00f3<\/strong><u>.<\/u><\/li>\n<li><strong>A partir del 24 d\u2019abril: 75 euros per embarcaci\u00f3<\/strong><\/li>\n<\/ul>\n<p>El Comit\u00e8 de Regates es reserva el dret d\u2019admetre inscripcions fora de termini.<\/p>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-03\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Recorregut i Regata en Directe<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-03\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p>Dos recorreguts, tu esculls la distancia:<\/p>\n<ul>\n<li><strong><u>Recorregut 35 NM: <\/u><\/strong><em>Puntuable pel Campionat de Catalunya Solitaris i A Dos de la FCV. <\/em>L\u2019Escala \u2013 Illes Medes \u2013 Illa Messina \u2013 L\u2019Escala.<\/li>\n<li><strong><u>Recorregut 65 NM: <\/u><\/strong><em>Puntuable el Circu\u00eft de Regates Costeres de la FCV.<\/em>Dues opcions (s\u2019indicar\u00e0 durant la reuni\u00f3 de patrons):\u00a0L\u2019Escala \u2013 Illes Medes \u2013 Banyuls de la Marenda (Fran\u00e7a) \u2013 l\u2019Escala<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.estela.co\/es\/tracking-regata\/7069\/regata-comodor-2021bis\"><strong>Segueix la regata en Directe:\u00a0<\/strong><\/a><\/p>\n<p><iframe src=\"https:\/\/www.estela.co\/es\/tracking-regata\/7069\/regata-comodor-2021bis\" width=\"420\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-04\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Guardons<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-04\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <ul>\n<li><strong>Guanyador Absolut<\/strong> \u2013 ser\u00e0 aquell que amb Temps compensat dins de la seva categoria hagi tingut un menor temps<\/li>\n<li>1\u00ba, 2\u00ba, 3\u00ba i 4\u00ba Classificat de la Classe RI i Rally<\/li>\n<li>1\u00ba Classificat de la Classe J70<\/li>\n<li>1\u00ba Tripulaci\u00f3 femenina o mitxa<\/li>\n<li>El nom de les embarcacions guanyadores absolutes de cada divisi\u00f3 RI i Rally figurar\u00e0 en el trofeu especial \u201cComodor\u201d que est\u00e0 en dip\u00f2sit a les oficines del Club N\u00e0utic l\u2019Escala.<\/li>\n<li><strong>Gran Premi Jotun \u2013 Varador l\u2019Escala<\/strong><strong> a sortejar entre les embarcacions que finalitzin la regata dins del temps establert &#8211; 1 servei de \u00ab\u00a0manteniment expr\u00e9s 2021\u00a0\u00bb (Neteja, antifouling, 5 dies estada, hissada i botadura)<\/strong><strong>\u00a0<\/strong><strong>a Varador l&rsquo;Escala i amb una pintura antifouling a escollir de la marca JOTUN (Non Stop o Racing). <\/strong><\/li>\n<li>Restaurant <strong>El Moli de L\u2019Escala<\/strong> &#8211; Men\u00fa per a dues persones<\/li>\n<li>Restaurant <strong>Can Miquel<\/strong> &#8211; Men\u00fa per a dues persones<\/li>\n<li>Restaurant <strong>Grop<\/strong> &#8211; Men\u00fa per a dues persones<\/li>\n<li>Restaurant <strong>La Clota<\/strong> &#8211; Men\u00fa per a dues persones<\/li>\n<li>Restaurant <strong>Mery Lou<\/strong> \u2013 Men\u00fa per dues persones<\/li>\n<li>Restaurant <strong>La Barra del Port<\/strong>\u00a0&#8211; Men\u00fa per a dues persones<\/li>\n<li>Restaurant <strong>Koorpilombolo<\/strong> &#8211; Men\u00fa per a dues persones<\/li>\n<li>Bodega <strong>Els Barrils<\/strong> &#8211; 2 copes de vi i una tapa<\/li>\n<li><strong>Club N\u00e0utic l&rsquo;Escala<\/strong> &#8211; 1 lot de 3 ampolles de vi \u00ab\u00a050 aniversari del Club\u00a0\u00bb<\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                        <\/div><!-- end accordion -->\n                <\/div><!-- end accordion-block -->\n            \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n    \n        <div class=\"btn-box\">\n            <a href=\"https:\/\/www.flickr.com\/photos\/nauticescala\/albums\/72157692259000402\" target=\"_blank\" class=\"btn btn-primary\">Fotografies<\/a>\n\n        \n        \n\n<\/div><!-- end btn-box -->\n\n   \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\t<div class=\"container\">\n\n<div class=\"content-block\">\n \t \t\n \t \t   \n \t\t    <div class=\"partners-block\">\t    \t\n\t    \t\t    \t\t<h3>Patrocinadors:<\/h3>\n\t    \t  \n\t    \t   \n\t    \t\t\t        <ul class=\"partners-list\">\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/www.jotun.com\/es\/es\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/01\/jotun.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/olympiagrup.com\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/olympia-grup-350x59.jpg\" alt=\"Olympia grup\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/varadorlescala.com\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/03\/varador-lescala-home-1.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t            \n\t\t        <\/ul><!-- end partners-list -->\t    \t\t\n\t    \t\t    <\/div><!-- end partners-block --> \t   \t\n \t   \n<\/div><!-- end content-block -->\n\n\t<\/div>\n\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\t<div class=\"container\">\n\n<div class=\"content-block\">\n \t \t\n \t \t   \n \t\t    <div class=\"partners-block\">\t    \t\n\t    \t\t    \t\t<h3>Col\u00b7laboradors<\/h3>\n\t    \t  \n\t    \t   \n\t    \t\t\t        <ul class=\"partners-list\">\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/www.visitlescala.com\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/01\/ajuntament-escala-1.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/08\/diputacio-350x201.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/08\/logo-fcv-350x215.png\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/www.empordalia.com\/ca\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/empordalia-350x194.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"http:\/\/elsbarrils.com\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/elsbarrils-e1619704598283.png\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/molidelescala.com\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/moli-e1619704244965.png\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/www.visitlescala.com\/es\/restaurantes\/mery-lou\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/mery-lu-e1619705561710.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/www.visitlescala.com\/es\/restaurantes\/la-clota\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/la-clota-350x128.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/www.visitlescala.com\/es\/restaurante\/korpilombolo\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/koorpilombolo-e1619705605538.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/restaurantgrop.cat\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/grop-1-e1619704411417.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"https:\/\/canmiquelrestaurant.com\/\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/can-miquel-logo-350x85.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"http:\/\/labarradelport.com\/ca\/index.php?idioma=ca\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t            \n\t\t        <\/ul><!-- end partners-list -->\t    \t\t\n\t    \t\t    <\/div><!-- end partners-block --> \t   \t\n \t   \n<\/div><!-- end content-block -->\n\n\t<\/div>\n\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section><div class='photonic-flickr-stream photonic-stream ' id='photonic-flickr-stream-1'>\n<div id='photonic-slideshow-flickr-1' class='photonic-slideshow splide default title-display-tooltip photonic-slideshow-adapt-height-width' data-splide='{&quot;type&quot;:&quot;fade&quot;,&quot;perPage&quot;:&quot;1&quot;,&quot;autoplay&quot;:true,&quot;interval&quot;:&quot;5000&quot;,&quot;speed&quot;:&quot;1000&quot;,&quot;drag&quot;:true,&quot;pauseOnHover&quot;:true,&quot;pagination&quot;:false,&quot;slideFocus&quot;:false,&quot;arrows&quot;:false,&quot;direction&quot;:&quot;ltr&quot;,&quot;breakpoints&quot;:{&quot;480&quot;:{&quot;perPage&quot;:1}}}'>\n\t<div class='splide__track'>\n\t\t<ul class='photonic-slideshow-content splide__list'>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651817572_5ea525ecc6_h.jpg' alt='2024-nauticescala-Comodor-107' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651817572' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53652906728_fb5dfdb2d1_h.jpg' alt='2024-nauticescala-Comodor-106' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53652906728' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651817577_24f2f2f455_h.jpg' alt='2024-nauticescala-Comodor-105' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651817577' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53652689441_419c8b956e_h.jpg' alt='2024-nauticescala-Comodor-104' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53652689441' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651817567_5ef46a0f25_h.jpg' alt='2024-nauticescala-Comodor-103' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651817567' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53652689431_7a2f83ff50_h.jpg' alt='2024-nauticescala-Comodor-102' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53652689431' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653036694_26c17799df_h.jpg' alt='2024-nauticescala-Comodor-101' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653036694' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653150060_9240d90fb9_h.jpg' alt='2024-nauticescala-Comodor-100' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653150060' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653036689_6ad42cd888_h.jpg' alt='2024-nauticescala-Comodor-99' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653036689' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653036684_95b38eceac_h.jpg' alt='2024-nauticescala-Comodor-98' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653036684' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53652689401_8af3f3b8fd_h.jpg' alt='2024-nauticescala-Comodor-97' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53652689401' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651817547_f777d3fefe_h.jpg' alt='2024-nauticescala-Comodor-96' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651817547' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53652906683_4b2e79e99b_h.jpg' alt='2024-nauticescala-Comodor-95' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53652906683' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651817522_f7a4edb9c2_h.jpg' alt='2024-nauticescala-Comodor-94' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651817522' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53652906663_2144e487ba_h.jpg' alt='2024-nauticescala-Comodor-93' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53652906663' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53652906668_b42a29c41a_h.jpg' alt='2024-nauticescala-Comodor-92' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53652906668' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653036634_9ef8ec5ed7_h.jpg' alt='2024-nauticescala-Comodor-91' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653036634' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651817487_07fa25c7a0_h.jpg' alt='2024-nauticescala-Comodor-90' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651817487' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651817492_cb6f7699dc_h.jpg' alt='2024-nauticescala-Comodor-89' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651817492' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653036629_12273cb21b_h.jpg' alt='2024-nauticescala-Comodor-88' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653036629' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653150140_694787c3a9_h.jpg' alt='2024-nauticescala-Comodor-87' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653150140' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53652689481_874569ccb0_h.jpg' alt='2024-nauticescala-Comodor-86' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53652689481' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53652906748_c4e627e65c_h.jpg' alt='2024-nauticescala-Comodor-85' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53652906748' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651817622_b5b1777909_h.jpg' alt='2024-nauticescala-Comodor-84' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651817622' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651817617_733c2155f0_h.jpg' alt='2024-nauticescala-Comodor-83' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651817617' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653150100_5cec29c642_h.jpg' alt='2024-nauticescala-Comodor-82' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653150100' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653036764_10d4e760ed_h.jpg' alt='2024-nauticescala-Comodor-81' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653036764' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653036754_99edbbdec8_h.jpg' alt='2024-nauticescala-Comodor-80' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653036754' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651817612_a1c14aaeba_h.jpg' alt='2024-nauticescala-Comodor-79' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651817612' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653150090_379d3d5b29_h.jpg' alt='2024-nauticescala-Comodor-78' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653150090' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53653036714_be7ae2643a_h.jpg' alt='2024-nauticescala-Comodor-77' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53653036714' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651207133_db8cbae7c7_h.jpg' alt='2024-nauticescala-Comodor-76' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651207133' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651450285_3493191399_h.jpg' alt='2024-nauticescala-Comodor-75' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651450285' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651340189_c1256a7535_h.jpg' alt='2024-nauticescala-Comodor-74' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651340189' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992351_5099af3dfb_h.jpg' alt='2024-nauticescala-Comodor-73' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992351' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651450275_6f28c339d8_h.jpg' alt='2024-nauticescala-Comodor-72' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651450275' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651340179_6c56c0b8cb_h.jpg' alt='2024-nauticescala-Comodor-71' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651340179' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650119072_163ef9c260_h.jpg' alt='2024-nauticescala-Comodor-70' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650119072' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651207098_ec329c8294_h.jpg' alt='2024-nauticescala-Comodor-69' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651207098' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651450245_bbb9d885bc_h.jpg' alt='2024-nauticescala-Comodor-68' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651450245' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651340159_936cb7617d_h.jpg' alt='2024-nauticescala-Comodor-67' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651340159' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992321_f4b7888798_h.jpg' alt='2024-nauticescala-Comodor-66' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992321' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650119027_fada909307_h.jpg' alt='2024-nauticescala-Comodor-65' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650119027' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651340129_ea9f0d8ddb_h.jpg' alt='2024-nauticescala-Comodor-64' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651340129' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650118997_d93095d559_h.jpg' alt='2024-nauticescala-Comodor-63' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650118997' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650119012_1a834c7c1d_h.jpg' alt='2024-nauticescala-Comodor-62' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650119012' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651207048_6eccf6f68f_h.jpg' alt='2024-nauticescala-Comodor-61' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651207048' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651340089_3b3e03c826_h.jpg' alt='2024-nauticescala-Comodor-60' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651340089' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651340104_80c0b7c3b1_h.jpg' alt='2024-nauticescala-Comodor-59' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651340104' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651450165_9d9499fe3e_h.jpg' alt='2024-nauticescala-Comodor-58' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651450165' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651450170_408c759ccc_h.jpg' alt='2024-nauticescala-Comodor-57' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651450170' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651450140_1314933c69_h.jpg' alt='2024-nauticescala-Comodor-56' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651450140' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650118972_f4e5b9605d_h.jpg' alt='2024-nauticescala-Comodor-55' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650118972' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651207013_efb184b970_h.jpg' alt='2024-nauticescala-Comodor-54' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651207013' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992261_713446efe7_h.jpg' alt='2024-nauticescala-Comodor-53' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992261' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650118957_c817665667_h.jpg' alt='2024-nauticescala-Comodor-52' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650118957' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651450095_c387f6e076_h.jpg' alt='2024-nauticescala-Comodor-51' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651450095' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650118947_2ca00d74f4_c.jpg' alt='2024-nauticescala-Comodor-50' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650118947' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992241_52ab7ad260_h.jpg' alt='2024-nauticescala-Comodor-49' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992241' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992231_10b2d58037_h.jpg' alt='2024-nauticescala-Comodor-48' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992231' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992226_c0aa887aeb_h.jpg' alt='2024-nauticescala-Comodor-47' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992226' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651206938_815fa13fe1_c.jpg' alt='2024-nauticescala-Comodor-46' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651206938' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651206933_100d75238b_c.jpg' alt='2024-nauticescala-Comodor-45' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651206933' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651450050_46478e336e_h.jpg' alt='2024-nauticescala-Comodor-44' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651450050' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651450060_df1c41ab4e_h.jpg' alt='2024-nauticescala-Comodor-43' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651450060' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650118872_96004d5e99_h.jpg' alt='2024-nauticescala-Comodor-42' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650118872' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992161_9421086b4c_h.jpg' alt='2024-nauticescala-Comodor-41' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992161' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651206868_ff6bfb4fc2_h.jpg' alt='2024-nauticescala-Comodor-40' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651206868' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651450015_2af79a0b20_c.jpg' alt='2024-nauticescala-Comodor-39' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651450015' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651450000_d8e0fe8f9e_h.jpg' alt='2024-nauticescala-Comodor-38' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651450000' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651339959_01aece36eb_h.jpg' alt='2024-nauticescala-Comodor-37' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651339959' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651339939_323b42fbb1_h.jpg' alt='2024-nauticescala-Comodor-36' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651339939' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650118837_871180403c_h.jpg' alt='2024-nauticescala-Comodor-35' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650118837' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992126_6370dd1bd2_h.jpg' alt='2024-nauticescala-Comodor-34' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992126' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650118827_863d825ce3_h.jpg' alt='2024-nauticescala-Comodor-33' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650118827' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651449960_8797f6d7c4_h.jpg' alt='2024-nauticescala-Comodor-32' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651449960' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651339919_539bdb9064_h.jpg' alt='2024-nauticescala-Comodor-31' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651339919' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992086_2335ce12b2_h.jpg' alt='2024-nauticescala-Comodor-30' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992086' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651206813_b413cd91ec_h.jpg' alt='2024-nauticescala-Comodor-29' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651206813' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651206788_65a8d7b1c7_h.jpg' alt='2024-nauticescala-Comodor-28' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651206788' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651449890_073dd03049_h.jpg' alt='2024-nauticescala-Comodor-27' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651449890' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992021_8f5f859958_h.jpg' alt='2024-nauticescala-Comodor-26' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992021' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992041_5867cebea3_h.jpg' alt='2024-nauticescala-Comodor-25' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992041' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992016_40f5157f61_h.jpg' alt='2024-nauticescala-Comodor-24' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992016' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650992011_6d6fdb9fed_h.jpg' alt='2024-nauticescala-Comodor-23' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650992011' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651449880_8d99e4d73b_h.jpg' alt='2024-nauticescala-Comodor-22' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651449880' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650118732_95326ca238_h.jpg' alt='2024-nauticescala-Comodor-21' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650118732' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651339849_b6aa6cd40e_h.jpg' alt='2024-nauticescala-Comodor-20' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651339849' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651339834_443d6c6eba_h.jpg' alt='2024-nauticescala-Comodor-19' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651339834' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651206713_f5369e22ef_h.jpg' alt='2024-nauticescala-Comodor-18' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651206713' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651449835_745d582fd6_h.jpg' alt='2024-nauticescala-Comodor-17' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651449835' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651339819_6539a0f977_h.jpg' alt='2024-nauticescala-Comodor-16' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651339819' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651206703_d1401fef2b_h.jpg' alt='2024-nauticescala-Comodor-15' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651206703' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651206693_dffab4df34_h.jpg' alt='2024-nauticescala-Comodor-14' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651206693' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650991941_58a8b14240_h.jpg' alt='2024-nauticescala-Comodor-13' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650991941' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650991916_1df9e007bb_h.jpg' alt='2024-nauticescala-Comodor-12' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650991916' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651206668_d4d93e1f9c_h.jpg' alt='2024-nauticescala-Comodor-11' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651206668' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651206633_83646fd7f6_h.jpg' alt='2024-nauticescala-Comodor-10' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651206633' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651449780_2a1cdae62c_h.jpg' alt='2024-nauticescala-Comodor-9' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651449780' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650118627_33dcd6e9ac_h.jpg' alt='2024-nauticescala-Comodor-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650118627' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651339739_552506c997_h.jpg' alt='2024-nauticescala-Comodor-7' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651339739' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651206613_4235adc5fe_h.jpg' alt='2024-nauticescala-Comodor-6' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651206613' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650991886_ecb2f4dc2f_h.jpg' alt='2024-nauticescala-Comodor-5' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650991886' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651449775_b46b2a6adc_h.jpg' alt='2024-nauticescala-Comodor-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651449775' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53650119107_308f28155e_h.jpg' alt='2024-nauticescala-Comodor-3' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53650119107' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651207153_4cf976b6f0_h.jpg' alt='2024-nauticescala-Comodor-2' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651207153' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/53651340209_ed40ea52b7_h.jpg' alt='2024-nauticescala-Comodor' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-53651340209' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877365719_52d605573f_h.jpg' alt='2023-Nauticescala-Comodor-111' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877365719' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877586315_365e8e95e8_h.jpg' alt='2023-Nauticescala-Comodor-110' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877586315' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877653813_28794a400d_h.jpg' alt='2023-Nauticescala-Comodor-109' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877653813' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877365694_9c8d50f33a_h.jpg' alt='2023-Nauticescala-Comodor-108' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877365694' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877653798_ddb1c7ef51_h.jpg' alt='2023-Nauticescala-Comodor-107' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877653798' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52876624792_cba8c847c5_h.jpg' alt='2023-Nauticescala-Comodor-106' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52876624792' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52876624767_2ce3030e36_h.jpg' alt='2023-Nauticescala-Comodor-105' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52876624767' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877586285_117b275c61_h.jpg' alt='2023-Nauticescala-Comodor-104' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877586285' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877653788_7deda2ee22_h.jpg' alt='2023-Nauticescala-Comodor-103' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877653788' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877586250_5273a8b34e_h.jpg' alt='2023-Nauticescala-Comodor-102' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877586250' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52876624727_26b3770fef_h.jpg' alt='2023-Nauticescala-Comodor-101' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52876624727' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877208301_827d1c0d6a_h.jpg' alt='2023-Nauticescala-Comodor-100' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877208301' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877365609_191fbb3f96_h.jpg' alt='2023-Nauticescala-Comodor-99' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877365609' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877653753_eff9a47d59_h.jpg' alt='2023-Nauticescala-Comodor-98' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877653753' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877653708_ef46a6cb38_h.jpg' alt='2023-Nauticescala-Comodor-97' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877653708' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52876624672_8fb34fd13a_h.jpg' alt='2023-Nauticescala-Comodor-96' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52876624672' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877653688_ecdc1649ef_h.jpg' alt='2023-Nauticescala-Comodor-95' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877653688' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52876624677_027d18f546_h.jpg' alt='2023-Nauticescala-Comodor-94' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52876624677' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52876624667_c84b212bb6_h.jpg' alt='2023-Nauticescala-Comodor-93' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52876624667' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877586200_945684a80d_h.jpg' alt='2023-Nauticescala-Comodor-92' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877586200' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877653633_b6ea50cd46_h.jpg' alt='2023-Nauticescala-Comodor-91' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877653633' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877586155_d0d4c25a5c_h.jpg' alt='2023-Nauticescala-Comodor-90' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877586155' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877208166_4c16e17f37_h.jpg' alt='2023-Nauticescala-Comodor-89' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877208166' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877365544_a0fe39dc55_h.jpg' alt='2023-Nauticescala-Comodor-88' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877365544' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877365529_6248db8dfa_h.jpg' alt='2023-Nauticescala-Comodor-87' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877365529' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877586130_12e3d791af_h.jpg' alt='2023-Nauticescala-Comodor-86' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877586130' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877586120_21324786dc_h.jpg' alt='2023-Nauticescala-Comodor-85' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877586120' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52876624592_263e97a915_h.jpg' alt='2023-Nauticescala-Comodor-84' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52876624592' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877586075_618d816f44_h.jpg' alt='2023-Nauticescala-Comodor-83' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877586075' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877586025_37f6fb1607_h.jpg' alt='2023-Nauticescala-Comodor-82' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877586025' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877208106_77d5be8368_h.jpg' alt='2023-Nauticescala-Comodor-81' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877208106' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52876624512_0a1b4f1f9a_h.jpg' alt='2023-Nauticescala-Comodor-80' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52876624512' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877365409_30db70f45a_h.jpg' alt='2023-Nauticescala-Comodor-79' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877365409' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877365394_f207a3cca3_h.jpg' alt='2023-Nauticescala-Comodor-78' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877365394' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877208096_a54317c42a_h.jpg' alt='2023-Nauticescala-Comodor-77' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877208096' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877653468_6683d2a86c_h.jpg' alt='2023-Nauticescala-Comodor-76' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877653468' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877653933_0b6be91d03_h.jpg' alt='2023-Nauticescala-Comodor-75' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877653933' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877653908_fb9f66a867_h.jpg' alt='2023-Nauticescala-Comodor-74' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877653908' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877208376_e3859b43e9_h.jpg' alt='2023-Nauticescala-Comodor-73' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877208376' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52877586325_0b319a6f77_h.jpg' alt='2023-Nauticescala-Comodor-72' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52877586325' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267818_bff5ceb86f_h.jpg' alt='2023-Nauticescala-Comodor-71' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267818' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874826376_40efa77d01_h.jpg' alt='2023-Nauticescala-Comodor-70' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874826376' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874247272_0a6d4dde26_h.jpg' alt='2023-Nauticescala-Comodor-69' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874247272' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207400_612bf79382_h.jpg' alt='2023-Nauticescala-Comodor-68' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207400' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207395_fe738c449a_h.jpg' alt='2023-Nauticescala-Comodor-67' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207395' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992814_35dec2a98d_h.jpg' alt='2023-Nauticescala-Comodor-66' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992814' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207350_56ee83cbca_h.jpg' alt='2023-Nauticescala-Comodor-65' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207350' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874247217_ce6e047997_h.jpg' alt='2023-Nauticescala-Comodor-64' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874247217' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992804_f32bab80e2_h.jpg' alt='2023-Nauticescala-Comodor-63' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992804' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874826321_f78c6f4b1c_h.jpg' alt='2023-Nauticescala-Comodor-62' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874826321' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992789_9d9ca228db_h.jpg' alt='2023-Nauticescala-Comodor-61' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992789' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992769_2c34ea472f_h.jpg' alt='2023-Nauticescala-Comodor-60' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992769' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874247182_a1a671ef8a_h.jpg' alt='2023-Nauticescala-Comodor-59' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874247182' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267723_1344a44312_h.jpg' alt='2023-Nauticescala-Comodor-58' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267723' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267713_9e36afedba_h.jpg' alt='2023-Nauticescala-Comodor-57' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267713' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207280_413bc24bf6_h.jpg' alt='2023-Nauticescala-Comodor-56' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207280' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992734_2c0055abcc_h.jpg' alt='2023-Nauticescala-Comodor-55' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992734' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992724_536d9216dd_h.jpg' alt='2023-Nauticescala-Comodor-54' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992724' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207275_bb0553a0d2_h.jpg' alt='2023-Nauticescala-Comodor-53' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207275' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874826226_ffcb2a29c2_h.jpg' alt='2023-Nauticescala-Comodor-52' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874826226' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874826221_a3e00064b8_h.jpg' alt='2023-Nauticescala-Comodor-51' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874826221' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874826216_b9d7eb9500_h.jpg' alt='2023-Nauticescala-Comodor-50' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874826216' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992674_ac83a81fbb_h.jpg' alt='2023-Nauticescala-Comodor-49' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992674' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992669_f4d2603b25_h.jpg' alt='2023-Nauticescala-Comodor-48' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992669' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267638_cde37bb28b_h.jpg' alt='2023-Nauticescala-Comodor-47' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267638' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874826201_499d6cdc17_h.jpg' alt='2023-Nauticescala-Comodor-46' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874826201' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207190_5f191a2925_h.jpg' alt='2023-Nauticescala-Comodor-45' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207190' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874247152_3d089af588_h.jpg' alt='2023-Nauticescala-Comodor-44' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874247152' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267598_aae1fc066e_h.jpg' alt='2023-Nauticescala-Comodor-43' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267598' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992614_f97a856f64_h.jpg' alt='2023-Nauticescala-Comodor-42' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992614' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874247157_924c53c11e_h.jpg' alt='2023-Nauticescala-Comodor-41' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874247157' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207165_90ed851952_h.jpg' alt='2023-Nauticescala-Comodor-40' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207165' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874247137_f0d0fcd0b5_h.jpg' alt='2023-Nauticescala-Comodor-39' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874247137' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992549_6b86216c6a_h.jpg' alt='2023-Nauticescala-Comodor-38' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992549' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992554_16793a8d2d_h.jpg' alt='2023-Nauticescala-Comodor-37' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992554' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207120_373debca58_h.jpg' alt='2023-Nauticescala-Comodor-36' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207120' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874247087_3af501c81a_h.jpg' alt='2023-Nauticescala-Comodor-35' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874247087' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992539_80ee1b74c8_h.jpg' alt='2023-Nauticescala-Comodor-34' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992539' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874247097_aa22256a9d_h.jpg' alt='2023-Nauticescala-Comodor-33' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874247097' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992529_77a2bc1116_h.jpg' alt='2023-Nauticescala-Comodor-32' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992529' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992509_24962e4c4f_h.jpg' alt='2023-Nauticescala-Comodor-31' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992509' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874826001_3ac27ce27e_h.jpg' alt='2023-Nauticescala-Comodor-30' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874826001' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992499_a291afa9c0_h.jpg' alt='2023-Nauticescala-Comodor-29' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992499' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207090_8290078da3_h.jpg' alt='2023-Nauticescala-Comodor-28' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207090' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207095_d81fba8035_h.jpg' alt='2023-Nauticescala-Comodor-27' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207095' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207100_1cca7555ea_h.jpg' alt='2023-Nauticescala-Comodor-26' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207100' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207080_38cf7c8898_h.jpg' alt='2023-Nauticescala-Comodor-25' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207080' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207020_328a700aa2_h.jpg' alt='2023-Nauticescala-Comodor-24' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207020' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267438_4aae1c3c81_h.jpg' alt='2023-Nauticescala-Comodor-23' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267438' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874825941_4ab60ea7aa_h.jpg' alt='2023-Nauticescala-Comodor-22' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874825941' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207030_f655f742c2_h.jpg' alt='2023-Nauticescala-Comodor-21' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207030' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267433_84e7c6830d_h.jpg' alt='2023-Nauticescala-Comodor-20' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267433' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875206975_ca85f087e7_h.jpg' alt='2023-Nauticescala-Comodor-19' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875206975' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992414_1b75e95c63_h.jpg' alt='2023-Nauticescala-Comodor-18' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992414' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267388_ec667faa03_h.jpg' alt='2023-Nauticescala-Comodor-17' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267388' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992349_cd00017902_h.jpg' alt='2023-Nauticescala-Comodor-16' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992349' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992334_f46eb96d6d_h.jpg' alt='2023-Nauticescala-Comodor-15' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992334' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267368_741662a0db_h.jpg' alt='2023-Nauticescala-Comodor-14' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267368' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874825856_4240546c74_h.jpg' alt='2023-Nauticescala-Comodor-13' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874825856' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875206910_41f7533261_h.jpg' alt='2023-Nauticescala-Comodor-12' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875206910' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874825821_0f3c59dbc5_h.jpg' alt='2023-Nauticescala-Comodor-11' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874825821' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992274_8e6390ddb4_h.jpg' alt='2023-Nauticescala-Comodor-10' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992274' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874825766_5ab4565c7f_h.jpg' alt='2023-Nauticescala-Comodor-9' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874825766' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874825776_f35292a142_h.jpg' alt='2023-Nauticescala-Comodor-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874825776' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992259_76806d6248_h.jpg' alt='2023-Nauticescala-Comodor-7' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992259' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267273_de5be84567_h.jpg' alt='2023-Nauticescala-Comodor-6' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267273' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267248_59e329502a_h.jpg' alt='2023-Nauticescala-Comodor-5' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267248' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992234_18f7f54ae9_h.jpg' alt='2023-Nauticescala-Comodor-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992234' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875207445_612aa1ca2a_h.jpg' alt='2023-Nauticescala-Comodor-3' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875207445' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52875267828_3f9bf319fd_h.jpg' alt='2023-Nauticescala-Comodor-2' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52875267828' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52874992864_b6e3ed5a5e_h.jpg' alt='2023-Nauticescala-Comodor' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52874992864' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059484118_e2d496e2e9_h.jpg' alt='2022-club nautic-escala-66' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059484118' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059452016_238d239e6a_h.jpg' alt='2022-club nautic-escala-65' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059452016' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058411992_e548a41a4d_h.jpg' alt='2022-club nautic-escala-64' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058411992' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059484013_627274f7ee_h.jpg' alt='2022-club nautic-escala-63' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059484013' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059483968_0e4e4d1612_h.jpg' alt='2022-club nautic-escala-62' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059483968' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059935880_69455d2f54_h.jpg' alt='2022-club nautic-escala-61' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059935880' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059687734_4eeaca8161_h.jpg' alt='2022-club nautic-escala-60' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059687734' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059451816_c9ce07019b_h.jpg' alt='2022-club nautic-escala-59' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059451816' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059687689_b2cb194d8a_h.jpg' alt='2022-club nautic-escala-58' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059687689' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059451781_249e2b7ad0_h.jpg' alt='2022-club nautic-escala-57' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059451781' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059483863_41922282e0_h.jpg' alt='2022-club nautic-escala-56' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059483863' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059935795_8c10a01900_h.jpg' alt='2022-club nautic-escala-55' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059935795' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059451746_57028c121d_h.jpg' alt='2022-club nautic-escala-54' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059451746' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059936215_321967dcf6_h.jpg' alt='2022-club nautic-escala-53' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059936215' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058412112_6f94cc3d0f_h.jpg' alt='2022-club nautic-escala-52' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058412112' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059687919_7fab809dfa_h.jpg' alt='2022-club nautic-escala-51' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059687919' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059022404_985e4f7af1_k.jpg' alt='2022-club nautic-escala-50' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059022404' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057745837_c990512a76_k.jpg' alt='2022-club nautic-escala-49' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057745837' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059271145_2a804459a7_k.jpg' alt='2022-club nautic-escala-48' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059271145' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057745792_9ade216566_k.jpg' alt='2022-club nautic-escala-47' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057745792' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058818148_87d447c805_k.jpg' alt='2022-club nautic-escala-46' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058818148' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059271220_6d62f78c06_k.jpg' alt='2022-club nautic-escala-45' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059271220' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057745737_07747ff262_k.jpg' alt='2022-club nautic-escala-44' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057745737' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059022264_892aaf0278_k.jpg' alt='2022-club nautic-escala-43' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059022264' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058761438_9dec544da1_k.jpg' alt='2022-club nautic-escala-42' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058761438' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058728156_dcef59a723_k.jpg' alt='2022-club nautic-escala-41' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058728156' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058964689_05ca3403d5_k.jpg' alt='2022-club nautic-escala-40' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058964689' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058761573_89c025b648_k.jpg' alt='2022-club nautic-escala-39' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058761573' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057688947_b07623fe82_k.jpg' alt='2022-club nautic-escala-38' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057688947' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058964774_0bcf13ccab_k.jpg' alt='2022-club nautic-escala-37' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058964774' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058964569_788fe0f2db_k.jpg' alt='2022-club nautic-escala-36' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058964569' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057688997_f9fbf710c1_k.jpg' alt='2022-club nautic-escala-35' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057688997' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058728321_3970661c83_k.jpg' alt='2022-club nautic-escala-34' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058728321' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058761753_11059baed7_k.jpg' alt='2022-club nautic-escala-33' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058761753' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059215035_21eae37f78_k.jpg' alt='2022-club nautic-escala-32' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059215035' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058761798_31d66d124c_k.jpg' alt='2022-club nautic-escala-31' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058761798' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057689052_14fa970e56_k.jpg' alt='2022-club nautic-escala-30' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057689052' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058761838_04ffc6bcc4_k.jpg' alt='2022-club nautic-escala-29' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058761838' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058728061_e87a72d899_k.jpg' alt='2022-club nautic-escala-28' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058728061' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059215105_2bb816b21a_k.jpg' alt='2022-club nautic-escala-27' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059215105' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058728406_d6de455a73_k.jpg' alt='2022-club nautic-escala-26' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058728406' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058728446_8c2c629173_k.jpg' alt='2022-club nautic-escala-25' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058728446' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058761943_b591988cc7_k.jpg' alt='2022-club nautic-escala-24' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058761943' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058965004_960cdc4a78_k.jpg' alt='2022-club nautic-escala-23' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058965004' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059215180_c5ed6b64ac_k.jpg' alt='2022-club nautic-escala-22' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059215180' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058965024_a1ac7a1e67_k.jpg' alt='2022-club nautic-escala-21' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058965024' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059214760_ec4e3d5d5d_k.jpg' alt='2022-club nautic-escala-20' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059214760' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058965049_12cfe4fea2_k.jpg' alt='2022-club nautic-escala-19' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058965049' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059215230_9a83483d07_k.jpg' alt='2022-club nautic-escala-18' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059215230' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057689197_a0b64f3c8f_k.jpg' alt='2022-club nautic-escala-17' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057689197' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057689212_a3d4441631_k.jpg' alt='2022-club nautic-escala-16' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057689212' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059215280_e345d214cd_k.jpg' alt='2022-club nautic-escala-15' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059215280' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057689282_fecb958db5_k.jpg' alt='2022-club nautic-escala-14' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057689282' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058761503_1bafb51ffc_k.jpg' alt='2022-club nautic-escala-13' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058761503' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058728666_e5eaa0afe2_k.jpg' alt='2022-club nautic-escala-12' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058728666' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058762188_a8e78789e2_k.jpg' alt='2022-club nautic-escala-11' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058762188' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057689357_6c87512388_k.jpg' alt='2022-club nautic-escala-10' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057689357' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059215360_f454fd9a5c_k.jpg' alt='2022-club nautic-escala-9' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059215360' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057689397_a225f895cb_k.jpg' alt='2022-club nautic-escala-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057689397' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52057689422_646ed2b584_k.jpg' alt='2022-club nautic-escala-7' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52057689422' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059214820_c339cfc4b7_k.jpg' alt='2022-club nautic-escala-6' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059214820' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058762248_6ccecce41e_k.jpg' alt='2022-club nautic-escala-5' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058762248' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058728771_f216343007_k.jpg' alt='2022-club nautic-escala-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058728771' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52059215415_a000623964_k.jpg' alt='2022-club nautic-escala-3' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52059215415' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/52058762308_9b45491d0b_k.jpg' alt='2022-club nautic-escala-2' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-52058762308' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51153006564_d0ae539d36_h.jpg' alt='2021-Club Nautic lEscala-20' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51153006564' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51152452563_d2357ce123_h.jpg' alt='2021-Club Nautic lEscala-19' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51152452563' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51152452473_ad0bb946e2_h.jpg' alt='2021-Club Nautic lEscala-10' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51152452473' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51153323580_6791dd4af4_h.jpg' alt='2021-Club Nautic lEscala-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51153323580' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51152452403_a9bb6a1590_h.jpg' alt='2021-Club Nautic lEscala-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51152452403' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51149663127_5c04aa6d6f_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-32' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51149663127' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51149663082_edfa459f0f_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-26' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51149663082' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51150336606_3f5cb50733_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-24' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51150336606' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51150570603_9ebf0dc1da_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-23' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51150570603' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51149663052_af1897a594_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-19' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51149663052' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51150570518_8f79f35f54_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-15' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51150570518' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51150336496_f4b91d2cdc_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-14' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51150336496' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51150570473_9f5a61c7fa_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-12' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51150570473' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51150336416_05e89450db_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-10' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51150336416' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51150336366_5e4c161ec7_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51150336366' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51150336341_7307ef304f_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-6' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51150336341' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51151443465_2b41d92a46_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor-5' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51151443465' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51150336716_8d07313af4_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala-Comodor' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51150336716' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/46989440534_bbbf6d8f69_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-55' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46989440534' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/32835110727_f321b14744_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-39' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-32835110727' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/46855722975_91a5cd195a_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-29' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46855722975' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/46855723215_5575744fa2_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-28' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46855723215' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/46855723255_ce5497becb_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-26' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46855723255' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/33895069668_8807d23d44_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-24' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33895069668' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/46855723315_56f22deb54_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-20' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46855723315' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/47719722802_cdbba3312f_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-19' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47719722802' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/33895070028_56f22deb54_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-18' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33895070028' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/46982931384_766bcfd4c7_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-16' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46982931384' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/47719723102_6fb9873ff2_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-13' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47719723102' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/46982931554_46404dc871_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-12' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46982931554' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/47719723312_3889ecd98f_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47719723312' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/46982931734_3889ecd98f_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-7' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46982931734' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/47719721642_f9c3f32da2_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47719721642' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/40806669703_f95689af62_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-36' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-40806669703' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/47720516352_a681d6b527_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-31' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47720516352' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/808\/40406746005_17c90159c0_c.jpg' alt='2018 Club N\u00e0utic L&#039;Escala-43' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-40406746005' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/793\/40589223904_7a5117ac14_c.jpg' alt='2018 Club N\u00e0utic L&#039;Escala-15' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-40589223904' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/797\/39493452260_d6fb036742_c.jpg' alt='2018 Club N\u00e0utic L&#039;Escala-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-39493452260' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/890\/39493452370_45479fc47c_c.jpg' alt='2018 Club N\u00e0utic L&#039;Escala-6' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-39493452370' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/795\/40589223174_3b62601a1f_c.jpg' alt='2018 Club N\u00e0utic L&#039;Escala-5' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-40589223174' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/813\/40589223314_6f990a748e_c.jpg' alt='2018 Club N\u00e0utic L&#039;Escala-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-40589223314' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2871\/34084775822_179ef28eaf_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-79' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34084775822' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2883\/33400454684_6cc8b9ecfe_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-77' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33400454684' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2914\/34212531125_86c7077511_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-48' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34212531125' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2822\/34081712351_0381952025_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-47' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34081712351' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2857\/33370176314_e961a04129_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-46' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33370176314' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2847\/34081717011_f700ba9086_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-45' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34081717011' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/4178\/33370184824_50c7451c76_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-44' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33370184824' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2816\/33401697323_beac237cf8_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-43' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33401697323' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2912\/33370195604_c3f4ec29c3_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-40' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33370195604' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2813\/33828376600_882a783b1b_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-38' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33828376600' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2844\/34055064612_3247ccda69_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-27' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34055064612' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/4159\/34055075652_96b1040eb8_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-23' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34055075652' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2921\/33401784213_a214881d34_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-18' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33401784213' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2899\/34081790041_c1c101c37a_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-14' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34081790041' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2836\/34171686376_cf255ceaa5_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-7' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34171686376' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2944\/34171692026_1108ca2409_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34171692026' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2941\/34212680585_4877d63c2b_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34212680585' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2829\/34201113396_97b583d60b_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-69' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34201113396' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2852\/34084792382_5532b7d1c5_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-68' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34084792382' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2850\/33400473094_f2a9fc50d6_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-56' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33400473094' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/2841\/33400474224_aed70aeb23_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-55' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33400474224' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/4155\/34241576105_70011cfe7c_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-52' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-34241576105' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/1444\/26101388852_a90236aa3c_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-28' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-26101388852' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/1617\/25589085594_f80bb514b3_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-27' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-25589085594' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/1631\/25591177893_ea6bc27e4c_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-17' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-25591177893' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/1501\/26127526991_9f30d82589_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-12' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-26127526991' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/1472\/26193837815_3e8e11fa1e_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-3' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-26193837815' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/1516\/25591182563_93e7aa93d4_c.jpg' alt='Club N\u00e0utic L&#039;Escala - Puerto deportivo Costa Brava-2' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-25591182563' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/8780\/17112553005_8bf502d197_c.jpg' alt='Regata Comodor - CN L&#039;Escala-33' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-17112553005' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/8740\/16926357309_16ce6ed8f3_c.jpg' alt='Regata Comodor - CN L&#039;Escala-26' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-16926357309' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7667\/16492414913_e08bbc1a53_c.jpg' alt='Regata Comodor - CN L&#039;Escala-18' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-16492414913' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/8781\/16926356869_d7d5944038_c.jpg' alt='Regata Comodor - CN L&#039;Escala-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-16926356869' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t<\/ul>\n\t<\/div><!-- splide__track -->\n<\/div><!-- .photonic-slideshow-->\n\n<\/div><!-- .photonic-stream or .photonic-panel -->\n","protected":false},"excerpt":{"rendered":"<p>Classes Creuer: Solitaris i A Dos<\/p>\n","protected":false},"featured_media":25657,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[99],"product_tag":[],"activity_type":[],"level":[],"age":[],"modality":[],"payment_method":[],"class_list":{"0":"post-23234","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sense-categoria","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>XI Copa Comodor - Gran Premi Jotun &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"Regata Copa Comodor - Gran Premi Jotun - Vela de creuer a la Costa Brava - L&#039;Escala - Girona\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XI Copa Comodor - Gran Premi Jotun\" \/>\n<meta property=\"og:description\" content=\"Regata Copa Comodor - Gran Premi Jotun - Vela de creuer a la Costa Brava - L&#039;Escala - Girona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-05T10:58:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/2021-club-nautic-lescala-creuer-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"605\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/regata-comodor-2021\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/regata-comodor-2021\\\/\",\"name\":\"XI Copa Comodor - Gran Premi Jotun &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/regata-comodor-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/regata-comodor-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2021-club-nautic-lescala-creuer-6.jpg\",\"datePublished\":\"2021-01-20T15:34:09+00:00\",\"dateModified\":\"2025-03-05T10:58:24+00:00\",\"description\":\"Regata Copa Comodor - Gran Premi Jotun - Vela de creuer a la Costa Brava - L'Escala - Girona\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/regata-comodor-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/regata-comodor-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/regata-comodor-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2021-club-nautic-lescala-creuer-6.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/2021-club-nautic-lescala-creuer-6.jpg\",\"width\":1200,\"height\":605},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/activitats-costa-brava\\\/regata-comodor-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reservez votre activit\u00e9s sur la Costa Brava\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/reservez-votre-activites-sur-la-costa-brava\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"XI Copa Comodor &#8211; Gran Premi Jotun\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XI Copa Comodor - Gran Premi Jotun &#8211; Club N\u00e0utic L\u2019Escala","description":"Regata Copa Comodor - Gran Premi Jotun - Vela de creuer a la Costa Brava - L'Escala - Girona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"XI Copa Comodor - Gran Premi Jotun","og_description":"Regata Copa Comodor - Gran Premi Jotun - Vela de creuer a la Costa Brava - L'Escala - Girona","og_url":"https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2025-03-05T10:58:24+00:00","og_image":[{"width":1200,"height":605,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/2021-club-nautic-lescala-creuer-6.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/","url":"https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/","name":"XI Copa Comodor - Gran Premi Jotun &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/2021-club-nautic-lescala-creuer-6.jpg","datePublished":"2021-01-20T15:34:09+00:00","dateModified":"2025-03-05T10:58:24+00:00","description":"Regata Copa Comodor - Gran Premi Jotun - Vela de creuer a la Costa Brava - L'Escala - Girona","breadcrumb":{"@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/2021-club-nautic-lescala-creuer-6.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/01\/2021-club-nautic-lescala-creuer-6.jpg","width":1200,"height":605},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/activitats-costa-brava\/regata-comodor-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Reservez votre activit\u00e9s sur la Costa Brava","item":"https:\/\/nauticescala.com\/fr\/reservez-votre-activites-sur-la-costa-brava\/"},{"@type":"ListItem","position":3,"name":"XI Copa Comodor &#8211; Gran Premi Jotun"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/product\/23234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/media\/25657"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/media?parent=23234"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/product_brand?post=23234"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/product_cat?post=23234"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/product_tag?post=23234"},{"taxonomy":"activity_type","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/activity_type?post=23234"},{"taxonomy":"level","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/level?post=23234"},{"taxonomy":"age","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/age?post=23234"},{"taxonomy":"modality","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/modality?post=23234"},{"taxonomy":"payment_method","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/payment_method?post=23234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}