 {"id":35022,"date":"2021-12-18T12:47:33","date_gmt":"2021-12-18T11:47:33","guid":{"rendered":"http:\/\/nauticescala.com\/?p=35022&#038;post_type=product&#038;preview_id=35022"},"modified":"2022-04-06T16:03:30","modified_gmt":"2022-04-06T14:03:30","slug":"costa-brava-sailing-meeting-2022","status":"publish","type":"product","link":"https:\/\/nauticescala.com\/fr\/reservez-votre-activites-costa-brava\/costa-brava-sailing-meeting-2022\/","title":{"rendered":"XIV Costa Brava Sailing Meeting &#8211; 2022"},"content":{"rendered":"\n            \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n                            <div class=\"accordion-block\">\n                    <div id=\"accordion\" class=\"accordion\">\n                                                                            <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-01\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>T.O.A.<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-01\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <ul>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/04\/OPTIMIST-GENERAL.pdf\" target=\"_blank\" rel=\"noopener\">OPTIMIST GENERAL\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/04\/OPEN-GENERAL.pdf\" target=\"_blank\" rel=\"noopener\">OPEN GENERAL<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/04\/TEMPS-LIMIT-PROTESTA.pdf\" target=\"_blank\" rel=\"noopener\">TEMPS L\u00cdMIT DE PROTESTES\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/04\/OPTIMIST-P2.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 2 OPTIMIST &#8211; 03\/04\/2022 a les 16:10h<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/04\/OPTIMIST-P1.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 1 OPTIMIST &#8211; 03\/04\/2022 a les 15:45h<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/04\/OPEN-P2.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 2 OPEN &#8211; 03\/04\/2022 a les 15:55h\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/04\/OPEN-P1.pdf\" target=\"_blank\" rel=\"noopener\">PROVA 1 OPEN &#8211; 03\/04\/2022 a les 15:25h<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/12\/AVIS-3.pdf\" target=\"_blank\" rel=\"noopener\">AVIS 3<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/04\/INSCRITS_CBSM2022_optimist.pdf\" target=\"_blank\" rel=\"noopener\">Llistat d&rsquo;inscrits Optimist\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/04\/INSCRITS_CBSM2022_open.pdf\" target=\"_blank\" rel=\"noopener\">Llistat d&rsquo;inscrits, Open, M\u00e0ster i Voladors.<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/04\/INSCRITS_CBSM2022_TECNICS.pdf\" target=\"_blank\" rel=\"noopener\">Llistat de Entrenadors (1.4.2022)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/12\/Avis-num.-2.pdf\">AV\u00cdS n\u00fam. 2<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/12\/AVIS-1-COVID.pdf\" target=\"_blank\" rel=\"noopener\">AV\u00cdS n\u00fam. 1\u00a0 Declaraci\u00f3 Responsasble (COVID)<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/03\/INFORMACIO-I-LOGISTICA.pdf\" target=\"_blank\" rel=\"noopener\">Log\u00edstica i \u00e0rea de varada<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2022\/03\/IRCBSM2022.pdf\" target=\"_blank\" rel=\"noopener\">Instruccions de regata\u00a0<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/12\/AR-CBSM2022.pdf\" target=\"_blank\" rel=\"noopener\">Anunci de Regata 2022<\/a><\/li>\n<li><a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=lqB1eUSjukqpLGJ9SVJpFIb5kQPhU09Hv1nt7Meg8qVUN1pJVldXTVpNSzc0NkhNQklLTU05TjFOVSQlQCN0PWcu\" target=\"_blank\" rel=\"noopener\">Sol\u00b7licitud Entrenadors i acompanyants<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/formulari-regata-de-vela-2\/\">Pagament de la Regata i inscripci\u00f3<\/a><\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-02\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Drets d&rsquo;inscripci\u00f3<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-02\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p>El per\u00edode de sol\u00b7licitud d\u2019inscripcions <strong>finalitzar\u00e0 el dia 30 de mar\u00e7 les 15.00 h.<\/strong> Els drets d\u2019inscripci\u00f3 per aquesta regata s\u00f3n: <strong>15 euros per tripulant.<\/strong><\/p>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-03\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Guardons<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-03\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <ul>\n<li>Classe Optimist: premis als 3 primers classificats de les categories SOTS16, SOTS13 i SOTS11<\/li>\n<li>Classe Voladors: Es donar\u00e0 premi als 3 primers classificats de cada categoria si hi ha, m\u00e9s de 5 participants, es donar\u00e0 premi als 2 primers classificats si n\u2019hi ha, \u00a04 o 5 \u00a0participants, o es donar\u00e0 premi al primer si n\u2019hi ha menys de 4 participants..<\/li>\n<li>Classe M\u00e0ster: Es donar\u00e0 premi als 3 primers classificats de cada categoria si hi ha, m\u00e9s de 5 participants, es donar\u00e0 premi als 2 primers classificats si n\u2019hi ha, \u00a04 o 5\u00a0 participants, o premi al primer si n\u2019hi ha menys de 4 participants. Es preveu donar tamb\u00e9 premi al primer classificat de cada categoria constitu\u00efda. Els premis no seran acumulables i es donar\u00e0 prioritat als tres primer classificats.<\/li>\n<li>Classe OPEN: Es donar\u00e0 premi als 3 primers classificats si hi ha, m\u00e9s de 5 participants, es donar\u00e0 premi als 2 primers classificats si n\u2019hi ha, \u00a04 o 5\u00a0 participants, o premi al primer si n\u2019hi ha menys de 4 participants. Es preveu donar tamb\u00e9 premi al primer classificat de cada categoria constitu\u00efda. Els premis no seran acumulables i es donar\u00e0 prioritat als tres primer classificats.<\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-04\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Horaris<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-04\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p>L&rsquo;horari de les proves seran:<\/p>\n<ul>\n<li>Per la Classe Optimist la hora prevista de sortida ser\u00e0 les 12 hores de cada dia de regata.<\/li>\n<li>Per la Classe L\u00e0ser Master la hora prevista de sortida ser\u00e0 les 12 hores de cada dia de regata.<\/li>\n<li>Per la Classe Voladors la hora prevista de sortida ser\u00e0 les 13 hores de cada dia de regata<\/li>\n<\/ul>\n<p>L&rsquo;organitzaci\u00f3 es reserva el dret de retardar aquests horaris.<\/p>\n<p>&nbsp;<\/p>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-05\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Vols llogar una embarcaci\u00f3?<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-05\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <p>Tens ganes de participar a la regata per\u00f2 no tens embarcaci\u00f3?\u00a0<a href=\"https:\/\/nauticescala.com\/es\/compra-actividades-costa-brava\/alquiler-de-vela-ligera\/\" target=\"_blank\" rel=\"noopener\">Lloga-la<\/a>\u00a0i no et quedis sense navegar!<\/p>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-06\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Necessites allotjament?<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-06\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                                                                            <ul class=\"members-list\">\n                                                                                                                                                                                                <li>\n                                                                                                                                                    <a href=\"https:\/\/www.lescalaresort.com\/\">\n                                                                                                                                                            <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/01\/escala-resort-1.jpg\" alt=\"\" \/>\n                                                                                                                                                        <\/a>\n                                                                                                                                            <\/li>\n                                                                                                                                                                                                                                                                <li>\n                                                                                                                                                    <a href=\"https:\/\/www.vacancescostabrava.cat\/ca\/\">\n                                                                                                                                                            <img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/02\/vacances-costa-brava.jpg\" alt=\"\" \/>\n                                                                                                                                                        <\/a>\n                                                                                                                                            <\/li>\n                                                                                                                                                                                    <\/ul><!-- end members-list -->\n                                                    \n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                                <div class=\"card\">\n                                <div class=\"card-header\">\n                                    <h3>\n                                        <a href=\"#\" class=\"collapsed\" data-toggle=\"collapse\" data-target=\"#collapse-07\" aria-expanded=\"true\"><i class=\"ico-opener\">&nbsp;<\/i>Edicions anteriors<\/a>\n                                    <\/h3>\n                                <\/div><!-- end card-header -->\n                                <div id=\"collapse-07\" class=\"collapse\">\n                                                                    <div class=\"card-body\">\n\n                                        \n                                            \n                                                \n                                                    <ul>\n<li style=\"list-style-type: none\">\n<ul>\n<li><a href=\"https:\/\/nauticescala.com\/activitats-costa-brava\/xii-costa-brava-sailing-meeting\/\">2020<\/a><\/li>\n<li><a href=\"https:\/\/nauticescala.com\/activitats-costa-brava\/2021-xiii-costa-brava-sailing-meeting\/\">2021<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n                                                \n                                            \n                                        \n                                    <\/div><!-- end card-body -->\n                                <\/div><!-- end collapse -->\n                            <\/div><!-- end card -->\n                                                                        <\/div><!-- end accordion -->\n                <\/div><!-- end accordion-block -->\n            \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\n    \n        <div class=\"btn-box\">\n            <a href=\"https:\/\/www.flickr.com\/photos\/nauticescala\/albums\/72157708140932824\" target=\"_blank\" class=\"btn btn-primary\">Fotografies<\/a>\n\n        \n        \n\n<\/div><!-- end btn-box -->\n\n   \n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section><div class='photonic-flickr-stream photonic-stream ' id='photonic-flickr-stream-1'>\n<div id='photonic-slideshow-flickr-1' class='photonic-slideshow splide default title-display-tooltip photonic-slideshow-adapt-height-width' data-splide='{&quot;type&quot;:&quot;fade&quot;,&quot;perPage&quot;:&quot;1&quot;,&quot;autoplay&quot;:true,&quot;interval&quot;:&quot;5000&quot;,&quot;speed&quot;:&quot;1000&quot;,&quot;drag&quot;:true,&quot;pauseOnHover&quot;:true,&quot;pagination&quot;:false,&quot;slideFocus&quot;:false,&quot;arrows&quot;:true,&quot;direction&quot;:&quot;ltr&quot;,&quot;breakpoints&quot;:{&quot;480&quot;:{&quot;perPage&quot;:1}}}'>\n\t<div class='splide__track'>\n\t\t<ul class='photonic-slideshow-content splide__list'>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980018309_d6a0d49a3b_h.jpg' alt='2022-club nautic lescala-CBSM-57' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980018309' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980297055_655c1e1665_h.jpg' alt='2022-club nautic lescala-CBSM-56' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980297055' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980297020_031dcb0bb1_h.jpg' alt='2022-club nautic lescala-CBSM-55' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980297020' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979809403_b35de22397_h.jpg' alt='2022-club nautic lescala-CBSM-54' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979809403' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980296960_8797fe74ed_h.jpg' alt='2022-club nautic lescala-CBSM-53' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980296960' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979809318_6466a8805d_h.jpg' alt='2022-club nautic lescala-CBSM-52' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979809318' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980296865_366cd98225_h.jpg' alt='2022-club nautic lescala-CBSM-51' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980296865' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980296845_36f036ae56_h.jpg' alt='2022-club nautic lescala-CBSM-50' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980296845' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979738176_fbd60eb4e3_h.jpg' alt='2022-club nautic lescala-CBSM-49' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979738176' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980018089_378c7f048a_h.jpg' alt='2022-club nautic lescala-CBSM-48' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980018089' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980296805_fe88f45b3a_h.jpg' alt='2022-club nautic lescala-CBSM-47' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980296805' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978731887_a0f606fb5f_h.jpg' alt='2022-club nautic lescala-CBSM-46' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978731887' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979738116_aab0d5f051_h.jpg' alt='2022-club nautic lescala-CBSM-45' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979738116' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979738101_52fb1458be_h.jpg' alt='2022-club nautic lescala-CBSM-44' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979738101' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980296720_34edfa14c4_h.jpg' alt='2022-club nautic lescala-CBSM-43' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980296720' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979739991_bd368e8531_h.jpg' alt='2022-club nautic lescala-CBSM-42' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979739991' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978733817_6924df7765_h.jpg' alt='2022-club nautic lescala-CBSM-41' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978733817' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979739926_99dacd1a54_h.jpg' alt='2022-club nautic lescala-CBSM-40' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979739926' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979810933_f76bc3ce53_h.jpg' alt='2022-club nautic lescala-CBSM-39' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979810933' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980298570_c156aede7b_h.jpg' alt='2022-club nautic lescala-CBSM-38' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980298570' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980298540_316474fdf9_h.jpg' alt='2022-club nautic lescala-CBSM-37' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980298540' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980298515_7e1fe1b1e4_h.jpg' alt='2022-club nautic lescala-CBSM-36' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980298515' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979739736_2831fcf079_h.jpg' alt='2022-club nautic lescala-CBSM-35' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979739736' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978733542_55533e440d_h.jpg' alt='2022-club nautic lescala-CBSM-34' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978733542' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979739671_05cc85e23f_h.jpg' alt='2022-club nautic lescala-CBSM-33' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979739671' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979810648_9e6325bf1a_h.jpg' alt='2022-club nautic lescala-CBSM-32' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979810648' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979810603_82a9040c2b_h.jpg' alt='2022-club nautic lescala-CBSM-31' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979810603' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979739556_7b200343ac_h.jpg' alt='2022-club nautic lescala-CBSM-30' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979739556' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978733277_aa2120c7db_h.jpg' alt='2022-club nautic lescala-CBSM-28' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978733277' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980298250_f4c5f07143_h.jpg' alt='2022-club nautic lescala-CBSM-29' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980298250' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980019464_a99cd5be84_h.jpg' alt='2022-club nautic lescala-CBSM-27' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980019464' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979739366_0892ec39b7_h.jpg' alt='2022-club nautic lescala-CBSM-26' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979739366' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980298050_c00d0d7124_h.jpg' alt='2022-club nautic lescala-CBSM-25' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980298050' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980297975_d68685086e_h.jpg' alt='2022-club nautic lescala-CBSM-24' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980297975' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980297950_7ec9da89d8_h.jpg' alt='2022-club nautic lescala-CBSM-23' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980297950' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979739206_fae58cba76_h.jpg' alt='2022-club nautic lescala-CBSM-22' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979739206' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978732977_45dd47b135_h.jpg' alt='2022-club nautic lescala-CBSM-21' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978732977' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979739141_0c27e30854_h.jpg' alt='2022-club nautic lescala-CBSM-20' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979739141' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978732912_507ee1e597_h.jpg' alt='2022-club nautic lescala-CBSM-19' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978732912' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978732872_6a60283cf9_h.jpg' alt='2022-club nautic lescala-CBSM-18' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978732872' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978732847_85dce181ab_h.jpg' alt='2022-club nautic lescala-CBSM-17' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978732847' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980297720_3d071c8fa3_h.jpg' alt='2022-club nautic lescala-CBSM-16' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980297720' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980297685_e76b8d2f4b_h.jpg' alt='2022-club nautic lescala-CBSM-15' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980297685' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980018879_5a2f47061e_h.jpg' alt='2022-club nautic lescala-CBSM-14' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980018879' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978732727_1944fb4790_h.jpg' alt='2022-club nautic lescala-CBSM-13' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978732727' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979809963_b2868ee5af_h.jpg' alt='2022-club nautic lescala-CBSM-12' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979809963' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978732657_ad462f1b75_h.jpg' alt='2022-club nautic lescala-CBSM-11' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978732657' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979809903_3f368bff8c_h.jpg' alt='2022-club nautic lescala-CBSM-10' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979809903' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978732577_e4e5627fbc_h.jpg' alt='2022-club nautic lescala-CBSM-9' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978732577' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980018594_56207fae99_h.jpg' alt='2022-club nautic lescala-CBSM-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980018594' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978732482_4d0e1d0588_h.jpg' alt='2022-club nautic lescala-CBSM-7' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978732482' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979738611_643bc138ac_h.jpg' alt='2022-club nautic lescala-CBSM-6' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979738611' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979809713_fc5e150511_h.jpg' alt='2022-club nautic lescala-CBSM-5' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979809713' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980297265_cdf7081375_h.jpg' alt='2022-club nautic lescala-CBSM-4' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980297265' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51980297210_ee3e575b46_h.jpg' alt='2022-club nautic lescala-CBSM-3' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51980297210' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51979809618_1a64926248_h.jpg' alt='2022-club nautic lescala-CBSM-2' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51979809618' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51978732227_b2b4a90f51_h.jpg' alt='2022-club nautic lescala-CBSM' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51978732227' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51095098278_0ba1d30823_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-86' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51095098278' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094501648_7e04441e3e_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-78' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094501648' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094767790_61e732682a_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-76' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094767790' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094767735_f5c304c5c2_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-75' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094767735' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094053862_b22b5f6aa5_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-71' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094053862' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094038359_8d64f56e5d_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-70' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094038359' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094767630_363b3c7d45_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-69' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094767630' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094767625_331f9ab0d0_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-68' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094767625' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51093958446_64cc020792_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-64' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51093958446' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094501813_0e42e656a9_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-61' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094501813' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094038679_85a947954e_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-60' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094038679' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51093958831_70a9dacff9_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-57' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51093958831' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094038614_1216fd9a67_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-56' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094038614' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094054082_660c7371cc_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-53' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094054082' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51093958766_319ee45a8a_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-51' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51093958766' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094767880_02f016b202_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-49' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094767880' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094501703_0071f6c1a3_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-48' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094501703' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094038509_a88abcfcc7_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-47' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094038509' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51094767840_1a0cb5cf7b_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-46' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51094767840' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51092605850_967dff271e_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-43' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51092605850' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51091875779_cf14991e8a_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-42' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51091875779' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51092605805_abb00f0715_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-41' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51092605805' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51091887462_fb8b75d5b7_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-40' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51091887462' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51092606260_8502685274_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-34' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51092606260' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51092339188_0daf138b0b_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-32' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51092339188' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51092339178_345fdaa671_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-31' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51092339178' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51091876149_631ae90444_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-30' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51091876149' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51091796441_803a66459a_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-29' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51091796441' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51091796426_4512c46e96_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-28' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51091796426' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51091796386_d1934ebc6a_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-25' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51091796386' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51091796341_8504e49693_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-22' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51091796341' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51091796291_a6183b2415_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-17' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51091796291' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51091887242_4c4b17282c_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-16' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51091887242' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51092339063_6d13fbd77e_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-15' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51092339063' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51092606070_82ecf6d051_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-14' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51092606070' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51091887182_983445f048_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-12' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51091887182' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51092606000_686b0ce380_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-9' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51092606000' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51092338973_9348b1e4e0_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-8' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51092338973' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51091887097_a722e55de6_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-6' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51091887097' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/65535\/51092605940_6d45314f39_h.jpg' alt='2021-Club N\u00e0utic l&#039;Escala CBSM-5' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-51092605940' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7824\/47606823631_610b9c3f9e_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-90' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47606823631' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7812\/46882581104_73aa0634bf_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-88' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46882581104' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7919\/46882581534_c96cbd14e8_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-87' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46882581534' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7856\/46882581024_878d887e81_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-83' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46882581024' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7843\/47606823051_0463dc252c_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-77' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47606823051' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7854\/47606824901_f4148af2ea_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-76' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47606824901' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7854\/46882580934_461d755afb_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-75' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46882580934' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7917\/47606824571_1316791798_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-69' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47606824571' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7849\/46882580864_944c7a6297_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-68' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-46882580864' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7803\/47606822361_cca6d7de28_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-65' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47606822361' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7819\/47606825531_9521d8642f_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-61' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47606825531' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7807\/47606824071_d77afcdbd7_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-59' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47606824071' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7840\/47606824011_1d530fa3d8_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-56' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47606824011' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7905\/47606825451_d967515556_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-54' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47606825451' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7922\/47546522332_703316ecde_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-49' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47546522332' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7814\/40633333203_87c94c7d6b_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-44' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-40633333203' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7810\/47546522352_475009c180_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-43' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47546522352' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7802\/40633331363_8ecf54aba3_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-39' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-40633331363' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7901\/47546521962_2f2a5aa72f_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-38' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47546521962' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7811\/33722469828_b70908c4b5_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-37' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33722469828' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7895\/47546522532_e9f71537d2_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-31' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47546522532' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7886\/33722471398_8eeba5b0ea_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-30' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-33722471398' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7882\/47546522832_bb8536d247_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-18' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47546522832' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7817\/47546522902_a2f38d16af_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-16' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47546522902' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7895\/32657116977_84a5e0259b_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-15' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-32657116977' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t\t<li class='photonic-slideshow-img splide__slide'>\n\t\t\t\t<div class='splide__slide__container'>\n\t\t\t\t<img src='https:\/\/live.staticflickr.com\/7897\/47546523022_330392e68e_c.jpg' alt='2019 - Club N\u00e0utic l&#039;Escala-9' title='' data-photonic-tooltip=\"\" id='photonic-slideshow-flickr-1-47546523022' \/>\n\t\t\t\t<\/div>\n\t\t\t<\/li>\n\t\t<\/ul>\n\t<\/div><!-- splide__track -->\n<\/div><!-- .photonic-slideshow-->\n\n<\/div><!-- .photonic-stream or .photonic-panel -->\n<section class=\"article-section\"><div class=\"container\">\n\n<\/div><\/section>\t<div class=\"container\">\n\n<div class=\"content-block\">\n \t \t\n \t \t   \n \t\t    <div class=\"partners-block\">\t    \t\n\t    \t\t    \t\t<h3>Col\u00b7labora:<\/h3>\n\t    \t  \n\t    \t   \n\t    \t\t\t        <ul class=\"partners-list\">\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/08\/logo-fcv-350x215.png\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t        \t\t\t\t\t            <li>\n\t\t\t                <a target=\"_blank\" href=\"#no-follow\">\n\t\t\t                \t\t\t\t                \t\t<img decoding=\"async\" src=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2020\/01\/ajuntament-escala.jpg\" alt=\"\">\n\t\t\t                \t\t\t\t                <\/a>\n\t\t\t            <\/li>\t\t        \t\t\n\t\t        \t\t\t            \n\t\t        <\/ul><!-- end partners-list -->\t    \t\t\n\t    \t\t    <\/div><!-- end partners-block --> \t   \t\n \t   \n<\/div><!-- end content-block -->\n\n\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Vela lleugera<br \/>Inscripcions: a partir del 02.03.2022<\/p>\n","protected":false},"featured_media":26347,"template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[99],"product_tag":[],"activity_type":[],"level":[],"age":[],"modality":[],"payment_method":[],"class_list":{"0":"post-35022","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sense-categoria","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>XIV Costa Brava Sailing Meeting - 2022 &#8211; Club N\u00e0utic L\u2019Escala<\/title>\n<meta name=\"description\" content=\"Regata de Vela Lleugera a l&#039;Escala, Costa Brava Girona, para las Classes Optimist, L\u00e1ser, Open, Moth i Waszp\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XIV Costa Brava Sailing Meeting - 2022\" \/>\n<meta property=\"og:description\" content=\"Regata de Vela Lleugera a l&#039;Escala, Costa Brava Girona, para las Classes Optimist, L\u00e1ser, Open, Moth i Waszp\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Club N\u00e0utic L\u2019Escala\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-06T14:03:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/04\/2021-club-nautic-lescala-cbsm-57.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"605\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/activitats-costa-brava\\\/costa-brava-sailing-meeting-2022\\\/\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/activitats-costa-brava\\\/costa-brava-sailing-meeting-2022\\\/\",\"name\":\"XIV Costa Brava Sailing Meeting - 2022 &#8211; Club N\u00e0utic L\u2019Escala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/activitats-costa-brava\\\/costa-brava-sailing-meeting-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/activitats-costa-brava\\\/costa-brava-sailing-meeting-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/2021-club-nautic-lescala-cbsm-57.jpg\",\"datePublished\":\"2021-12-18T11:47:33+00:00\",\"dateModified\":\"2022-04-06T14:03:30+00:00\",\"description\":\"Regata de Vela Lleugera a l'Escala, Costa Brava Girona, para las Classes Optimist, L\u00e1ser, Open, Moth i Waszp\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/activitats-costa-brava\\\/costa-brava-sailing-meeting-2022\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nauticescala.com\\\/fr\\\/activitats-costa-brava\\\/costa-brava-sailing-meeting-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/activitats-costa-brava\\\/costa-brava-sailing-meeting-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/2021-club-nautic-lescala-cbsm-57.jpg\",\"contentUrl\":\"https:\\\/\\\/nauticescala.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/2021-club-nautic-lescala-cbsm-57.jpg\",\"width\":1200,\"height\":605},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/activitats-costa-brava\\\/costa-brava-sailing-meeting-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reservez votre activit\u00e9s sur la Costa Brava\",\"item\":\"https:\\\/\\\/nauticescala.com\\\/fr\\\/reservez-votre-activites-sur-la-costa-brava\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"XIV Costa Brava Sailing Meeting &#8211; 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nauticescala.com\\\/#website\",\"url\":\"https:\\\/\\\/nauticescala.com\\\/\",\"name\":\"Club N\u00e0utic L\u2019Escala\",\"description\":\"Port esportiu a la Costa Brava\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nauticescala.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XIV Costa Brava Sailing Meeting - 2022 &#8211; Club N\u00e0utic L\u2019Escala","description":"Regata de Vela Lleugera a l'Escala, Costa Brava Girona, para las Classes Optimist, L\u00e1ser, Open, Moth i Waszp","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/","og_locale":"fr_FR","og_type":"article","og_title":"XIV Costa Brava Sailing Meeting - 2022","og_description":"Regata de Vela Lleugera a l'Escala, Costa Brava Girona, para las Classes Optimist, L\u00e1ser, Open, Moth i Waszp","og_url":"https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/","og_site_name":"Club N\u00e0utic L\u2019Escala","article_modified_time":"2022-04-06T14:03:30+00:00","og_image":[{"width":1200,"height":605,"url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/04\/2021-club-nautic-lescala-cbsm-57.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/","url":"https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/","name":"XIV Costa Brava Sailing Meeting - 2022 &#8211; Club N\u00e0utic L\u2019Escala","isPartOf":{"@id":"https:\/\/nauticescala.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/#primaryimage"},"image":{"@id":"https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/04\/2021-club-nautic-lescala-cbsm-57.jpg","datePublished":"2021-12-18T11:47:33+00:00","dateModified":"2022-04-06T14:03:30+00:00","description":"Regata de Vela Lleugera a l'Escala, Costa Brava Girona, para las Classes Optimist, L\u00e1ser, Open, Moth i Waszp","breadcrumb":{"@id":"https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/#primaryimage","url":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/04\/2021-club-nautic-lescala-cbsm-57.jpg","contentUrl":"https:\/\/nauticescala.com\/wp-content\/uploads\/2021\/04\/2021-club-nautic-lescala-cbsm-57.jpg","width":1200,"height":605},{"@type":"BreadcrumbList","@id":"https:\/\/nauticescala.com\/fr\/activitats-costa-brava\/costa-brava-sailing-meeting-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nauticescala.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Reservez votre activit\u00e9s sur la Costa Brava","item":"https:\/\/nauticescala.com\/fr\/reservez-votre-activites-sur-la-costa-brava\/"},{"@type":"ListItem","position":3,"name":"XIV Costa Brava Sailing Meeting &#8211; 2022"}]},{"@type":"WebSite","@id":"https:\/\/nauticescala.com\/#website","url":"https:\/\/nauticescala.com\/","name":"Club N\u00e0utic L\u2019Escala","description":"Port esportiu a la Costa Brava","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nauticescala.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/product\/35022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/media\/26347"}],"wp:attachment":[{"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/media?parent=35022"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/product_brand?post=35022"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/product_cat?post=35022"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/product_tag?post=35022"},{"taxonomy":"activity_type","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/activity_type?post=35022"},{"taxonomy":"level","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/level?post=35022"},{"taxonomy":"age","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/age?post=35022"},{"taxonomy":"modality","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/modality?post=35022"},{"taxonomy":"payment_method","embeddable":true,"href":"https:\/\/nauticescala.com\/fr\/wp-json\/wp\/v2\/payment_method?post=35022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}